{"id":57462,"date":"2021-09-03T21:22:54","date_gmt":"2021-09-03T21:22:54","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=57462"},"modified":"2021-09-03T22:08:49","modified_gmt":"2021-09-03T22:08:49","slug":"deuxieme-heure-de-smackdown-16","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/03\/deuxieme-heure-de-smackdown-16\/","title":{"rendered":"Deuxi\u00e8me Heure de Smackdown!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/03\/resultats-du-wwe-friday-night-smackdown-du-3-septembre-2021\/\">Pour revenir \u00e0 la premi\u00e8re heure de Smackdown, cliquez ici.<\/a><\/strong><\/li><\/ul>\n\n\n\n<p><strong>Seth Rollins vs Cesaro<\/strong><\/p>\n\n\n\n<p>En fin de match, Cesaro tente une prise sur Seth Rollins, mais ce dernier le frappe avec une chaise ! L&rsquo;arbitre met fin \u00e0 la rencontre.<\/p>\n\n\n\n<p><em>Gagnant par DQ: Cesaro <\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, Seth Rolins continue son attaque sur Cesaro. Il pose la t\u00eate de Cesaro sur une chaise et en prend une autre pour un Conchairto, mais Edge arrive sur le ring ! Rollins part, tandis qu&rsquo;Edge v\u00e9rifie si Cesaro va bien.<\/p>\n\n\n\n<p>&#8211; Dans le vestiaire de Roman Reigns, Paul Heyman dit qu&rsquo;ils ont un probl\u00e8me. Reigns dit qu&rsquo;ils n&rsquo;ont aucun probl\u00e8me, il va \u00e9craser Finn Balor. Heyman dit qu&rsquo;ils ont un probl\u00e8me avec Brock Lesnar. Reigns r\u00e9pond qu&rsquo;ils n&rsquo;ont aucun probl\u00e8me, il va \u00e9craser Lesnar. Heyman dit que Brock Lesnar sera pr\u00e9sent la semaine prochaine ! Roman Reigns lui demande o\u00f9 est Lesnar ? Comment sait-il que Lesnar n&rsquo;est pas l\u00e0 ce soir ?<\/p>\n\n\n\n<p>&#8211; Happy Corbin arrive dans l&rsquo;ar\u00e8na avec sa voiture.<\/p>\n\n\n\n<p>&#8211; <strong>Kevin Owen<\/strong>s fait son entr\u00e9e pour son <strong>KO Show<\/strong>. Il nous souhaite la bienvenue et nous demande d&rsquo;accueillir Happy Corbin.<\/p>\n\n\n\n<p>Happy Corbin fait son entr\u00e9e puis dit qu&rsquo;il est heureux de faire partie du Kevin Owens Show. Il a un invit\u00e9 sp\u00e9cial qui peut rembourser les 100$ qu&rsquo;il lui doit, voici Logan Paul ! Ce dernier arrive sur le ring et Owens dit que Paul ainsi que Corbin ont beaucoup de choses en commun. On a l&rsquo;une des ordures les plus \u00e9gocentriques, les plus \u00e9go\u00efstes et les plus inutiles pour aller sur le ring de la WWE, puis on a Corbin. Logan Paul tend de l&rsquo;argent \u00e0 Owens, mais ce dernier refuse. Owens n&rsquo;a pas besoin de son argent. Tout ce dont il a besoin, c&rsquo;est que Paul quitte ce ring et ne montre plus jamais son visage \u00e0 la WWE. Kevin Owens pousse Logan Paul, mais Baron Corbin lui met un coup de poing !<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Carmella tape la pose avec une voix l&rsquo;annon\u00e7ant comme \u00e9tant la plus belle femme \u00e0 la WWE, puis on voit Liv Morgan juste derri\u00e8re qui dit qu&rsquo;elle ne croit pas ce qu&rsquo;elle voit.<\/p>\n\n\n\n<p><strong>Sami Zayn vs Dominik Mysterio<\/strong><\/p>\n\n\n\n<p>En fin de match, Rey Mysterio arrive sur la rampe et Dominik Mysterio saute par dessus la troisi\u00e8me corde (et l&rsquo;arbitre) pour tomber sur Sami Zayn \u00e0 l&rsquo;ext\u00e9rieur du ring. Dominik est distrait par son p\u00e8re, il remet Zayn sur le ring. Dominik remonte \u00e9galement, mais Zayn en profite pour faire son Helluva Kick et le tomb\u00e9 pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant : Sami Zayn<\/em><\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Sonya Deville est au t\u00e9l\u00e9phone. Naomi arrive et veut un match, mais Deville lui dit de demander la semaine prochaine.<\/p>\n\n\n\n<p>&#8211; La semaine prochaine \u00e0 SmackDown : Brock Lesnar est de retour, Edge sera contre Seth Rollins, et nous aurons une signature de contrat entre Bianca Belair et Becky Lynch pour Extreme Rules.<\/p>\n\n\n\n<p>&#8211; Dans la Gorilla Position, Finn Balor promet de reprendre la ceinture.<\/p>\n\n\n\n<p>&#8211; Finn Balor fait son entr\u00e9e, mais il se fait attaquer par les Usos ! Les Street Profits finissent par arriver puis coursent les Usos jusque dans les coulisses. Balor est au sol, tandis que Roman Reigns fait son entr\u00e9e avec Paul Heyman.<\/p>\n\n\n\n<p>&#8211; Au retour Finn est debout mais mal en point et donne le OK \u00e0 l&rsquo;arbitre pour lancer le match.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat Universal<\/strong><\/p>\n\n\n\n<p><strong>Finn Balor vs Roman Reigns (c) acc Paul Heyman<\/strong><\/p>\n\n\n\n<p>En fin de match, Finn Balor monte sur la troisi\u00e8me corde et fait son Coup de Grace sur Roman Reigns suivi du tomb\u00e9, mais le champion se rel\u00e8ve ! Reigns lui applique la Guillotine et Balor perd connaissance.<\/p>\n\n\n\n<p><em>Gagnant: Roman Reigns<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le match, Roman Reigns et Paul Heyman quittent le ring. Sur leur chemin, les lumi\u00e8res deviennent rouges le temps d&rsquo;un instant&#8230; Le show se termine ainsi.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/03\/regardez-le-wwe-friday-night-smackdown-du-3-septembre-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour voir ce Smackdown, cliquez ici.<\/strong><\/a><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re heure de Smackdown, cliquez ici. Seth Rollins vs Cesaro En fin de match, Cesaro tente une prise sur Seth Rollins, mais ce dernier le frappe avec une chaise ! L&rsquo;arbitre met fin \u00e0 la rencontre. Gagnant par DQ: Cesaro Apr\u00e8s le match, Seth Rolins continue son attaque sur Cesaro. Il&#8230;<\/p>\n","protected":false},"author":4,"featured_media":57464,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"ppma_author":[292],"class_list":["post-57462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-smackdown"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=57462"}],"version-history":[{"count":12,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57462\/revisions"}],"predecessor-version":[{"id":57489,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57462\/revisions\/57489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/57464"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=57462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=57462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=57462"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=57462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}