{"id":57458,"date":"2021-09-03T21:18:31","date_gmt":"2021-09-03T21:18:31","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=57458"},"modified":"2021-09-05T16:16:45","modified_gmt":"2021-09-05T16:16:45","slug":"resultats-du-wwe-friday-night-smackdown-du-3-septembre-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/03\/resultats-du-wwe-friday-night-smackdown-du-3-septembre-2021\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du WWE Friday Night Smackdown du 3 Septembre 2021!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/03\/regardez-le-wwe-friday-night-smackdown-du-3-septembre-2021\/\" target=\"_blank\"><strong>Pour voir ce Smackdown, cliquez ici.<\/strong><\/a><\/li><\/ul>\n\n\n\n<p><strong>WWE SmackDown Jacksonville, Floride, 3 septembre 2021<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Michael Cole et Corey Graves<\/p>\n\n\n\n<p>&#8211; Let WWE Friday Night SmackDown d\u00e9bute sur une vid\u00e9o concernant ce qu&rsquo;il s&rsquo;est pass\u00e9 la semaine derni\u00e8re. Les pyros \u00e9clatent et les commentateurs nous souhaitent la bienvenue. <\/p>\n\n\n\n<p>&#8211; Les Usos arrivent ensuite sur le ring, tandis que Roman Reigns les regarde depuis son vestiaire. Jimmy Uso dit qu&rsquo;il a essay\u00e9 de comprendre pourquoi les Street Profits ont voulu mettre leur nez dans les affaires de la famille. Peut-\u00eatre qu&rsquo;ils veulent se faire un nom, qu&rsquo;ils essayent de faire leur preuves. Jey Uso dit qu&rsquo;ils ont manqu\u00e9 de respect au Head of the Table et au Bloodline, qu&rsquo;ils fassent leurs preuvent face aux 7 fois champions par \u00e9quipe.<\/p>\n\n\n\n<p>Les Street Profits font leur entr\u00e9e et disent que les Usos sont d\u00e9biles et qu&rsquo;ils \u00e9taient dans l&#8217;embarras devant Roman Reigns la semaine derni\u00e8re. Qu&rsquo;est-ce qu&rsquo;ils font sur le ring sans la permission de Reigns ?<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>The Usos (Jimmy &amp; Jey) vs Street Profits (Montez Ford &amp; Angelo Dawkins)<\/strong><\/p>\n\n\n\n<p>En fin de match, Montez Ford fait son Frog Splash sur Jimmy Uso, suivi du tomb\u00e9 mais Jey l&rsquo;arr\u00eate puis envoie Ford dans le poteau du ring \u00e0 plusieurs reprises. L&rsquo;arbitre met fin au match.<\/p>\n\n\n\n<p><em>Gagnants par DQ : Street Profits <\/em><\/p>\n\n\n\n<p> Apr\u00e8s le match, les Usos continuent leur attaque, mais les Street Profits prennent le dessus puis vont c\u00e9l\u00e9brer sur la table des commentateurs. On voit Roman Reigns et Paul Heyman qui regardaient dans le vestiaire de Reigns.<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Paul Heyman est arr\u00eat\u00e9 par Kayla Braxton. Heyman lui dit d&rsquo;aller s&rsquo;amuser, mais son t\u00e9l\u00e9phone sonne avec le theme song de Brock Lesnar en sonnerie. Heyman ne r\u00e9pond pas, et la personnes appelle une nouvelle fois. Heyman d\u00e9croche et dit qu&rsquo;il transmettra le message. Il veut partir, mais tombe sur Big E qui se met \u00e0 rigoler avec sa mallette.<\/p>\n\n\n\n<p>&#8211; <strong>Becky Lynch<\/strong> fait son entr\u00e9e. La foule commence \u00e0 chanter \u00ab\u00a0You Deserve It\u00a0\u00bb. Lynch dit que la semaine derni\u00e8re, elle a \u00e9t\u00e9 interrompue par toutes les catcheuses du vestiaire. Elle n&rsquo;a m\u00eame pas pu parler \u00e0 Bianca Belair. C&rsquo;est une sacr\u00e9e athl\u00e8te, probablement la catcheuse la plus athl\u00e9tique de l&rsquo;histoire de la WWE. C&rsquo;est la seule autre femme \u00e0 avoir remport\u00e9 le main event de WrestleMania. Elle \u00e9tait excit\u00e9e d&rsquo;avoir un match contre Bianca Belair \u00e0 SummerSlam. Son retour a sauv\u00e9 le match de Belair \u00e0 SummerSlam. Quand Sasha Banks n&rsquo;a pas pu faire le match, il a \u00e9t\u00e9 d\u00e9cid\u00e9 d&rsquo;appeler le plus gros nom. Elle attendait de reprendre son titre depuis qu&rsquo;elle est partie, et Belair n&rsquo;est pas pr\u00eate. Elle peut s&rsquo;autoproclamer la EST et penser qu&rsquo;elle est la meilleure, mais on sait que c&rsquo;est un mensonge. Bianca Belair fait son entr\u00e9e.<\/p>\n\n\n\n<p>Bianca Belair dit que le titre \u00e9tait plus qu&rsquo;un titre pour elle. C&rsquo;\u00e9tait une partie d&rsquo;elle pendant 132 jours, ce moment \u00e0 SummerSlam est grav\u00e9 dans son esprit. Elle a fait tout ce chemin pour perdre en 26 secondes. Becky Lynch vient ici et dit son nom comme si elle la connaissait, sauf qu&rsquo;elle ne la connait pas. Bianca Belair explique pourquoi elle est appel\u00e9e la EST de la WWE. Elle dit ensuite que Roman Reigns d\u00e9fend son titre ce soir, alors pourquoi pas Becky Lynch ? La championne r\u00e9pond qu&rsquo;elle s&rsquo;en fout de ce que fait Roman Reigns et refuse !<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Dolph Ziggler et Robert Roode marchent et Ziggler s&rsquo;arr\u00eate pour parler \u00e0 Toni Storm. Il lui propose une place au premier rang. Storm r\u00e9pond qu&rsquo;elle l&rsquo;aime bien, mais elle soutient plus Rick Boogs, puis Ziggler part.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Rick Boogs acc par Shinsuke Nakamura vs Dolph Ziggler acc  par Robert Roode<\/strong><\/p>\n\n\n\n<p>En fin de match, Rick Boogs fait une prise \u00e0 Dolph Ziggler et enchaine avec le tomb\u00e9 pour la victoire.<\/p>\n\n\n\n<p><em>Gagnant : Rick Boogs<\/em><\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Becky Lynch est arr\u00eat\u00e9e par Sonya Deville et Adam Pearce, qui lui disent que Bianca Belair aura son rematch pour le titre f\u00e9minin de SmackDown. Lynch r\u00e9pond que \u00e7a arrivera lorsqu&rsquo;elle sera pr\u00eate. Ils lui disent que ce match aura lieu \u00e0 Extreme Rules, un contrat sera sign\u00e9 la semaine prochaine.<\/p>\n\n\n\n<p>&#8211; Dans la Gorilla Position, Kayla Braxton demande \u00e0 Seth Rollins pourquoi il a choisi un match contre Cesaro. Rollins r\u00e9pond que c&rsquo;est le moment pour une nouveau d\u00e9part. Il a regard\u00e9 son match contre Edge plusieurs fois. Il a trouv\u00e9 ce qui a men\u00e9 Edge \u00e0 l&#8217;emporter. Il va utiliser cette information pour battre son ennemi jur\u00e9.<\/p>\n\n\n\n<p>&#8211; Cesaro fait sont entr\u00e9e et on part \u00e0 la pause.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/03\/deuxieme-heure-de-smackdown-16\/\">Pour la suite de Smackdown, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce Smackdown, cliquez ici. WWE SmackDown Jacksonville, Floride, 3 septembre 2021 Les commentateurs sont Michael Cole et Corey Graves &#8211; Let WWE Friday Night SmackDown d\u00e9bute sur une vid\u00e9o concernant ce qu&rsquo;il s&rsquo;est pass\u00e9 la semaine derni\u00e8re. Les pyros \u00e9clatent et les commentateurs nous souhaitent la bienvenue. &#8211; Les Usos arrivent ensuite sur&#8230;<\/p>\n","protected":false},"author":4,"featured_media":57459,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,36,23],"tags":[],"ppma_author":[292],"class_list":["post-57458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=57458"}],"version-history":[{"count":5,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57458\/revisions"}],"predecessor-version":[{"id":57475,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57458\/revisions\/57475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/57459"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=57458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=57458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=57458"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=57458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}