{"id":57409,"date":"2021-09-02T23:16:00","date_gmt":"2021-09-02T23:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=57409"},"modified":"2021-09-03T22:09:56","modified_gmt":"2021-09-03T22:09:56","slug":"resultats-et-video-du-nxt-uk-2-septembre-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/02\/resultats-et-video-du-nxt-uk-2-septembre-2021\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du NXT UK, 2 Septembre 2021!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/02\/regardez-le-nxt-uk-du-2-septembre-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour voir ce NXT UK, cliquez ici.<\/strong><\/a><\/li><\/ul>\n\n\n\n<p><strong>WWE NXT UK Londres, BT Sport, 2 septembre 2021<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Andy Shepherd et Nigel McGuinness.<\/p>\n\n\n\n<p>&#8211; Le NXT UK d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue.<\/p>\n\n\n\n<p>&#8211; Les catcheuses arrivent sur le ring pour le premier match, mais Blair Davenport attaque Nina Samuels pendant son entr\u00e9e. Davenport la pousse en bas du coin pendant qu&rsquo;elle posait et la lance contre les barricades. Sid Scala arrive avec des officiels sur le ring. Scala lui demande de se calmer, mais Davenport frappe Scala et lui fait un Falcon Arrow ! Plus d&rsquo;officiels arrivent pour arr\u00eater Davenport.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur le match entre Aoife Valkyrie et Jinny de la semaine derni\u00e8re. Les commentateurs annoncent que Valkyrie souffre d&rsquo;une blessure tr\u00e8s s\u00e9rieuse et sera absente pour une p\u00e9riode ind\u00e9termin\u00e9e. En coulisse, Jinny dit qu&rsquo;elle n&rsquo;a peut-\u00eatre pas gagn\u00e9 le match, mais c&rsquo;est elle qui est debout. Elle avait d\u00e9clar\u00e9 que Valkyrie n&rsquo;allait pas pouvoir survire. Le monde entier a vu la chute de Valkyrie.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Symbiosis.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Jack Starz et Dave Mastiff battent Dan Maloney et Andy Wild<\/strong> avec un Headbutt de Starz sur Maloney et Mastiff prend la tag pour faire son Cannonball contre le coin pour le compte de trois.<\/p>\n\n\n\n<p>&#8211; \u00c0 l&rsquo;ext\u00e9rieur, Pretty Deadly fait une vid\u00e9o TikTok pour la WWE. Ils se font interrompe par Gallus. Wolfgang dit qu&rsquo;il est d\u00e9gout\u00e9 d&rsquo;avoir ce duo comme champion. Wolfgang pousse Lewis dans la fontaine et Gallus quitte.<\/p>\n\n\n\n<p><strong>Emilia McKenzie bat Amale<\/strong> lorsqu&rsquo;elle renverse le finisher d&rsquo;Amale avec un Roll Up pour le compte de trois.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FJasonDarkCashDescoteaux%2Fposts%2F4807337695966057&amp;show_text=true&amp;width=500\" width=\"500\" height=\"392\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n<p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; En coulisse, Sid Scala re\u00e7oit toujours l&rsquo;aide du m\u00e9decin apr\u00e8s l&rsquo;attaque de Davenport.<\/p>\n\n\n\n<p>&#8211; En colisse, on retrouve Oliver Carter et Ashton Smith. Ils croisent Saxon Huxley qui brise un vestiaire. Carter dit qu&rsquo;ils aiment bien son attitude. Huxley dit qu&rsquo;ils peuvent compter sur lui. Carter et Smith approuvent pour l&rsquo;avoir comme partenaire contre Symbiosis.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Sam Gradwell et Wolfgang qui vont s&rsquo;affronter la semaine prochaine dans le tournoi Heritage.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Tournoi Heritage Cup<\/strong><\/p>\n\n\n\n<p>Teoman bat Nathan Frazer au round 5 avec 2-1 lorsqu&rsquo;il \u00e9vtie un saut du coin de Frazer alors qu&rsquo;il \u00e9tait distrait par Rohan. Teoman enchaine avec un Reverse DDT pour le compte de trois.<\/p>\n\n\n\n<p>L&rsquo;\u00e9pisode se termine avec une c\u00e9l\u00e9bration de Teoman.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/09\/02\/regardez-le-nxt-uk-du-2-septembre-2021\/\" target=\"_blank\"><strong>Pour voir ce NXT UK, cliquez ici.<\/strong><\/a><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce NXT UK, cliquez ici. WWE NXT UK Londres, BT Sport, 2 septembre 2021 Les commentateurs sont Andy Shepherd et Nigel McGuinness. &#8211; Le NXT UK d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue. &#8211; Les catcheuses arrivent sur le ring pour le premier match, mais Blair Davenport attaque Nina Samuels pendant&#8230;<\/p>\n","protected":false},"author":4,"featured_media":57411,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"ppma_author":[292],"class_list":["post-57409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=57409"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57409\/revisions"}],"predecessor-version":[{"id":57412,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57409\/revisions\/57412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/57411"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=57409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=57409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=57409"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=57409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}