{"id":57300,"date":"2021-09-01T17:49:00","date_gmt":"2021-09-01T17:49:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=57300"},"modified":"2021-09-01T14:56:41","modified_gmt":"2021-09-01T14:56:41","slug":"jour-de-liberte-pour-plusieurs-anciens-de-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/09\/01\/jour-de-liberte-pour-plusieurs-anciens-de-la-wwe\/","title":{"rendered":"Jour De Libert\u00e9 Pour Plusieurs Anciens de la WWE!"},"content":{"rendered":"\n<p>Six anciens lutteurs de la WWE deviennent aujourd&rsquo;hui des agents libres, leurs clauses de non-comp\u00e9tition de 90 jours expirant ce jour :Buddy Murphy, Braun Strowman, Lana, Ruby Riott, Santana Garrett et Aleister Black<\/p>\n\n\n\n<p><strong>Aleister Black<\/strong>, qui utilise maintenant le nom de Malakai Black \u00e0 la AEW, avait une situation contractuelle diff\u00e9rente et a pu faire ses d\u00e9buts il y a plusieurs semaines. \u00c9tant sous son contrat NXT, il n&rsquo;avait qu&rsquo;une close de 30 jours dans son cas.<\/p>\n\n\n\n<p><strong>Ruby Riott<\/strong>, maintenant appel\u00e9 Ruby Soho, a publi\u00e9 sa troisi\u00e8me vignette teaser hier soir et la rumeur dit qu\u2019elle signera bient\u00f4t avec la AEW. Ci-dessous, sa derni\u00e8re vid\u00e9o.<\/p>\n\n\n\n<p><strong> CJ Perry<\/strong>  la femme de Rusev. Il n\u2019y a pas de rumeur sur l\u2019avenir de Lana dans la lutte professionnelle, mais elle appara\u00eetra dans Surreal Life de VH1 \u00e0 partir du 27 septembre. Elle a r\u00e9cemment annonc\u00e9 ses premi\u00e8res apparitions post-WWE sur Instagram. Elle appara\u00eetra au Jimmy World\u2019s Order \u00e0 Los Angeles le 12 septembre, puis \u00e0 la convention Legends of the Ring \u00e0 Iselin, new jersey, le 2 octobre.<\/p>\n\n\n\n<p><strong>Santana Garrett <\/strong>a post\u00e9 un message \u00ab COMING SOON \u00bb sur Instagram la semaine derni\u00e8re, puis a sous-entendu qu\u2019elle \u00ab faisait des mouvements \u00bb dans un autre post lundi.Wait and see comme on dit.<\/p>\n\n\n\n<p><strong>Murphy<\/strong>, qui utilise maintenant le nom de Buddy Matthews dans sa carri\u00e8re post-WWE, a cr\u00e9e un bad buzz involontaire aujourd\u2019hui apr\u00e8s avoir post\u00e9 un graphique faisant r\u00e9f\u00e9rence \u00e0 son expiration de non-comp\u00e9tition WWE. Le message comprenait une photo de quelqu\u2019un se lib\u00e9rant des cha\u00eenes sur ses poignets.<br><\/p>\n\n\n\n<p>Le Dernier mais non le moindre, <strong>Braun Strowman<\/strong> qui utilisera apparemment \u00ab Titan \u00bb comme nom de ring post-WWE, a teas\u00e9 plus t\u00f4t cette semaine qu\u2019il ferait une annonce \u00e0 12 heures ce mercredi. Il a eut des rumeur qu&rsquo;il pourrait signer avec la AEW ou Impact Wrestling, mais il n\u2019y a pas de mot sur o\u00f9 il finira. Il a \u00e9galement sorti de nouveaux produits d\u00e9riv\u00e9s \u00ab RISE \u00bb.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Six anciens lutteurs de la WWE deviennent aujourd&rsquo;hui des agents libres, leurs clauses de non-comp\u00e9tition de 90 jours expirant ce jour :Buddy Murphy, Braun Strowman, Lana, Ruby Riott, Santana Garrett et Aleister Black Aleister Black, qui utilise maintenant le nom de Malakai Black \u00e0 la AEW, avait une situation contractuelle diff\u00e9rente et a pu faire&#8230;<\/p>\n","protected":false},"author":4,"featured_media":57301,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,22,4],"tags":[],"ppma_author":[292],"class_list":["post-57300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-news"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=57300"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57300\/revisions"}],"predecessor-version":[{"id":57302,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57300\/revisions\/57302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/57301"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=57300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=57300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=57300"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=57300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}