{"id":57253,"date":"2021-08-31T10:35:00","date_gmt":"2021-08-31T10:35:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=57253"},"modified":"2021-08-31T18:40:36","modified_gmt":"2021-08-31T18:40:36","slug":"les-participantes-a-la-womens-casino-battle-royal-le-roster-de-la-aew-est-comparable-a-celui-de-la-wcw-en-1997","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/08\/31\/les-participantes-a-la-womens-casino-battle-royal-le-roster-de-la-aew-est-comparable-a-celui-de-la-wcw-en-1997\/","title":{"rendered":"Les participantes \u00e0 la Women&rsquo;s Casino Battle Royal! \/ Le roster de la AEW est comparable \u00e0 celui de la WCW en 1997!"},"content":{"rendered":"\n<p>Ce dimanche, la All Elite Wrestling proposera son prochain PPV avec All Out. Le Main Event verra ainsi notamment Kenny Omega d\u00e9fendre son titre de la compagnie contre Christian Cage alors que CM Punk fera lui ses d\u00e9buts contre Darby Allin. La lutte f\u00e9minine sera \u00e9galement \u00e0 l&rsquo;honneur avec Britt Baker d\u00e9fendant sa ceinture contre Kris Statlander.<\/p>\n\n\n\n<p>En plus de ce match pour la ceinture f\u00e9minine, 21 autres lutteuses seront en action lors du Buy-In \u00e0 l&rsquo;action du retour de la Casino Battle Royal. Voici la derni\u00e8re liste des participantes confirm\u00e9es:<\/p>\n\n\n\n<p>Nyla Rose<br>Hikaru Shida<br>Thunder Rosa<br>Tay Conti<br>Penelope Ford<br>Jade Cargill<br>The Bunny<br>Big Swole<br>Red Velvet<br>Diamante<br>Julia Hart<br>Emi Sakura<\/p>\n\n\n\n<p>12 lutteuses ont donc \u00e9t\u00e9 confirm\u00e9es laissant ainsi 9 places libres. Celles-ci pourraient \u00eatre occup\u00e9es par des lutteuses r\u00e9guli\u00e8res comme Riho, Leyla Hirsch, Serena Deeb, Abadon, KiLynn King ou encore Abadon. Ruby Riott est \u00e9galement fortement pressentie pour \u00eatre la lutteuse myst\u00e8re #21.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Tony Khan \u00e9tait l&rsquo;invit\u00e9 de Busted Open Radio ou il nous a parl\u00e9 de l\u2019AEW en la comparant au roster 1997 de la WCW.<\/p>\n\n\n\n<p>Il nous dit :&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cJe ne veux pas comparer notre roster \u00e0 quoi que ce soit, jamais, mais j&rsquo;aime comparer notre roster parfois \u00e0 ce que je pense \u00eatre la caract\u00e9ristique d&rsquo;un grand roster, qui \u00e9tait la WCW de 1997 o\u00f9 vous aviez toutes ces stars et tous ces jeunes talents.<\/p><p>\u00a0Je fais vraiment de mon mieux pour essayer d&rsquo;utiliser le roster encore mieux qu&rsquo;il ne l&rsquo;\u00e9tait lorsque la compagnie avait du succ\u00e8s et qu&rsquo;elle g\u00e9n\u00e9rait de l&rsquo;argent en 97 et 98. Ils avaient beaucoup de jeunes talents dont ils n&rsquo;avaient pas conscience et qu&rsquo;ils auraient pu construire pour l&rsquo;avenir afin d&rsquo;en faire une compagnie rentable qui ne serait jamais amen\u00e9e \u00e0 fermer. Ils auraient pu en faire une machine \u00e0 imprimer de l&rsquo;argent s&rsquo;ils avaient d\u00e9velopp\u00e9 les jeunes talents qu&rsquo;ils avaient en interne comme Chris Jericho, Dean Malenko, Eddie Guerrero et Rey Mysterio.\u00a0<\/p><p>J&rsquo;essaie de construire des stars pour l&rsquo;avenir et c&rsquo;est pour cela qu&rsquo;il y a tant de stars locales qui sont pr\u00e9sent\u00e9es \u00e0 All Out. Il y a de grandes opportunit\u00e9s ici et je ne pense pas que Jericho, Mysterio et Guerrero aient eu ces m\u00eames opportunit\u00e9s lorsqu&rsquo;ils \u00e9taient dans un roster avec des noms de tous les temps comme Hulk Hogan, Ric Flair, Randy Savage et Roddy Piper.\u00a0<\/p><p>Ils ont construit une grande entreprise de t\u00e9l\u00e9vision avec ce roster qui n&rsquo;a malheureusement pas dur\u00e9, mais je pense qu&rsquo;il aurait dur\u00e9 plus longtemps s&rsquo;ils avaient construit les jeunes stars comme j&rsquo;essaie de le faire.\u201d<\/p><\/blockquote>\n\n\n\n<p>Tr\u00e8s belle analogie faite par Tony Khan entre le roster de l\u2019AEW et celui de la WCW en 1997. Il est vrai que la WCW avait les meilleurs jeunes catcheurs \u00e0 l&rsquo;\u00e9poque et qui se trouvaient presque tous dans la division Cruiserweight. La division Heavyweight n&rsquo;\u00e9tait r\u00e9serv\u00e9e qu&rsquo;\u00e0 certains catcheurs tr\u00e8s grands et costaud physiquement et qui \u00e9taient quasiment tous des superstars.&nbsp;<\/p>\n\n\n\n<p>L\u00e0 o\u00f9 Tony Khan veut diff\u00e9rer c\u2019est dans le traitement de ces jeunes talents, l\u00e0 o\u00f9 la WCW les a d\u00e9laiss\u00e9s, la AEW veut au contraire capitaliser et en faire de futures stars. C\u2019est peut-\u00eatre la future clef du succ\u00e8s pour la AEW, savoir associer le talent et la jeunesse avec le talent ainsi que l&rsquo;exp\u00e9rience de grandes superstars. Plusieurs exemples nous le prouvent sur la carte du prochain PPV All Out 2021, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/08\/29\/carte-du-aew-all-out-2021-de-dimanche-prochain\/\" target=\"_blank\">vous pouvez\u00a0retrouver la carte juste ici.<\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ce dimanche, la All Elite Wrestling proposera son prochain PPV avec All Out. Le Main Event verra ainsi notamment Kenny Omega d\u00e9fendre son titre de la compagnie contre Christian Cage alors que CM Punk fera lui ses d\u00e9buts contre Darby Allin. La lutte f\u00e9minine sera \u00e9galement \u00e0 l&rsquo;honneur avec Britt Baker d\u00e9fendant sa ceinture contre&#8230;<\/p>\n","protected":false},"author":609,"featured_media":57256,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,65,22,4],"tags":[],"ppma_author":[295],"class_list":["post-57253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-all-out","category-indy","category-news"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=57253"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57253\/revisions"}],"predecessor-version":[{"id":57257,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57253\/revisions\/57257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/57256"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=57253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=57253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=57253"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=57253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}