{"id":57224,"date":"2021-08-31T05:15:00","date_gmt":"2021-08-31T05:15:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=57224"},"modified":"2021-08-31T13:30:25","modified_gmt":"2021-08-31T13:30:25","slug":"ric-flair-a-all-out-la-reaction-de-vince-mcmahon-sur-son-depart-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/08\/31\/ric-flair-a-all-out-la-reaction-de-vince-mcmahon-sur-son-depart-et-plus\/","title":{"rendered":"Ric Flair \u00e0 All-Out! La R\u00e9action de Vince McMahon sur son D\u00e9part! Retour des Four Horsemen \u00e0 la AEW et Plus!"},"content":{"rendered":"\n<p>Ric Flair \u00e9tait l&rsquo;invit\u00e9 du dernier \u00e9pisode de Oral Sessions, podcast de Rene \u00ab\u00a0Young\u00a0\u00bb Paquette o\u00f9 il nous a parl\u00e9 de Vince McMahon, des Four Horsemen mais aussi de ce qu\u2019il va faire ce week-end.<\/p>\n\n\n\n<p>Rene Paquette \u00e9tait en train de dire qu\u2019elle est heureuse de voir Ric Flair heureux et vivre sa meilleure et elle ajoute qu\u2019il n\u2019est plus sous contrat avec la WWE et qu\u2019il n\u2019a aucune clause qui lui interdit d&rsquo;appara\u00eetre dans un autre show. Elle dit qu\u2019elle a h\u00e2te de voir o\u00f9 est qu\u2019il va appara\u00eetre puis Ric Flair lui demande o\u00f9 est ce qu\u2019il peut la voir elle.<\/p>\n\n\n\n<p>Rene Paquette lui r\u00e9pond que pour la voir, il faudra se rendre \u00e0 un show de la AEW car elle est souvent avec son mari pour ses matchs. Flair lui demande ensuite si elle sera \u00e0 Chicago pour le week-end (elle r\u00e9pond oui) et c\u2019est l\u00e0 que Ric Flair lui dit qu\u2019il sera lui aussi \u00e0 Chicago pour le week-end avec sa femme.<\/p>\n\n\n\n<p>Ce dimanche 5 ao\u00fbt la AEW tiendra son plus grand show de l\u2019ann\u00e9e en direct de Chicago et Andrade El Idolo, le futur gendre de Ric Flair, sera de la partie dans un match face \u00e0 PAC. Sachant que Ric Flair sera \u00e0 Chicago en coulisse, il ne serait pas impossible de le voir accompagner son futur gendre pour ce match, comme il l\u2019a fait lors de Triplemania XXIX.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/08\/29\/carte-du-aew-all-out-2021-de-dimanche-prochain\/\" target=\"_blank\" rel=\"noreferrer noopener\">Carte Actuelle du AEW All-Out 2021 ici,<\/a><\/strong><\/li><\/ul>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Toujours lors de ce podcast avec l&rsquo;\u00e9pouse de l&rsquo;ancien Dean Ambrose, Ric Flair a parl\u00e9 de la r\u00e9action de Vince McMahon lors qu&rsquo;il lui a annonc\u00e9 qu&rsquo;il quittait la WWE. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cJ&rsquo;ai parl\u00e9 \u00e0 Vince apr\u00e8s que ce soit fini et j&rsquo;ai dit, \u00ab\u00a0<em>peu importe les chemins que nos vies prennent, nous serons toujours fr\u00e8res<\/em>\u00ab\u00a0. Il m&rsquo;a r\u00e9pondu : \u00ab\u00a0<em>Tu as bien raison<\/em>\u00ab\u00a0. Ashley (Charlotte Flair) ne partira jamais d&rsquo;ici, elle n&rsquo;a jamais \u00e9t\u00e9 aussi heureuse. \u00c9videmment, ils ne sont pas en col\u00e8re contre moi.\u201d<\/p><\/blockquote>\n\n\n\n<p>Ric Flair nous dit que Vince McMahon n\u2019a aucune animosit\u00e9 ou \u00e9nervement envers Ric Flair suite \u00e0 son d\u00e9part de la f\u00e9d\u00e9ration et il nous dit aussi que Charlotte Flair ne quittera sans doute jamais la WWE car elle s\u2019y sent tr\u00e8s bien, m\u00eame si il ne faut jamais dire jamais dans la vie.<\/p>\n\n\n\n<p>Charlotte Flair est l\u2019une des plus grandes et meilleures catcheuses \u00e0 la WWE de ces derni\u00e8res ann\u00e9es, la perdre serait un vrai \u00e9chec pour la f\u00e9d\u00e9ration de Vince McMahon, m\u00eame si nous le savons, personne n\u2019est irrempla\u00e7able.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Il nous parle de l&rsquo;\u00e9ventualit\u00e9 de travailler pour la AEW dans le futur :&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cHypoth\u00e9tiquement, si je voulais travailler \u00e0 la AEW, j&rsquo;irais voir Vince et lui dirais : \u00ab\u00a0J<em>e veux faire \u00e7a et je veux remonter sur le ring et je sais que tu n&rsquo;aimes pas \u00e7a, que je sois mis \u00e0 terre ou autre chose<\/em>\u00ab\u00a0. Il me r\u00e9pondrait : \u00ab\u00a0<em>En fin de compte, ce qui est le mieux pour toi est le mieux pour moi<\/em>\u00ab\u00a0.<\/p><\/blockquote>\n\n\n\n<p>Ric Flair a un tr\u00e8s grand respect pour Vince McMahon et c\u2019est pour cette raison que s\u2019il signe \u00e0 l\u2019AEW, il ira d\u2019abord le voir pour lui en parler par pure respect et courtoisie. M\u00eame si Vince n\u2019est pas pour que Ric Flair remonte sur un ring ou qu\u2019il soit impliqu\u00e9 physiquement, il respectera sa d\u00e9cision.<\/p>\n\n\n\n<p>Il nous parle ensuite d\u2019un retour sur un ring pour un combat ou m\u00eame d\u2019une apparition et un retour d\u2019un groupe\/\u00e9quipe mythique :&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cRemonter sur le ring et divertir ? Absolument. Je demanderais \u00e0 Vince d&rsquo;abord parce que je lui dois bien \u00e7a. J&rsquo;ai re\u00e7u un texto de Randy Orton, je ne peux pas vous le lire, je ne l&rsquo;ai pas. Laissez-moi vous dire quelque chose, si vous \u00eates \u00e0 l&rsquo;AEW et que les Four Horsemen se r\u00e9unissent, tout le monde regarde. Arn Anderson, Tully Blanchard, Barry Windham est assis \u00e0 un kilom\u00e8tre d&rsquo;ici, et JJ Dillon, vous le faites venir en avion. Vous faites une interview d&rsquo;une demi-heure avec Tony Schiavone et Jim Ross.\u201d<\/p><\/blockquote>\n\n\n\n<p>Ric Flair nous dit qu\u2019il serait tr\u00e8s heureux de remonter sur un ring et de divertir. Pour la AEW comme il l\u2019a dit pr\u00e9c\u00e9demment, il devra parler d\u2019abord avec Vince McMahon par respect et ensuite il nous parle des 4 Horsemen, son groupe mythique qui pourrait se r\u00e9unir l\u00e0-bas.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Il est revenu sur ce qui a men\u00e9 \u00e0 son d\u00e9part de la WWE.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cJ&rsquo;avais un tas d&rsquo;opportunit\u00e9s en attente. J&rsquo;avais des choses que je faisais actuellement au moment o\u00f9 j&rsquo;ai sign\u00e9 mon contrat. Ils les ont autoris\u00e9s. Wendy a pu garder son magasin. Ce sont des choses importantes.\u00a0<\/p><p>J&rsquo;ai pu garder les cam\u00e9os et quelques autres choses. Quelques projets se sont concr\u00e9tis\u00e9s et je suis arriv\u00e9 au point o\u00f9 je leur ai demand\u00e9, je les ai probablement \u00e9puis\u00e9s en leur demandant, non pas de m&rsquo;accorder des droits acquis, mais de me laisser les faire.\u00a0<\/p><p>Naturellement, la r\u00e9ponse a \u00e9t\u00e9: \u00ab\u00a0Tu peux les faire, peut-\u00eatre\u00a0\u00bb. Je voulais enfin, comme je l&rsquo;ai fait pendant trois ans, vivre sans n&rsquo;\u00eatre qu&rsquo;une masse salariale. C&rsquo;est tout ce que c&rsquo;\u00e9tait. Il n&rsquo;y a pas d&rsquo;animosit\u00e9, c&rsquo;est juste du business. Je voulais essayer quelque chose et ils avaient une vision diff\u00e9rente.\u201d<\/p><\/blockquote>\n\n\n\n<p>Ric Flair nous dit que son d\u00e9part n\u2019est pas d\u00fb \u00e0 des tensions avec la WWE mais plut\u00f4t \u00e0 des diff\u00e9rences de point de vue concernant son futur. Alors que Ric Flair aimerait continuer \u00e0 concr\u00e9tiser certains projets et \u00eatre actif, la WWE ne semble pas avoir de plans pour Ric Flair ni dans le court terme, ni dans le long terme.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cPour \u00eatre pay\u00e9, en gros, beaucoup d&rsquo;argent. Il n&rsquo;y a rien de mal \u00e0 \u00e7a. Je participe \u00e0 NWA 73, ce qui est \u00e9norme. J&rsquo;ai \u00e9t\u00e9 le dernier champion du monde itin\u00e9rant, 365, deux fois le samedi et le dimanche. J&rsquo;ai fait \u00e7a pendant cinq ans.\u00a0<\/p><p>Peu de gens peuvent dire \u00e7a. Je n&rsquo;aurais probablement pas pu le faire. Pas parce que Vince aurait dit non. Il ne l&rsquo;aurait jamais su. Je ne suis pas parti avec de l&rsquo;animosit\u00e9. Quand j&rsquo;ai failli mourir il y a quatre ans, j&rsquo;ai d\u00e9couvert qui \u00e9taient mes amis quand je me suis r\u00e9veill\u00e9, et j&rsquo;ai d\u00e9couvert qui \u00e9taient mes amis quand j&rsquo;ai quitt\u00e9 la WWE.\u00a0<\/p><p>Vous seriez surpris, du c\u00f4t\u00e9 positif, du nombre de personnes qui m&rsquo;ont tendu la main. Je peux aussi vous dire que les gens qui ont lanc\u00e9 des rumeurs n&rsquo;ont pas besoin d&rsquo;en parler. \u00ab\u00a0<em>Oh, il va \u00e0 la AEW. Lui et Tony Khan sont amis<\/em>\u00ab\u00a0. Oui, nous sommes amis, mais je n&rsquo;ai pas entendu un mot de Tony Khan. S&rsquo;il te demande, dis-lui que je suis dans le coin.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Il a dit aussi, qu\u2019a la WWE, il \u00e9tait litt\u00e9ralement tr\u00e8s bien pay\u00e9 \u00e0 ne rien faire, m\u00eame si il n&rsquo;y a rien de mal \u00e0 \u00e7a, Ric Flair nous dit aussi qu\u2019il aurait aim\u00e9 faire bien plus et c\u2019est aussi une raison de son d\u00e9part.<\/p>\n\n\n\n<p>Ric Flair parle \u00e9galement qu\u2019il a eu \u00e9norm\u00e9ment de retours positifs \u00e0 propos de son d\u00e9part de la WWE. Il nous dit qu\u2019il a d\u00e9couvert qui \u00e9taient ses vrais amis \u00e0 ce moment-l\u00e0, comme \u00e0 l&rsquo;\u00e9poque o\u00f9 il avait failli mourir il y\u2019a quelques ann\u00e9es (AVC).<\/p>\n\n\n\n<p>Il est un tr\u00e8s grand ami de Tony Khan donc il n\u2019est pas impossible de le voir \u00e0 la AEW m\u00eame si Ric Flair aime en rire pour le moment.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ric Flair \u00e9tait l&rsquo;invit\u00e9 du dernier \u00e9pisode de Oral Sessions, podcast de Rene \u00ab\u00a0Young\u00a0\u00bb Paquette o\u00f9 il nous a parl\u00e9 de Vince McMahon, des Four Horsemen mais aussi de ce qu\u2019il va faire ce week-end. Rene Paquette \u00e9tait en train de dire qu\u2019elle est heureuse de voir Ric Flair heureux et vivre sa meilleure et&#8230;<\/p>\n","protected":false},"author":609,"featured_media":57225,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,22,4],"tags":[],"ppma_author":[295],"class_list":["post-57224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-news"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=57224"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57224\/revisions"}],"predecessor-version":[{"id":57231,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57224\/revisions\/57231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/57225"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=57224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=57224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=57224"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=57224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}