{"id":57094,"date":"2021-08-29T07:57:00","date_gmt":"2021-08-29T07:57:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=57094"},"modified":"2021-08-29T16:06:30","modified_gmt":"2021-08-29T16:06:30","slug":"un-compliment-de-bret-hart-pour-del-rio-la-fin-de-contrat-de-page-avec-la-wwe-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/08\/29\/un-compliment-de-bret-hart-pour-del-rio-la-fin-de-contrat-de-page-avec-la-wwe-et-plus\/","title":{"rendered":"Un Compliment de Bret Hart pour Del Rio! \/ La Fin de Contrat de Page avec la WWE, et Plus!"},"content":{"rendered":"\n<p>Il ne sont plus ensemble mais voici des nouvelles de l&rsquo;ancien couple qui a fait beaucoup parler lors des derni\u00e8res ann\u00e9es \u00e0 la WWE et hors de la compagnie.<\/p>\n\n\n\n<p>Comme vous le savez surement, les Superstars de la WWE ont eu l&rsquo;obligation d&rsquo;arr\u00eater leur cha\u00eene Twitch, Only Fans ou autre. Et bien, il y a une personne qui a visiblement r\u00e9ussi \u00e0 continuer et c&rsquo;est Paige.\u00a0Cette ancienne championne des Divas a subi une lourde blessure au cou en 2017 et a d\u00fb mettre fin subitement \u00e0 sa carri\u00e8re dans le ring.\u00a0Depuis, elle s&rsquo;est cr\u00e9\u00e9e une communaut\u00e9 lors de ses lives Twitch et\u00a0esp\u00e8re pouvoir remonter sur le ring un jour, \u00e0 l&rsquo;instar de Daniel Bryan ou encore Edge, et ce bien qu&rsquo;elle l&rsquo;a fait une premi\u00e8re fois en revenant pour une courte dur\u00e9e. <\/p>\n\n\n\n<p>Justement, au cours d&rsquo;un r\u00e9cent stream, Paige a mis au clair sa situation contractuelle avec la WWE.\u00a0La premi\u00e8re championne de NXT avoue \u00eatre toujours son contrat avec la f\u00e9d\u00e9ration et que celui-ci se termine en juin 2022. Elle ne sait pas si un nouveau contrat lui sera propos\u00e9, mais si tel est le cas, Paige esp\u00e8re qu&rsquo;elle pourra continuer son aventure sur Twitch.<\/p>\n\n\n\n<p>Nous verrons donc l&rsquo;ann\u00e9e prochaine si la WWE compte garder Paige, malgr\u00e9 son absence lors des shows pour le moment.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Quand on parle de Page on ne peut s&#8217;emp\u00eacher de penser \u00e0 Del Rio. <\/p>\n\n\n\n<p>El Patron \u00e9tait l&rsquo;invit\u00e9 de Unskripted by Sportskeeda sur YouTube o\u00f9 il nous a r\u00e9v\u00e9l\u00e9 ce que lui a confi\u00e9 Bret Hart sur son travail de heel lors de son passage \u00e0 la WWE.<\/p>\n\n\n\n<p>Il nous dit :&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cJe me souviens de Bret \u00ab\u00a0The Hitman\u00a0\u00bb Hart qui est venu me dire \u00e7a, et je me sens tellement chanceux que quelqu&rsquo;un comme lui m&rsquo;ait dit \u00e7a. Il est venu me voir et m&rsquo;a dit : \u00ab\u00a0Mec, tu es un gars tellement gentil, mais quand je te vois \u00e0 la t\u00e9l\u00e9 et que tu fais ce sourire en coin, j&rsquo;ai envie de frapper la t\u00e9l\u00e9 tout de suite. Tu es tellement bon en tant que m\u00e9chant que tu ne devrais jamais \u00eatre un gentil. Tu es le meilleur. Tu es le meilleur en tant que heel\u201d, et puis tu sais, c&rsquo;\u00e9tait un compliment incroyable venant du meilleur du business, une de mes idoles\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Un beau compliment de la part du l\u00e9gendaire Bret Hart qui a appr\u00e9ci\u00e9 le travail en tant que heel de Alberto El Patron lorsqu&rsquo;il \u00e9tait Alberto Del Rio \u00e0 la WWE.<\/p>\n\n\n\n<p>Alberto El Patron est pass\u00e9 par la WWE de 2009 \u00e0 2014 et a fait un retour entre 2015 et 2016. Son histoire avec la WWE ne s\u2019est pas tr\u00e8s bien termin\u00e9e entre probl\u00e8mes personnels et probl\u00e8mes en coulisses avec quelques superstars.<\/p>\n\n\n\n<p>Il esp\u00e8re un jour retourner \u00e0 la WWE et remporter un titre de champion du monde avant de pourquoi pas \u00eatre intronis\u00e9 au Hall of Fame de la f\u00e9d\u00e9ration comme son oncle, le l\u00e9gendaire Mil Mascaras, qui a \u00e9t\u00e9 intronis\u00e9 en 2012.<\/p>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/NEvOvM0wwYA\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/center>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Il ne sont plus ensemble mais voici des nouvelles de l&rsquo;ancien couple qui a fait beaucoup parler lors des derni\u00e8res ann\u00e9es \u00e0 la WWE et hors de la compagnie. Comme vous le savez surement, les Superstars de la WWE ont eu l&rsquo;obligation d&rsquo;arr\u00eater leur cha\u00eene Twitch, Only Fans ou autre. Et bien, il y a&#8230;<\/p>\n","protected":false},"author":609,"featured_media":57095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,22,4,23],"tags":[],"ppma_author":[295],"class_list":["post-57094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-news","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=57094"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57094\/revisions"}],"predecessor-version":[{"id":57096,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/57094\/revisions\/57096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/57095"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=57094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=57094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=57094"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=57094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}