{"id":56720,"date":"2021-08-26T05:11:00","date_gmt":"2021-08-26T05:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=56720"},"modified":"2021-08-26T13:58:27","modified_gmt":"2021-08-26T13:58:27","slug":"roman-reigns-tient-ses-promesses-a-un-fan-de-cena-en-pleure-il-parle-dessayer-dimiter-bret-hart-undertaker-et-ric-flair","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/08\/26\/roman-reigns-tient-ses-promesses-a-un-fan-de-cena-en-pleure-il-parle-dessayer-dimiter-bret-hart-undertaker-et-ric-flair\/","title":{"rendered":"Roman Reigns tient ses promesses \u00e0 un fan de Cena en Pleure! Il parle d&rsquo;essayer d&rsquo;imiter Bret Hart, Undertaker et Ric Flair!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Roman Reigns a fait une interview avec\u00a0<a href=\"https:\/\/youtu.be\/sPRElVVJMNA\">ODE<\/a>\u00a0avant SummerSlam o\u00f9 il a conserv\u00e9 le titre universel de la WWE sur John Cena dans l&rsquo;\u00e9v\u00e9nement principal.\u00a0<\/p>\n\n\n\n<p>Pendant ce temps, il a parl\u00e9 des&nbsp;gars qu&rsquo;il admirait en grandissant.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Bret Hart\u00a0a toujours \u00e9t\u00e9 mon gars.\u00a0J&rsquo;ai appr\u00e9ci\u00e9 ce type de performance athl\u00e9tique et centr\u00e9e sur le sport qu&rsquo;il a mis en place.\u00a0Il \u00e9tait le lutteur professionnel d&rsquo;un lutteur professionnel.\u00a0Son \u00e9thique de travail et le d\u00e9vouement dont il fait preuve sont sans \u00e9gal.\u00a0En vieillissant, vous entendez toutes les histoires et tout le respect qui a brill\u00e9 sur The Undertaker.\u00a0J&rsquo;ai eu un match avec lui, pouvoir le refaire aurait \u00e9t\u00e9 g\u00e9nial.<\/p><p>Le gros de sa carri\u00e8re, quand il \u00e9tait un artiste hebdomadaire \u00e0 temps plein, \u00e7a aurait \u00e9t\u00e9 g\u00e9nial de faire une tourn\u00e9e compl\u00e8te pour pouvoir faire le tour du monde et apprendre de lui et d\u00e9couvrir ce que c&rsquo;est que d&rsquo;\u00eatre sur le ring avec lui nuit apr\u00e8s nuit aurait \u00e9t\u00e9 vraiment bien.\u00a0En ce moment, Ric Flair, \u00e0 ma mani\u00e8re\u2026 nous ne sommes pas le m\u00eame type d&rsquo;interpr\u00e8tes ou de personnages mais il y a une lumi\u00e8re similaire que j&rsquo;essaie de faire briller sur mon h\u00e9ritage et cette partie de ma carri\u00e8re pour laquelle il est connu.\u00a0\u00c9lever tous les talents, \u00eatre coh\u00e9rent et durable pendant des ann\u00e9es et tirer constamment le meilleur de chaque personne sur le ring avec moi.\u00a0Ce sont des traits que j&rsquo;essaie d&rsquo;imiter \u00bb, a-t-il d\u00e9clar\u00e9.<\/p><\/blockquote>\n\n\n\n<p><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Toujours concernant le champion universel de la WWE, Roman Reigns, s&rsquo;est rendu sur Twitter plus t\u00f4t et a r\u00e9agi \u00e0 un jeune fan de John Cena qui a pass\u00e9 une mauvaise soir\u00e9e durant SummerSlam samedi dernier.<\/p>\n\n\n\n<p>Une vid\u00e9o devenue virale montrant un jeune fan v\u00eatu de marchandises de Cena, regardant comment Reigns a vaincu le v\u00e9t\u00e9ran de la WWE Superstar lors de l&rsquo;\u00e9v\u00e9nement principal du pay-per-view SummerSlam de samedi.\u00a0La vid\u00e9o s&rsquo;est termin\u00e9e avec le gar\u00e7on pleurant la d\u00e9faite de son idole.<\/p>\n\n\n\n<p>Reigns a r\u00e9pondu \u00e0 la vid\u00e9o tweet\u00e9e par B\/R Wrestling et a d\u00e9clar\u00e9 qu&rsquo;il \u00e9tait un homme de parole.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab&nbsp;Votre chef de tribu tient ses promesses, gamin.&nbsp;#ManOfMyWord \u00bb, a \u00e9crit Reigns.<\/p><\/blockquote>\n\n\n\n<p>Cena aurait termin\u00e9 avecla WWE pour le moment, mais devrait travailler sur l&rsquo;enregistrement de Super SmackDown le 10 septembre au Madison Square Garden de New York.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/08\/21\/resultats-et-video-du-wwe-summerslam-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour les r\u00e9sultats ou revoir SummerSlam, cliquez ici.<\/strong><\/a><\/li><\/ul>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Your Tribal Chief keeps his promises kid. <a href=\"https:\/\/twitter.com\/hashtag\/ManOfMyWord?src=hash&amp;ref_src=twsrc%5Etfw\">#ManOfMyWord<\/a> <a href=\"https:\/\/t.co\/J2r4RRU67J\">https:\/\/t.co\/J2r4RRU67J<\/a><\/p>&mdash; Roman Reigns (@WWERomanReigns) <a href=\"https:\/\/twitter.com\/WWERomanReigns\/status\/1430219503707860995?ref_src=twsrc%5Etfw\">August 24, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Roman Reigns a fait une interview avec\u00a0ODE\u00a0avant SummerSlam o\u00f9 il a conserv\u00e9 le titre universel de la WWE sur John Cena dans l&rsquo;\u00e9v\u00e9nement principal.\u00a0 Pendant ce temps, il a parl\u00e9 des&nbsp;gars qu&rsquo;il admirait en grandissant. \u00ab\u00a0Bret Hart\u00a0a toujours \u00e9t\u00e9 mon gars.\u00a0J&rsquo;ai appr\u00e9ci\u00e9 ce type de performance athl\u00e9tique et centr\u00e9e sur le sport qu&rsquo;il a mis&#8230;<\/p>\n","protected":false},"author":665,"featured_media":56949,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,53,23],"tags":[],"ppma_author":[289],"class_list":["post-56720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-summerslam","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/56720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=56720"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/56720\/revisions"}],"predecessor-version":[{"id":56951,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/56720\/revisions\/56951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/56949"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=56720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=56720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=56720"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=56720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}