{"id":56317,"date":"2021-08-18T07:16:00","date_gmt":"2021-08-18T07:16:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=56317"},"modified":"2021-08-18T15:26:31","modified_gmt":"2021-08-18T15:26:31","slug":"liberation-de-wyatt-une-mauvaise-gestion-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/08\/18\/liberation-de-wyatt-une-mauvaise-gestion-wwe\/","title":{"rendered":"Lib\u00e9ration de Wyatt Une Mauvaise Gestion WWE!"},"content":{"rendered":"\n<p>Lors du dernier \u00e9pisode de son Podcast Grilling JR, Jim Ross nous a parl\u00e9 de sa crainte d\u2019avoir trop de titres \u00e0 l\u2019AEW mais il a aussi r\u00e9agi au licenciement de Bray Wyatt.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cIl y a de la politique de nos jours \u00e0 cause des immenses salaires. Bray Wyatt a sans doute \u00e9t\u00e9 licenci\u00e9 car il doit gagner plus d&rsquo;un million avec une garantie de maintien et il est rest\u00e9 \u00e0 la maison. Ce n&rsquo;est pas une bonne gestion.<\/p><p>Je ne dis pas que le gars aurait d\u00fb \u00eatre licenci\u00e9, il aurait d\u00fb \u00eatre utilis\u00e9 si vous le payez si cher. Comment cela s&rsquo;est pass\u00e9 est une histoire pour un autre jour parce que je ne connais pas les d\u00e9tails. Je sais qu&rsquo;ils se sont d\u00e9barrass\u00e9s d&rsquo;un gar\u00e7on tr\u00e8s talentueux et je suis s\u00fbr qu&rsquo;il n&rsquo;aura aucun probl\u00e8me \u00e0 trouver du travail, en parlant de Bray Wyatt.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<p>Jr pense que Bray Wyatt a \u00e9t\u00e9 licenci\u00e9 pour des raisons budg\u00e9taires car il fait partie des plus gros salaires et surtout qu\u2019il n\u2019est pas utilis\u00e9, donc pay\u00e9 \u00e0 rien faire. Il ne cautionne aucunement le licenciement mais comprend les raisons et surtout il ne comprend pas comment la WWE peut en arriver l\u00e0, c\u2019est donc la gestion de l\u2019entreprise qui est en cause.<\/p>\n\n\n\n<p>Jim Ross est s\u00fbr que Bray trouvera chaussure \u00e0 son pied dans une autre f\u00e9d\u00e9ration que la WWE car c\u2019est un bon gars et il ne comprend pas comment et pourquoi la WWE l\u2019a mis au placard pendant autant de temps.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>Jim Ross a aussi parl\u00e9 de l\u2019arriv\u00e9e future d\u2019un titre Trios et il nous a parl\u00e9 de sa crainte d\u2019avoir trop de ceintures pour une f\u00e9d\u00e9ration.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cL&rsquo;AEW n&rsquo;a pas de titre junior, je ne le pr\u00e9conise pas non plus. Trop de titres g\u00e2chent vraiment la soupe pour moi, on n&rsquo;en a pas besoin d&rsquo;autant. J&rsquo;ai entendu quelqu&rsquo;un dire l&rsquo;autre jour qu&rsquo;il esp\u00e9rait que l&rsquo;AEW ait un titre de champion \u00e0 six et je ne serais pas contre, mais ce ne serait pas quelque chose pour lequel je pourrais sauter au plafond.<\/p><p>Il est difficile de maintenir une concentration positive sur plusieurs titres. Lequel est le plus important ? Je pense que la tendance actuelle pour beaucoup c&rsquo;est de se dire qu&rsquo;il suffit d&rsquo;ajouter des titres, cela r\u00e9soudra nos probl\u00e8mes.<\/p><p>Non, ce n&rsquo;est pas le cas et si vous en avez trop, ils se diluent. Je suis tr\u00e8s fier du fait qu&rsquo;\u00e0 AEW nous avons trois titres principaux. Un pour les femmes et deux titres en simple pour les hommes. Je pense que c&rsquo;est \u00e0 peu pr\u00e8s correct, si vous \u00eates une comp\u00e9titrice, vous savez quel est votre objectif. Le titre TNT que Miro d\u00e9tient est certainement un titre qui rappelle un titre TV \u00e0 mon avis. Je ne le minimise pas, c&rsquo;est juste ce qu&rsquo;il me rappelle. Bien s\u00fbr, le grand titre est celui que d\u00e9tient Kenny Omega, je pense que nous le faisons bien. Ajouter des titres juste pour rendre les talents heureux, c&rsquo;est vraiment n&rsquo;importe quoi. \u00ab\u00a0<\/p><\/blockquote>\n\n\n\n<p>Jim Ross n\u2019est pas favorable \u00e0 l&rsquo;arriv\u00e9e d\u2019un titre Junior Heavyweight ou Cruiserweight et il n\u2019est pas non plus tr\u00e8s chaud \u00e0 l&rsquo;id\u00e9e d\u2019avoir un Trios Tag Title a l\u2019AEW. Sa raison est simple, trop de titres tue les titres. C\u2019est un avis mais avoir d\u2019autres titres comme le trios serait tr\u00e8s int\u00e9ressant pour l\u2019AEW car ils ont \u00e9norm\u00e9ment d&rsquo;\u00e9quipes compos\u00e9es de trois catcheurs qui pourraient briller encore plus dans cette division et avec la multiplication des shows, la visibilit\u00e9 sera pr\u00e9sente mais \u00e0 condition que la f\u00e9d\u00e9ration fasse le n\u00e9cessaire pour mettre en valeur le titre.&nbsp;<\/p>\n\n\n\n<p>Avoir beaucoup de titres c\u2019est bien mais en prendre soin et les mettre en valeur c\u2019est encore mieux.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Lors du dernier \u00e9pisode de son Podcast Grilling JR, Jim Ross nous a parl\u00e9 de sa crainte d\u2019avoir trop de titres \u00e0 l\u2019AEW mais il a aussi r\u00e9agi au licenciement de Bray Wyatt. \u201cIl y a de la politique de nos jours \u00e0 cause des immenses salaires. Bray Wyatt a sans doute \u00e9t\u00e9 licenci\u00e9 car&#8230;<\/p>\n","protected":false},"author":4,"featured_media":56318,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,30,4,23],"tags":[],"ppma_author":[292],"class_list":["post-56317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-ex-wwe","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/56317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=56317"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/56317\/revisions"}],"predecessor-version":[{"id":56319,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/56317\/revisions\/56319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/56318"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=56317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=56317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=56317"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=56317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}