{"id":55929,"date":"2021-08-11T21:19:56","date_gmt":"2021-08-11T21:19:56","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=55929"},"modified":"2021-08-11T22:05:07","modified_gmt":"2021-08-11T22:05:07","slug":"deuxieme-heure-de-dynamite-2","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/08\/11\/deuxieme-heure-de-dynamite-2\/","title":{"rendered":"Deuxi\u00e8me Heure de Dynamite!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/08\/11\/resultats-du-aew-dynamite-11-aout-2021\/\">Pour revenir \u00e0 la premi\u00e8re heure de Dynamite, cliquez ici.<\/a><\/li><\/ul>\n\n\n\n<p>&#8211; En coulisse, Dasha est avec Andrade El Idolo pour avoir sa r\u00e9ponse \u00e0 Pac. Andrade dit qu&rsquo;il n&rsquo;est pas reconnaissant. Chavo Guerrero dit qu&rsquo;Andrade lui montrait du respect avec la premi\u00e8re classe, la limousine, le champagne et Pac le remercie ainsi. Andrade dit que Pac doit faire attention \u00e0 ce qu&rsquo;il souhaite. Chavo dit qu&rsquo;Andrade devrait montrer \u00e0 Pac qui est le patron.\u00a0Chavo dit que Pac va le d\u00e9couvrir \u00e0 All Out.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, on retrouve Santana et Ortiz. Ils expliquent qu&rsquo;ils ont encore faim, si FTR veut un rematch ils sont pr\u00eats. Ils ont eu un petit probl\u00e8me et FTR a d\u00e9cid\u00e9 de partir. Eux ils sont ici pour le sang.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Nyla Rose\u00a0acc  de Vickie Guerrero\u00a0vs Kris Statlander\u00a0acc  de Best Friends<\/strong><\/p>\n\n\n\n<p>En fin de match, Statlander fait son 450 Splash sur Rose pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Kris Statlander<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve les Young Bucks. Matt Jackson dit que les m\u00e9chants directeurs se sont d\u00e9barrass\u00e9s d&rsquo;Adam Page. Ils ont montr\u00e9 au monde pourquoi ils sont vraiment The Elite. Ils ont montr\u00e9 \u00e0 tout le monde qu&rsquo;ils sont les meilleurs. Nick Jackson dit que la semaine prochaine sera aussi facile qu&rsquo;un tir au panier. Nick se lance au basket, mais Luchasaurus bloque le ballon et Jungle Boy marque.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o promo sur le match entre Britt Baker et Red Velvet pour le titre f\u00e9minin qui aura lieu \u00e0 Rampage ce vendredi. Tony Schiavone est sur le ring et nous pr\u00e9sente la\u00a0<strong>championne Britt Baker<\/strong>\u00a0qui arrive sur le ring sous une grande ovation comme ce soir on est dans sa ville.<\/p>\n\n\n\n<p> Schiavone lui demande ses commentaires pour vendredi. Baker dit qu&rsquo;elle ne peut pas commenter sur l&rsquo;ascension de Velvet, se serait injuste. Elle ne peut pas s&rsquo;identifier, car elle a toujours \u00e9t\u00e9 au top de la division. Mais elle peut comprendre Velvet qui n&rsquo;a peur de rien. Elle aussi n&rsquo;avait pas peur de prendre la place lorsque l&rsquo;AEW avait besoin d&rsquo;une nouvelle championne et lorsque Pittsburg avait besoin d&rsquo;un champion. Baker dit que ce fut une ann\u00e9e difficile pour tout le monde, alors le titre est l&rsquo;espoir pour Pittsburg.\u00a0 Red Velvet n&rsquo;aura aucune chance en l&rsquo;affrontant dans Brittsburg. \u00c0 Rampage elles seront dans le main event pour le premier show. Elle sera toujours notre championne AEW, docteur Britt Baker ! Baker pose sur le ring, mais Red Velvet arrive pour la rouer de coups. Les arbitres arrivent pour s\u00e9parer les deux.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur l&rsquo;histoire entre Ricky Starks et Brian Cage. Starks dit que Cage pourra le retrouver la semaine prochaine \u00e0 Dynamite. Il sera sur le ring seul \u00e0 seul pour le confronter.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat par \u00c9quipe Impact Wrestling<\/strong><\/p>\n\n\n\n<p><strong>Evil Uno et Stu Grayson vs Doc Gallows et Karl Anderson (c)<\/strong><\/p>\n\n\n\n<p>En fin de match, l&rsquo;arbitre est distrait par un titre sur le ring. Gallows en profite pour prendre l&rsquo;avantage et sortir Uno du ring. Gallows et Anderson font leur Magic Killer sur Grayson pour le compte trois.<\/p>\n\n\n\n<p><em>Gagnants : Goc Gallows et Karl Anderson<\/em><\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la championne Kamille. Kamille dit que Leyla ne sera pas capable de la lever, le monde entier va la voir l&rsquo;\u00e9craser.<\/p>\n\n\n\n<p>&#8211; Tony Schiavone est sur le ring avec QT Marshall pour avoir ses excuses. Schiavone dit que \u00e7a fait trois semaines, il est pr\u00eat. Marshall dit que Schiavone devrait s&rsquo;excuser pour les critiques, mais il sait que Schiavone ne le fera jamais. Alors il va s&rsquo;excuser, pas pour lui avoir vers\u00e9 sur la t\u00eate son drink, mais bien ce qu&rsquo;ils vont faire \u00e0 son fils Chris Schiavone. Nick Comoroto va chercher le fils de Schiavone en ringside et Marshall le frappe ! Marshall lui demande des excuses. Schiavone dit qu&rsquo;il s&rsquo;excuse \u00e0 ce fils de p*te. Marshall dit que ce n&rsquo;est pas accept\u00e9. Marshall fait son Diamond Cutter sur le fils. Paul Wight arrive sur le ring ! Marshall lance Aaron Solo vers Paul Wight et quitte le ring.&nbsp;<strong>Paul Wight fait son ChokeSlam sur Solo<\/strong>&nbsp;!<\/p>\n\n\n\n<p>&#8211; Les commentateurs pr\u00e9sentent la carte de Rampage qui aura lieu ce vendredi avec les matchs annonc\u00e9s ce soir. Pour la semaine prochaine \u00e0 Dynamite : Young Bucks vs Jurassic Express pour les titres par \u00e9quipe, Shawn Spears vs Sammy Guevara et Guevara aura une annonce, et Darby Allin et Sting vs 2.0 dans un Tornado.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>4e \u00c9preuve pour Christ Jericho<\/strong><\/p>\n\n\n\n<p><strong>Chris Jericho vs Wardlow\u00a0acc  de MJF<\/strong><\/p>\n\n\n\n<p>Wardlow domine le match avec une s\u00e9rie de prises et de Powerbomb. \u00c0 la fin du combat, Wardlow fait son F10 sur Jericho et le monte sur le coin pour son coup de genou, mais Jericho le bloque et lui applique un Walls of Jericho ! MJF en profite pour mettre ses doigts dans les yeux de Jericho pendant que l&rsquo;arbitre est de dos. MJF veut donner sa bague, mais l&rsquo;arbitre le voit et l&rsquo;expulse. Jericho en profite pour prendre son b\u00e2ton de baseball et il frappe Wardlow en plein visage. Jericho enchaine avec son Judas Effect pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Chris Jericho<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Shawn Spears arrive pour attaquer Jericho dans le dos. Sammy Guevara arrive sur le ring pour aider Jericho, mais Wardlow le repousse avec un Spinebuster. MJF d\u00e9cide d&rsquo;appliquer un Arm Bar sur le bras faible de Jericho, mais Jake Hager arrive et il prend la fuite. MJF prend le micro et dit que Jericho a peut-\u00eatre atteint\u00a0l&rsquo;\u00e9preuve 5 et son rematch contre lui, mais il ne sait pas la stipulation. La semaine prochaine il va lui prendre quelque chose qu&rsquo;il aime. La semaine prochaine nous n&rsquo;aurons pas de Judas Effect. Jericho devra venir sous le silence, les fans ne pourront pas chanter. Et si Jericho le frappe avec son Judas Effect il va gagner automatiquement. La semaine prochaine Jericho va d\u00e9couvrir qu&rsquo;il a rencontr\u00e9 son successeur. Le nouveau roi en ville est MJF.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/08\/11\/regardez-le-aew-dynamite-du-11-aout-2021\/\"><strong>Pour voir ce AEW Dynamite, cliquez ici<\/strong><\/a><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re heure de Dynamite, cliquez ici. &#8211; En coulisse, Dasha est avec Andrade El Idolo pour avoir sa r\u00e9ponse \u00e0 Pac. Andrade dit qu&rsquo;il n&rsquo;est pas reconnaissant. Chavo Guerrero dit qu&rsquo;Andrade lui montrait du respect avec la premi\u00e8re classe, la limousine, le champagne et Pac le remercie ainsi. Andrade dit que&#8230;<\/p>\n","protected":false},"author":4,"featured_media":55930,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"ppma_author":[292],"class_list":["post-55929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dynamite"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=55929"}],"version-history":[{"count":10,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55929\/revisions"}],"predecessor-version":[{"id":55951,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55929\/revisions\/55951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/55930"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=55929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=55929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=55929"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=55929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}