{"id":55892,"date":"2021-08-11T16:28:28","date_gmt":"2021-08-11T16:28:28","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=55892"},"modified":"2021-08-11T16:28:31","modified_gmt":"2021-08-11T16:28:31","slug":"cm-punk-en-grande-forme","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/08\/11\/cm-punk-en-grande-forme\/","title":{"rendered":"CM Punk en Grande Forme!"},"content":{"rendered":"\n<p>Vous le savez, \u00e0 moins de changement majeur, le retour de CM Punk n\u2019est plus qu\u2019une question de jour, avec tous les indices et toutes les r\u00e9f\u00e9rences \u00e0 son sujet. Punk devrait d\u00e9buter lors du show Rampage de l\u2019AEW qui aura lieu \u00e0 l&rsquo;United Center de Chicago le 20 ao\u00fbt prochain.<\/p>\n\n\n\n<p>Aujourd&rsquo;hui nous avons obtenu des informations sur la condition physique de CM Punk en vue de ce retour. Notre source nous dit que CM Punk s&rsquo;entra\u00eene tout seul depuis assez longtemps, il a aussi entretenu son physique en vue de son r\u00f4le pour la s\u00e9rie Heels, donc CM Punk est dans une assez bonne condition physique depuis un certain moment. <\/p>\n\n\n\n<p>Il y a eut des discutions avec des membres de l&rsquo;\u00e9quipe, acteurs de la s\u00e9rie et a des catcheurs qui ont pu travailler avec CM Punk ces 6 derniers mois durant le tournage. Ils nous disent qu\u2019ils sont tr\u00e8s optimistes par rapport \u00e0 son \u00e9tat de forme et ils le d\u00e9crivent comme \u201cen grande forme physique et en tr\u00e8s bonne sant\u00e9\u201d.<\/p>\n\n\n\n<p>Une autre source nous dit qu\u2019elle a trouv\u00e9 que Punk avait un excellent niveau dans le ring, ce qui les a amen\u00e9s \u00e0 se demander s\u2019il s&rsquo;\u00e9tait entra\u00een\u00e9 en priv\u00e9 avant de revenir sur le ring pour la s\u00e9rie. Et enfin une derni\u00e8re source nous dit que Punk \u00e9tait tellement bon qu\u2019il avait l\u2019impression qu\u2019il n\u2019avait jamais arr\u00eat\u00e9.<\/p>\n\n\n\n<p>De plus, les sources  semblent \u00eatre tr\u00e8s impressionn\u00e9es et dithyrambiques \u00e0 propos de l&rsquo;\u00e9tat de forme de CM Punk en vue de son retour le 20 ao\u00fbt prochain, dans sa ville, Chicago. Le monde du catch est en \u00e9bullition et nous avons h\u00e2te de voir CM Punk de retour et de conna\u00eetre son premier adversaire sur les rings.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Vous le savez, \u00e0 moins de changement majeur, le retour de CM Punk n\u2019est plus qu\u2019une question de jour, avec tous les indices et toutes les r\u00e9f\u00e9rences \u00e0 son sujet. Punk devrait d\u00e9buter lors du show Rampage de l\u2019AEW qui aura lieu \u00e0 l&rsquo;United Center de Chicago le 20 ao\u00fbt prochain. Aujourd&rsquo;hui nous avons obtenu&#8230;<\/p>\n","protected":false},"author":4,"featured_media":55893,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,30,4],"tags":[],"ppma_author":[292],"class_list":["post-55892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-ex-wwe","category-news"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=55892"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55892\/revisions"}],"predecessor-version":[{"id":55894,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55892\/revisions\/55894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/55893"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=55892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=55892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=55892"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=55892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}