{"id":55461,"date":"2021-08-02T16:24:00","date_gmt":"2021-08-02T16:24:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=55461"},"modified":"2021-08-02T20:29:20","modified_gmt":"2021-08-02T20:29:20","slug":"mise-a-jour-des-coulisses-sur-la-sortie-de-ric-flair-a-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/08\/02\/mise-a-jour-des-coulisses-sur-la-sortie-de-ric-flair-a-la-wwe\/","title":{"rendered":"Mise \u00e0 jour des coulisses sur la sortie de Ric Flair \u00e0 la WWE! Qui a Contact\u00e9 Qui? Et Plus!"},"content":{"rendered":"\n<p>Du nouveau dans l&rsquo;histoire du Nature Boy qui a quitt\u00e9 la WWE. C&rsquo;est Ric Flair lui m\u00eame qui aurait contact\u00e9 le PDG de la WWE, Vince McMahon pour demander sa lib\u00e9ration.<\/p>\n\n\n\n<p>Comme indiqu\u00e9 pr\u00e9c\u00e9demment&nbsp;, le 16 fois champions du monde n&rsquo;est plus avec la soci\u00e9t\u00e9 apr\u00e8s avoir demand\u00e9 sa lib\u00e9ration et obtenu son  d\u00e9part, \u00e0 compter d&rsquo;aujourd&rsquo;hui.<\/p>\n\n\n\n<p>Dans une mise \u00e0 jour, nous apprenons  que Flair serait devenu frustr\u00e9 par certaines d\u00e9cisions du booking t\u00e9l\u00e9 la WWE  et a contact\u00e9 directement McMahon pour exprimer ses probl\u00e8mes.&nbsp;Flair a \u00e9galement demand\u00e9 \u00e0 Vince sa lib\u00e9ration de contrat.<\/p>\n\n\n\n<p>Flair \u00e9tait impliqu\u00e9 dans une histoire de relation avec Lacey Evans sur RAW plus t\u00f4t cette ann\u00e9e, mais cela a \u00e9t\u00e9 annul\u00e9 lorsque Evans a r\u00e9v\u00e9l\u00e9 sa grossesse l\u00e9gitime.&nbsp;Flair est parti depuis, mais le mot est que les probl\u00e8mes de booking et d&rsquo;utilisation qu&rsquo;il n&rsquo;aimait pas \u00e9taient assez r\u00e9cents.<\/p>\n\n\n\n<p>The Nature Boy a exprim\u00e9 son m\u00e9pris pour l&rsquo;histoire d&rsquo;Evans.&nbsp;Il a&nbsp;parl\u00e9 avec Ariel Helwani&nbsp;en mai et a admis qu&rsquo;il n&rsquo;\u00e9tait pas \u00e0 l&rsquo;aise avec le sc\u00e9nario, mais a finalement d\u00e9clar\u00e9 qu&rsquo;il avait fait ce qu&rsquo;on lui avait dit parce que Vince avait \u00e9t\u00e9 convaincu que cela ferait entrer Evans dans le programme avec Charlotte Flair.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Dans ce cas, je ne me sentais pas \u00e0 l&rsquo;aise\u00a0\u00bb, a admis Flair.&nbsp; La seule chose que j&rsquo;ai apprise, c&rsquo;est que vous n&rsquo;allez pas gagner une guerre quand quelqu&rsquo;un a pris sa d\u00e9cision.&nbsp;Elle n&rsquo;a certainement pas aim\u00e9 \u00e7a, mais la seule chose que je peux dire sur moi, c&rsquo;est que j&rsquo;ai toujours dit oui.&nbsp;Je ne voulais pas \u00eatre ce gars qui disait toujours . &lsquo;Oh, ce n&rsquo;est pas parfait pour moi.&rsquo;<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abQuand tout \u00e9tait fini, j&rsquo;\u00e9tais en col\u00e8re, mais maintenant je regarde en arri\u00e8re et je dis que ce n&rsquo;\u00e9tait pas \u00e7a.&nbsp;C&rsquo;\u00e9tait quelque chose avec lequel quand je suis arriv\u00e9 \u00e0 la t\u00e9l\u00e9vision, M. McMahon n&rsquo;\u00e9tait pas l\u00e0 pour discuter et il avait des choses en cours, je n&rsquo;aime pas mettre la pression sur quelqu&rsquo;un si je ne peux pas lui parler.&nbsp;Il vient de se d\u00e9cider, je pense que c&rsquo;\u00e9tait en grande partie parce que [Lacey] \u00e9tait un marine.&nbsp;Dieu seul sait que nous ne pouvons pas donner assez en retour aux gens qui servent dans l&rsquo;arm\u00e9e et je pense qu&rsquo;il voulait qu&rsquo;elle r\u00e9ussisse et le moyen de r\u00e9ussir parfois est de prendre deux personnes qui se d\u00e9brouillent tr\u00e8s bien et de leur donner le b\u00e2t blesse.<\/p><\/blockquote>\n\n\n\n<p>Dans cette m\u00eame interview, Flair a souhait\u00e9 le meilleur \u00e0 Evans et a not\u00e9 comment Vince le voit toujours comme il le faisait dans les ann\u00e9es 1980 et 1990.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0C&rsquo;est une fille vraiment sympa et tout \u00e7a, mais \u00e7a ne convenait pas cette fois\u00a0\u00bb, a d\u00e9clar\u00e9 Flair.&nbsp;\u00ab Nous en avons tir\u00e9 le meilleur parti, mais finalement, elle est enceinte de son mari maintenant.&nbsp;Ce n&rsquo;\u00e9tait jamais rien de personnel, je la connais \u00e0 peine et toute sa vie c&rsquo;est son mari et sa fille.&nbsp;Je n&rsquo;aimais pas celui-l\u00e0, pour lui, je serai toujours le \u00ab\u00a0vol de baisers, le deal de wheelin\u00a0\u00bb, tu ne comprends pas ce que je veux dire?&nbsp;Ce qui est g\u00e9nial parce qu&rsquo;il aime \u00e7a.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab M\u00eame s&rsquo;il d\u00e9testait \u00e7a quand je le disais, il disait que les talons des ann\u00e9es 80 ne dessinent pas !&nbsp;Je suis sur le dark match [une nuit et je me suis plaint et il a dit:  &lsquo;Je m&rsquo;en fiche, vous montrez l&rsquo;exemple ici, ces gens vous admirent.&rsquo;&nbsp;Vous n&rsquo;allez pas gagner l&rsquo;argument parce qu&rsquo;il est plus intelligent et qu&rsquo;il est le patron.&nbsp;Il est peut-\u00eatre le gars le plus intelligent que j&rsquo;aie jamais rencontr\u00e9.&nbsp;Il n&rsquo;arr\u00eate jamais d&rsquo;\u00eatre le meilleur.<\/p><\/blockquote>\n\n\n\n<p>Flair a sign\u00e9 un nouveau contrat avec la WWE en 2020 apr\u00e8s l&rsquo;expiration de son pr\u00e9c\u00e9dent contrat fin 2019. La WWE n&rsquo;a pas comment\u00e9 le d\u00e9part au moment d&rsquo;\u00e9crire ces lignes.<\/p>\n\n\n\n<p>Restez \u00e0 l&rsquo;\u00e9coute pour les mises \u00e0 jour.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Du nouveau dans l&rsquo;histoire du Nature Boy qui a quitt\u00e9 la WWE. C&rsquo;est Ric Flair lui m\u00eame qui aurait contact\u00e9 le PDG de la WWE, Vince McMahon pour demander sa lib\u00e9ration. Comme indiqu\u00e9 pr\u00e9c\u00e9demment&nbsp;, le 16 fois champions du monde n&rsquo;est plus avec la soci\u00e9t\u00e9 apr\u00e8s avoir demand\u00e9 sa lib\u00e9ration et obtenu son d\u00e9part, \u00e0&#8230;<\/p>\n","protected":false},"author":665,"featured_media":55468,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,23],"tags":[],"ppma_author":[289],"class_list":["post-55461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=55461"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55461\/revisions"}],"predecessor-version":[{"id":55471,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55461\/revisions\/55471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/55468"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=55461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=55461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=55461"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=55461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}