{"id":55435,"date":"2021-08-02T08:11:00","date_gmt":"2021-08-02T08:11:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=55435"},"modified":"2021-08-02T12:26:52","modified_gmt":"2021-08-02T12:26:52","slug":"aleister-black-fait-un-sauvetage-surprenant-un-lutteur-aew-comme-trophe-de-chasse-dun-gars-dimpact-priest-veut-toujours-la-ceinture-de-nxt-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/08\/02\/aleister-black-fait-un-sauvetage-surprenant-un-lutteur-aew-comme-trophe-de-chasse-dun-gars-dimpact-priest-veut-toujours-la-ceinture-de-nxt-et-plus\/","title":{"rendered":"Aleister Black Fait un Sauvetage Surprenant! Un Lutteur AEW Comme Troph\u00e9 de Chasse d&rsquo;un Gars d&rsquo;Impact! Priest Veut Toujours la Ceinture de NXT, et Plus!"},"content":{"rendered":"\n<p>Dimanche soir \u00e0 la PWG qui tenait son son premier show en un an et demi suite \u00e0 la pand\u00e9mie, avec une carte gard\u00e9e secr\u00e8te pour les fans pr\u00e9sents. <\/p>\n\n\n\n<p>Si le r\u00eave \u00e9tait de voir Daniel Bryan faire son retour au sein de la promotion californienne, les spectateurs pr\u00e9sents ont pu assister sur \u00e0 un gros d\u00e9but .Apr\u00e8s le Main Event, Demonic Flamita et Black Taurus sont venus attaquer le champion Bandido. Le v\u00e9t\u00e9ran Super Dragon a fait son retour pour lui aussi s&rsquo;en prendre au champion. Brody King. Sont alors apparu Malakai Black est alors apparus pour faire le sauvetage.<\/p>\n\n\n\n<p>Celui que vous connaissez sous le nom d&rsquo;Aleister Black de la WWE a ensuite pris le micro pour dire qu&rsquo;il serait pr\u00e9sent au prochain du 26 septembre et a challeng\u00e9 King qui a accept\u00e9 le d\u00e9fi.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Lights out again, <a href=\"https:\/\/twitter.com\/TommyEnd?ref_src=twsrc%5Etfw\">@TommyEnd<\/a> is back in <a href=\"https:\/\/twitter.com\/hashtag\/PWG?src=hash&amp;ref_src=twsrc%5Etfw\">#PWG<\/a>. Saves <a href=\"https:\/\/twitter.com\/bandidowrestler?ref_src=twsrc%5Etfw\">@bandidowrestler<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/MysteryVortex7?src=hash&amp;ref_src=twsrc%5Etfw\">#MysteryVortex7<\/a> <a href=\"https:\/\/t.co\/IYW0CPjOrC\">pic.twitter.com\/IYW0CPjOrC<\/a><\/p>\u2014 SoCal UNCENSORED (@socaluncensored) <a href=\"https:\/\/twitter.com\/socaluncensored\/status\/1422054610399756292?ref_src=twsrc%5Etfw\">August 2, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Pilier de la division par \u00e9quipe d&rsquo;Impact Wrestling en 2020, Josh Alexander a d\u00fb se r\u00e9inventer en lutteur au solo au d\u00e9part de son co\u00e9quipier Ethan Page. Le canadien a d&rsquo;ailleurs r\u00e9ussi cette transition avec succ\u00e8s, remportant en avril dernier et surtout en ayant plusieurs gros matchs pour cette ceinture.<\/p>\n\n\n\n<p>Depuis, Alexander a victorieusement d\u00e9fendu \u00e0 7 reprises son titre et notamment contre des repr\u00e9sentants d&rsquo;autres compagnies. Il a ainsi battu El Phantasmo de la NJPW au mois de mai et Black Taurus de la AAA lors du weekend dernier. Et cela lui a donn\u00e9 une id\u00e9e.<\/p>\n\n\n\n<p>Apr\u00e8s avoir vaincu des repr\u00e9sentants de la NJPW et AAA, Alexander voudrait accrocher un nouvel accomplissement \u00e0 son tableau de chasse avec une victoire sur un lutteur de la AEW.<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">EXCLUSIVE: <a href=\"https:\/\/twitter.com\/Walking_Weapon?ref_src=twsrc%5Etfw\">@Walking_Weapon<\/a> has beaten the best from <a href=\"https:\/\/twitter.com\/luchalibreaaa?ref_src=twsrc%5Etfw\">@luchalibreaaa<\/a>, <a href=\"https:\/\/twitter.com\/njpwglobal?ref_src=twsrc%5Etfw\">@njpwglobal<\/a> and IMPACT &#8211; now he&rsquo;s looking for the best from elsewhere. <a href=\"https:\/\/twitter.com\/hashtag\/Homecoming?src=hash&amp;ref_src=twsrc%5Etfw\">#Homecoming<\/a> <a href=\"https:\/\/t.co\/JpisyeESUm\">pic.twitter.com\/JpisyeESUm<\/a><\/p>\u2014 IMPACT (@IMPACTWRESTLING) <a href=\"https:\/\/twitter.com\/IMPACTWRESTLING\/status\/1421953891223015427?ref_src=twsrc%5Etfw\">August 1, 2021<\/a><\/blockquote> <script async=\"\" src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>DAMIAN PRIEST R\u00caVE ENCORE D\u2019\u00caTRE CHAMPION DE NXT<\/strong><\/p>\n\n\n\n<p>Malgr\u00e9 son transfert \u00e0 RAW, Damian Priest souhaite encore devenir champion de NXT.<\/p>\n\n\n\n<p>C\u2019est lors d\u2019une entrevue pour le Battleground Podcast que Priest a fait cette affirmation. Il croit que c\u2019est encore possible et il y a bien des lutteurs \u00e0 NXT qu\u2019il aimerait affronter. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0Je veux dire, il y a beaucoup de gars avec qui j&rsquo;aurais aim\u00e9 avoir l&rsquo;opportunit\u00e9 de travailler.\u00a0\u00bb<\/p><p>\u00ab&nbsp;\u00c9videmment, cela ne veut pas dire que nous n&rsquo;allions jamais travailler parce que c&rsquo;est toujours la WWE, n&rsquo;est-ce pas&nbsp;? Que \u00e7a se passe ici ou que j&rsquo;y retourne ou quoi que ce soit. Mais oui, il y a d\u00e9finitivement plus de moments, il y a d\u00e9finitivement des championnats. Je voulais \u00eatre le champion NXT. \u00ab\u00a0<\/p><\/blockquote>\n\n\n\n<p>Priest fait remarquer que Finn Balor est retourn\u00e9 \u00e0 NXT apr\u00e8s avoir fait partie de la division RAW. Il soutient avoir v\u00e9cu de belles exp\u00e9riences \u00e0 NXT, notamment en tant que champion nord-am\u00e9ricain.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abJe dois avoir de bonnes exp\u00e9riences, je dois devenir champion nord-am\u00e9ricain. J&rsquo;ai eu de grands matchs avec beaucoup de talent incroyable. Donc, \u00e0 la fin de la journ\u00e9e, c&rsquo;\u00e9tait toujours une course NXT r\u00e9ussie et positive. \u00bb<\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dimanche soir \u00e0 la PWG qui tenait son son premier show en un an et demi suite \u00e0 la pand\u00e9mie, avec une carte gard\u00e9e secr\u00e8te pour les fans pr\u00e9sents. Si le r\u00eave \u00e9tait de voir Daniel Bryan faire son retour au sein de la promotion californienne, les spectateurs pr\u00e9sents ont pu assister sur \u00e0 un&#8230;<\/p>\n","protected":false},"author":609,"featured_media":55436,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,30,22,4,41],"tags":[],"ppma_author":[295],"class_list":["post-55435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-ex-wwe","category-indy","category-news","category-tna-impact"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=55435"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55435\/revisions"}],"predecessor-version":[{"id":55438,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/55435\/revisions\/55438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/55436"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=55435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=55435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=55435"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=55435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}