{"id":54936,"date":"2021-07-22T23:45:00","date_gmt":"2021-07-22T23:45:00","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=54936"},"modified":"2021-07-25T12:55:12","modified_gmt":"2021-07-25T12:55:12","slug":"resultats-et-video-impact-wrestling-du-22-juillet-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/07\/22\/resultats-et-video-impact-wrestling-du-22-juillet-2021\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o: Impact Wrestling du 22 Juillet 2021!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/07\/22\/voir-impact-wrestling-en-direct-des-20h-est-2h-europe-programme-de-ce-soir-et-plus\/\" target=\"_blank\">Pour voir cet Impact, cliquez ici<\/a><\/strong><\/li><\/ul>\n\n\n\n<p><strong>&#8211; Chris Bey def. Rohit Raju (w. Shera)<\/strong><\/p>\n\n\n\n<p>Raju a port\u00e9 un Jumping Back Elbow suivi d&rsquo;une Diving Clothesline mais n&rsquo;a obtenu qu&rsquo;un compte de deux. L&rsquo;indien continue sur sa lanc\u00e9e avec un Crossface quand Bey finit par avancer la tendance. Si Raju \u00e9vite le Burning Hammer il se prend cependant ensuite un Cutter pour le compte de trois.<\/p>\n\n\n\n<p>A son retour en coulisse, Jay White vient se pr\u00e9senter \u00e0 Chris Bey et lui demande s&rsquo;il a re\u00e7u son message. Le vainqueur de l&rsquo;opener r\u00e9pond que oui mais qu&rsquo;il ne sait pas exactement ce que le n\u00e9oz\u00e9landais lui veut. White indique alors que le Bullet Club est toujours \u00e0 la recherche de nouvelles recrues et que Bey semble avoir le bon profil. Ce dernier refuse cependant en disant qu&rsquo;il travaille seul. White lui demande alors si cette technique paie. Bey ne sait quoi r\u00e9pondre et White part en disant que son offre est toujours valide.<\/p>\n\n\n\n<p>Gia Miller veut interviewer Kenny Omega et lui demander de s&rsquo;exprimer sur sa victoire de Slammiversary sur Sami Callihan. C&rsquo;est cependant Don Callis qui va r\u00e9pondre. Le v\u00e9t\u00e9ran indique tout d&rsquo;abord qu&rsquo;Omega souffre de blessures importantes suite \u00e0 son match brutal de samedi. Miller le lance maintenant sur Jay White et Callis dit qu&rsquo;il n&rsquo;\u00e9tait pas au courant qu&rsquo;il venait \u00e0 Impact Wrestling. Encore une chose en plus avec laquelle il n&rsquo;est pas d&rsquo;accord avec le management d&rsquo;Impact Wrestling. Calllis conclut en disant que cela soit White ou un autre, ils doivent passer par lui s&rsquo;ils veulent une chance au titre.<\/p>\n\n\n\n<p>Mickie James arrive sur le ring sous les chants \u00ab\u00a0Welcome Back\u00a0\u00bb du public. La revenante leur dit merci et ajoute que samedi soir, les choses ne se sont pas pass\u00e9es comme elle l&rsquo;esp\u00e9rait. Elle est donc l\u00e0 ce soir pour faire les choses biens et elle demande \u00e0 Deonna Purrazzo de venir la rejoindre. La championne arrive et s&rsquo;excuse de lui avoir port\u00e9 un Superkick. James ajoute qu&rsquo;elle veut les meilleures pour le show NWA Empower du mois d&rsquo;aout et qu&rsquo;elle croit que Purrazzo est au sommet du business. Elle lui propose donc d&rsquo;en \u00eatre. La championne indique cependant que la seule raison qui l&rsquo;a pouss\u00e9 \u00e0 venir sur ce ring est pour que James rectifie ses actions, elle n&rsquo;a pas besoin que des personnes comme elles disent qu&rsquo;elle est la meilleure, \u00e7a elle le sait d\u00e9j\u00e0. Purrazzo demande donc des excuses publiques. Sinon, elle va gifler James la semaine prochaine. Avant que cette derni\u00e8re ne puisse r\u00e9pondre, la musique de Gail Kim se d\u00e9clenche. L&rsquo;officielle indique que c&rsquo;est elle qui a invit\u00e9 James \u00e0 Slammiversary et qui l&rsquo;a pouss\u00e9 \u00e0 inviter Purrazzo pour Empower. Kim veut savoir si cette opportunit\u00e9 l&rsquo;int\u00e9resse. James ajoute que si Purrazzo veut ajouter une brique de plus \u00e0 sa l\u00e9gende, elle doit venir \u00e0 Empower. Purrazzo finit par accepter.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Vignette sur un lutteur qui se fait appeler Drama King (aka Aiden English).<\/p>\n\n\n\n<p><strong>&#8211; Matt Cardona, Chelsea Green et Jake Something def. Brian Myers, Sam Beale et Tenille Dashwood (w. Kaleb)<\/strong><\/p>\n\n\n\n<p>Apr\u00e8s que les hommes se soient \u00e9loign\u00e9s du ring, Green veut porter son Unprettier sur Dashwood mais s&rsquo;arr\u00eate en voyant Kaleb monter sur l&rsquo;apron. Taylor Wilde fait alors son retour pour venir le d\u00e9gager de l&rsquo;apron. Dashwood frappe cependant par derri\u00e8re Green avant de faire le tag \u00e0 Beale. Ce dernier soul\u00e8ve Green mais celle-ci se d\u00e9gage et envoie Beale contre Dashwood. Green porte ensuite son Unprettier sur Beale pour la victoire.<\/p>\n\n\n\n<p>Promo d&rsquo;Eddie Edwards qui invite W. Morrisey \u00e0 venir se battre contre lui dans le parking.<\/p>\n\n\n\n<p><strong>&#8211; Parking Lot Brawl: Eddie Edwards def. W. Morrisey<\/strong><\/p>\n\n\n\n<p>Edwards a fini par sortir deux Kendo Sticks et s&rsquo;est mis \u00e0 frapper Morrisey avec. Le g\u00e9ant a pr\u00e9f\u00e9r\u00e9 quitter ce match non-officiel et est parti.<\/p>\n\n\n\n<p>Gia Miller est avec le groupe form\u00e9 par Curt Hawkins et Tenille Dashwood et les interroge suite \u00e0 leur d\u00e9faite. Myers indique qu&rsquo;il a encore plein de choses \u00e0 apprendre \u00e0 Dashwood et c&rsquo;est pour cela qu&rsquo;il l&rsquo;a choisi pour \u00eatre sa partenaire pour Homecoming. Dashwood refuse cependant en disant qu&rsquo;elle ne veut plus faire \u00e9quipe avec lui apr\u00e8s ces deux d\u00e9faites \u00e0 la suite. Myers doit donc se trouver une nouvelle co\u00e9quipi\u00e8re et Sam Beale dit qu&rsquo;il a une id\u00e9e.<\/p>\n\n\n\n<p>Le nouveau venu Jay White arrive sur le ring et se pr\u00e9sente officiellement au public. Il indique qu&rsquo;il est venu \u00e0 l&rsquo;Impact Zone pour une chose: David Finlay. Les deux lutteurs sont pr\u00e9vus pour s&rsquo;affronter pour son NEVER Openweight Championship lors du show NJPW Resurgence le mois prochain. White traite ensuite Finlay d&rsquo;\u00e9chec ambulant et qu&rsquo;il d\u00e9shonore l&rsquo;h\u00e9ritage familial. Le n\u00e9oz\u00e9landais tient \u00e0 \u00eatre clair qu&rsquo;il ne remportera jamais sa ceinture. White tourne ensuite son attention vers The Elite en disant qu&rsquo;il a repris le flambeau du Bullet Club et l&rsquo;a amen\u00e9 dans une nouvelle \u00e8re. Il ajoute que les Good Brothers ne sont plus ce qu&rsquo;ils \u00e9taient et qu&rsquo;en cons\u00e9quence il refuse leur demande de r\u00e9int\u00e9grer le groupe. The Elite finit par arriver. Don Callis commence par complimenter White sur son look et la qualit\u00e9 de sa promo mais insiste sur le fait que le Bullet Club a connu son heure de gloire avec Kenny Omega comme leader. L&rsquo;\u00e8re de White n&rsquo;est remplie que de midcarder. Callis dit cependant avoir une proposition que White ne refusera pas. Ce dernier devrait supplier pour int\u00e9grer The Elite pour venir jouer avec les Main Eventers. White pr\u00e9f\u00e8re lui r\u00e9pondre en rappelant qu&rsquo;il a battu Omega la derni\u00e8re fois qu&rsquo;ils se sont affront\u00e9s. Omega intervient et ne semble pas heureux que Callis ait propos\u00e9 \u00e0 White de rejoindre leur groupe. Il indique qu&rsquo;ils ont besoin d&rsquo;en parler en priv\u00e9 et repart en coulisse avec Callis. Les Good Brothers encha\u00eenent alors et s&rsquo;amusent que White essaie de reproduire l&rsquo;histoire qu&rsquo;ils ont cr\u00e9\u00e9. White leur r\u00e9pond qu&rsquo;ils ont mis fin \u00e0 cela en vendant leur ame au diable (WWE) et que maintenant ils esp\u00e8rent pouvoir devenir aussi bon que lui. Les Good Brothers sont vex\u00e9s et commencent \u00e0 se rapprocher de White. Chris Bey arrive alors et avec White, renvoie les Good Brothers \u00e0 l&rsquo;ext\u00e9rieur. Bey a visiblement accept\u00e9 l&rsquo;invitation d&rsquo;int\u00e9grer le Bullet Club.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>Gia Miller est en interview avec Josh Alexander. Le champion X-Division dit qu&rsquo;apr\u00e8s avoir conserv\u00e9 son titre, son prochain objectif sera de devenir le visage d&rsquo;Impact Wrestling. Kenny Omega vient cependant l&rsquo;interrompre et lui demande s\u00a0\u00bbil a correctement entendu. Alexander confirme Omega n&rsquo;en croit pas d&rsquo;avoir entendu cela puis repart.<\/p>\n\n\n\n<p>Les Good Brothers sont \u00e9nerv\u00e9s en coulisse et challengent Jay White et Chris Bey pour la semaine prochaine.<\/p>\n\n\n\n<p><strong>&#8211; FinJuice (David Finlay et Juice Robinson) def. Ace Austin et Madman Fulton<\/strong><\/p>\n\n\n\n<p>Les FinJuice se sont occup\u00e9s d&rsquo;Austin suite \u00e0 un teamwork. Cela est cependant plus compliqu\u00e9 avec Fulton qui soul\u00e8ve Robinson qui parvient cependant \u00e0 ses d\u00e9gager et porter un roll-up \u00e0 son adversaire pour obtenir le compte de trois. Les perdants sont frustr\u00e9s et attaquent les vainqueurs post-match. Les FinJuice renversent cependant la tendance et se positionnent pour un Doomsday Device quand Rohit Raju et Shera interviennent pour emp\u00eacher cela. Les heels en surnombre d\u00e9truisent les faces. Le segment se termine cependant avec Shera et Fulton se faisant face alors que Raju et Austin leur disent qu&rsquo;ils sont amis.<\/p>\n\n\n\n<p>Rich Swann et Willie Mack sont en coulisse et disent qu&rsquo;ils veulent un match avec les Violent By Design. Les lumi\u00e8res s&rsquo;\u00e9teignent-se rallument et l&rsquo;on voit que les VDB ont attaqu\u00e9 Swann et Mack. Eric Young prend la parole pour dire que le challenge est accept\u00e9.<\/p>\n\n\n\n<p>Gia Miller trouve Moose devant le bureau de Scott D&rsquo;Amore. Le lutteur explique vouloir un rematch contre Chris Sabin apr\u00e8s sa d\u00e9faite de Slammiversary. Sabin arrive justement pour faire savoir qu&rsquo;il n&rsquo;a pas peur et l&rsquo;officiel organise ce match pour la semaine prochaine.<\/p>\n\n\n\n<p><strong>&#8211; Impact Knockouts Tag Team Championship: Havok et Rosemary (w. Crazzy Steve) (c) def. Fire N Flava (Kiera Hogan et Tasha Steelz)<\/strong><\/p>\n\n\n\n<p>Rematch de Slammiversary avec le m\u00eame r\u00e9sultat final. Alors qu&rsquo;Havok malmenait Hogan, Steelz est venue en aide \u00e0 sa co\u00e9quipi\u00e8re en venant attraper leur adversaire. Hogan veut en profiter pour frapper Havok mais cette derni\u00e8re \u00e9vite et Hogan touche accidentellement Steelz. Hogan ne s&rsquo;en remet pas de son erreur et Havok en profite pour faire le tag \u00e0 Rosemary. Les deux championnes portent alors leur finisher en commun sur Hogan pour conserver leur titre.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/07\/22\/voir-impact-wrestling-en-direct-des-20h-est-2h-europe-programme-de-ce-soir-et-plus\/\" target=\"_blank\">Pour voir cet Impact, cliquez ici<\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-small-font-size\"><em>Merci \u00e0 Francis No\u00ebl pour les r\u00e9sultats<\/em><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir cet Impact, cliquez ici &#8211; Chris Bey def. Rohit Raju (w. Shera) Raju a port\u00e9 un Jumping Back Elbow suivi d&rsquo;une Diving Clothesline mais n&rsquo;a obtenu qu&rsquo;un compte de deux. L&rsquo;indien continue sur sa lanc\u00e9e avec un Crossface quand Bey finit par avancer la tendance. Si Raju \u00e9vite le Burning Hammer il se&#8230;<\/p>\n","protected":false},"author":4,"featured_media":54939,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,21,41],"tags":[],"ppma_author":[292],"class_list":["post-54936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-resultats","category-tna-impact"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/54936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=54936"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/54936\/revisions"}],"predecessor-version":[{"id":54940,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/54936\/revisions\/54940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/54939"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=54936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=54936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=54936"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=54936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}