{"id":53765,"date":"2021-07-01T23:39:00","date_gmt":"2021-07-01T23:39:00","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=53765"},"modified":"2021-07-02T02:46:47","modified_gmt":"2021-07-02T02:46:47","slug":"resultats-et-video-du-nxt-uk-1et-juillet-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/07\/01\/resultats-et-video-du-nxt-uk-1et-juillet-2021\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du NXT UK, 1et Juillet 2021!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/07\/01\/regardez-le-nxt-uk-du-1er-juillet-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce NXT UK, cliquez ici<\/a><\/strong><\/li><\/ul>\n\n\n\n<p><strong>WWE NXT UK Londres, BT Sport, 1er juillet 2021!<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Andy Shepherd et Nigel McGuinness.<\/p>\n\n\n\n<p>&#8211; Ce soir c&rsquo;est WWE NXT UK, le show anglais d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue et les catcheuses arrivent sur le ring.<\/p>\n\n\n\n<p><strong>Emilia McKenzie bat Isla Dawn<\/strong> avec une German Suplex et elle enchaine avec son Shining Wizard pour le compte de trois sur Dawn.<\/p>\n\n\n\n<p>&#8211; En coulisse, on demande \u00e0 Wolfgant et Mark Coffey leur commentaire sur leur rivalit\u00e9 amical. Coffey dit qu&rsquo;ils sont \u00e9gaux, pour l&rsquo;instant. Il a une id\u00e9e ! Coffey quitte et Wolfgang le suit.<\/p>\n\n\n\n<p><strong>NXT UK Heritage Cup Championship<\/strong><\/p>\n\n\n\n<p>Tyler Bate (c) bat Jack Starz 2-1 au quatri\u00e8me round avec un coup de pied et son Tyler Driver 97 pour le compte de trois.<\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Bate f\u00e9licite Starz pour le match. Mark Coffey arrive avec Wolfgang et il monte sur le ring. Coffey f\u00e9licite Bate, mais il le frappe en rigolant et quitte le ring.<\/p>\n\n\n\n<p>&#8211; En coulisse, Sid Scala rejoint Pretty Deadly pendant leur photo shoot. Scala leur annonce que Subculture aura un match contre eux la semaine prochaine. Sam et Lewis ne sont pas contents et disent qu&rsquo;ils doivent m\u00e9rite leur chance. Scala dit que Lewis va affronter Mark Anderson et si Andrews gagne il aura le match.<\/p>\n\n\n\n<p>&#8211; Le championne Meiko Satomura arrive sur le ring. Satomura dit qu&rsquo;elle est la nouvelle championne apr\u00e8s sa victoire contre Kay Lee Ray. Elle est bien heureuse et NXT UK est maintenant sa maison. La musique de Nina Samuels commence et elle arrive. Samuels dit qu&rsquo;elle est ici pour la f\u00e9licite. Satomura et Ray ont donn\u00e9 un grand spectacle en montrant que NXT UK est l&rsquo;endroit o\u00f9 il faut \u00eatre. En plus Satomura est ici comme la championne, bravo. Samuels dit que ce n&rsquo;est pas un secret que NXT UK a besoin plus d&rsquo;elle et Satomura aussi. Satomura a besoin d&rsquo;une vraie star comme elle comme la premi\u00e8re adversaire pour qu&rsquo;elle puisse la faire connaitre. Amale arrive sur la sc\u00e8ne et attaque Samuels dans le dos ! Amale la lance contre la marche d&rsquo;acier.<\/p>\n\n\n\n<p><strong>Amale<\/strong>\u00a0dit que personne n&rsquo;a besoin de voir Samuels. Le monde a besoin de l&rsquo;espoir. Elle est arriv\u00e9 en baissant les yeux et elle va les gifler.\u00a0\u00c7a suffit de voir la m\u00eame femme chaque semaine. Elle n&rsquo;est pas ici pour f\u00e9liciter Satomura, mais bien prendre sa chance. Elle devrait \u00eatre la prochaine challenger.\u00a0Elle n&rsquo;est pas ici pour jouer. Satomura la frappe au visage et dit que \u00e7a suffit de parler, Amale aura son match !<\/p>\n\n\n\n<p>&#8211; En coulisse, Joe Coffey rejoint Rampage Brown et dit que rien n&rsquo;est r\u00e9gl\u00e9 entre les deux. Les deux rigolent.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Blair Davenport. Elle explique apr\u00e8s avoir fait le tour du monde. Elle a abandonn\u00e9 des amis et sa famille pour \u00eatre ici. Elle arrive. (On d\u00e9couvre son visage et il s&rsquo;agit de la catcheuse ind\u00e9pendante Bea Priestley.)<\/p>\n\n\n\n<p><strong>Aoife Valkyrie bat Mila Smidt<\/strong> avec un coup de genou et un Heel Kick. Valkyrie enchaine avec son Leg Drop du coin derri\u00e8re la t\u00eate pour le compte de trois.<\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Valkyrie et Jinny \u00e9changent des regards.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur Kenny Williams qui explique vouloir stopper l&rsquo;ascension de Nathan Frazer.<\/p>\n\n\n\n<p>&#8211; En coulisse, Eddie Dennis arr\u00eate Trent Seven pendant une discussion avec les m\u00e9dias pour savoir comment il se sent apr\u00e8s la parte de la coupe Heritage, sa d\u00e9faite \u00e0 TakeOver et celle contre Jordan Devlin. Seven dit qu&rsquo;il est heureux que Dennis se pr\u00e9occupe de lui autant. Mais il ne devrait plus jamais l&rsquo;interrompe.<\/p>\n\n\n\n<p><strong>Jordan Devlin bat A-Kid<\/strong> en r\u00e9sistant \u00e0 un Arm Bar de A-Kid et le repousse. Devlin \u00e9crase la jambe de A-Kid au sens contraire de l&rsquo;os et A-Kid tape.<\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, les m\u00e9decins arrivent pour s&rsquo;occuper de A-Kid et Devlin c\u00e9l\u00e8bre la victoire.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/07\/01\/regardez-le-nxt-uk-du-1er-juillet-2021\/\" target=\"_blank\">Pour voir ce NXT UK, cliquez ici<\/a><\/strong><\/li><\/ul>\n\n\n\n<p class=\"has-small-font-size\"><em>Merci \u00e0 Pierre Jean Jacques pour les r\u00e9sultats<\/em><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce NXT UK, cliquez ici WWE NXT UK Londres, BT Sport, 1er juillet 2021! Les commentateurs sont Andy Shepherd et Nigel McGuinness. &#8211; Ce soir c&rsquo;est WWE NXT UK, le show anglais d\u00e9marre avec les commentateurs qui nous souhaitent la bienvenue et les catcheuses arrivent sur le ring. Emilia McKenzie bat Isla Dawn&#8230;<\/p>\n","protected":false},"author":4,"featured_media":53766,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,21],"tags":[],"ppma_author":[292],"class_list":["post-53765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=53765"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53765\/revisions"}],"predecessor-version":[{"id":53767,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53765\/revisions\/53767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/53766"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=53765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=53765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=53765"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=53765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}