{"id":53546,"date":"2021-06-27T16:44:45","date_gmt":"2021-06-27T16:44:45","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=53546"},"modified":"2021-06-27T16:44:49","modified_gmt":"2021-06-27T16:44:49","slug":"scarlett-pourrait-faire-un-impact-a-la-wwe-des-ce-lundi","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/06\/27\/scarlett-pourrait-faire-un-impact-a-la-wwe-des-ce-lundi\/","title":{"rendered":"Scarlett Pourrait Faire un Impact \u00e0 la WWE D\u00e8s ce Lundi!"},"content":{"rendered":"\n<p>Comme vous le savez depuis quelques jours, apr\u00e8s Karrion Kross et Bronson Reed, c&rsquo;est\u00a0Scarlett et Shotzi Blackheart qui ont particip\u00e9 \u00e0 un dark match lors du dernier \u00e9pisode de SmackDown, afin d&rsquo;\u00eatre \u00e9valu\u00e9es par les officiels de la WWE. Sauf que la f\u00e9d\u00e9ration ne compte pas s&rsquo;arr\u00eater l\u00e0. Des superstars f\u00e9minines de NXT devraient \u00e9galement prendre le m\u00eame chemin que Kross et Reed.<\/p>\n\n\n\n<p>Ainsi, on apprend par notre source que Scarlett et Shotzi Blackheart devraient \u00eatre dans les coulisses de RAW ce lundi. Pour autant, \u00e7a ne veut pas dit qu&rsquo;elles participeront au show rouge. Elles pourraient tr\u00e8s bien faire un match lors de Main Event, \u00e9tant enregistr\u00e9 avant RAW, tout comme\u00a0Karrion Kross et Bronson Reed la semaine derni\u00e8re. Si tel est le cas, Scarlett fera alors son premier match t\u00e9l\u00e9vis\u00e9 \u00e0 la WWE puisqu&rsquo;elle n&rsquo;a fait qu&rsquo;accompagner le champion de NXT sur le show du mardi soir.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme vous le savez depuis quelques jours, apr\u00e8s Karrion Kross et Bronson Reed, c&rsquo;est\u00a0Scarlett et Shotzi Blackheart qui ont particip\u00e9 \u00e0 un dark match lors du dernier \u00e9pisode de SmackDown, afin d&rsquo;\u00eatre \u00e9valu\u00e9es par les officiels de la WWE. Sauf que la f\u00e9d\u00e9ration ne compte pas s&rsquo;arr\u00eater l\u00e0. Des superstars f\u00e9minines de NXT devraient \u00e9galement&#8230;<\/p>\n","protected":false},"author":4,"featured_media":53547,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[292],"class_list":["post-53546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=53546"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53546\/revisions"}],"predecessor-version":[{"id":53548,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53546\/revisions\/53548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/53547"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=53546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=53546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=53546"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=53546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}