{"id":53513,"date":"2021-06-26T03:57:00","date_gmt":"2021-06-26T03:57:00","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=53513"},"modified":"2021-06-27T00:02:44","modified_gmt":"2021-06-27T00:02:44","slug":"la-wwe-avait-de-gros-plans-pour-marina-shafir-dautres-noms-de-la-nxt-pret-du-roster-principal-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/06\/26\/la-wwe-avait-de-gros-plans-pour-marina-shafir-dautres-noms-de-la-nxt-pret-du-roster-principal-et-plus\/","title":{"rendered":"La WWE avait de gros plans pour Marina Shafir! D&rsquo;autres Noms de la NXT Pr\u00eat du Roster Principal, et Plus!"},"content":{"rendered":"\n<p>La semaine derni\u00e8re pour SmackDown,\u00a0les officiels de la WWE ont fait venir Karrion Kross et Bronson Reed pour un Dark Match afin de les \u00e9valuer. Le champion de NXT et le champion nord-am\u00e9ricain de NXT\u00a0ont finalement termin\u00e9 \u00e0 Main Event,\u00a0dans l&rsquo;espoir peut-\u00eatre d&rsquo;arriver dans le main roster ces prochaines semaines. Apr\u00e8s ces deux catcheurs, c&rsquo;est au tour \u00e0 deux autres stars du show jaune d&rsquo;\u00eatre appel\u00e9es par les officiels.<\/p>\n\n\n\n<p>Ainsi, on apprend via\u00a0que\u00a0la WWE a fait venir Scarlett et Shotzi Blackheart dans les coulisses de SmackDown cette semaine. Ces deux femmes ont particip\u00e9 \u00e0 un Dark Match, bien que Scarlett n&rsquo;ait toujours pas fait de matchs \u00e0 la WWE puisqu&rsquo;elle accompagne Karrion Kross. Toutefois, la raison pour laquelle la f\u00e9d\u00e9ration a choisi Scarlett et Shotzi Blackheart pour ce Dark Match n&rsquo;a pas \u00e9t\u00e9 expliqu\u00e9e.<\/p>\n\n\n\n<p>Selon\u00a0PWInsider, Karrion Kross \u00e9tait lui aussi dans les coulisses de SmackDown pour un autre Dark Match. Cette semaine, il a affront\u00e9 Slapjack.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p> Pour la seconde fois en juin 2021, la WWE a renvoy\u00e9 hier de nouvelles Superstars, cette fois-ci de NXT et principalement 205 Live. Pas moins de 14 stars ont \u00e9t\u00e9 touch\u00e9es par cette vague, dont\u00a0Marina Shafir pour qui la f\u00e9d\u00e9ration avait pourtant des plans avant son d\u00e9part.<\/p>\n\n\n\n<p>Notre source nous\u00a0r\u00e9v\u00e8le que\u00a0la WWE pr\u00e9voyait d&rsquo;int\u00e9grer Marina Shafir dans une nouvelle \u00e9quipe, celle de Diamond Mine\u00a0qui a d\u00e9but\u00e9 lors de NXT cette semaine. Roderick Strong est \u00e0 la t\u00eate de ce groupe, qui est le mari de Sharfir. Cette derni\u00e8re aurait alors \u00e9t\u00e9 la touche f\u00e9minine du clan. Le site am\u00e9ricain ajoute que de nombreuses personnes \u00e0 NXT pensaient que c&rsquo;\u00e9tait toujours le plan lorsque Diamond Mine a effectu\u00e9 ses d\u00e9buts mercredi dernier.<\/p>\n\n\n\n<p>Notons \u00e9galement que\u00a0Arturo Ruas faisait partie des plans originaux de cette \u00e9quipe, mais lui aussi s&rsquo;est fait renvoyer hier.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La semaine derni\u00e8re pour SmackDown,\u00a0les officiels de la WWE ont fait venir Karrion Kross et Bronson Reed pour un Dark Match afin de les \u00e9valuer. Le champion de NXT et le champion nord-am\u00e9ricain de NXT\u00a0ont finalement termin\u00e9 \u00e0 Main Event,\u00a0dans l&rsquo;espoir peut-\u00eatre d&rsquo;arriver dans le main roster ces prochaines semaines. Apr\u00e8s ces deux catcheurs, c&rsquo;est&#8230;<\/p>\n","protected":false},"author":609,"featured_media":53514,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,36,23],"tags":[],"ppma_author":[295],"class_list":["post-53513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-smackdown","category-wwe"],"authors":[{"term_id":295,"user_id":609,"is_guest":0,"slug":"rodrigo","display_name":"Rodrigue Tousignant","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/51fe284bb6dbe8a6b4c2bf998ad658f4a9cd24b7e58f15ec85888070c7340ce6?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/609"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=53513"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53513\/revisions"}],"predecessor-version":[{"id":53515,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53513\/revisions\/53515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/53514"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=53513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=53513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=53513"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=53513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}