{"id":53038,"date":"2021-06-18T21:08:12","date_gmt":"2021-06-18T21:08:12","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=53038"},"modified":"2021-06-19T00:21:06","modified_gmt":"2021-06-19T00:21:06","slug":"deuxieme-heure-de-smackdown-10","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/06\/18\/deuxieme-heure-de-smackdown-10\/","title":{"rendered":"Deuxi\u00e8me Heure de Smackdown!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/06\/18\/resultats-et-video-du-wwe-friday-night-smackdown-18-juin-2021\/\"><strong>Pour revenir \u00e0 la premi\u00e8re Heure de Smackdown, cliquez ici<\/strong><\/a><\/li><\/ul>\n\n\n\n<p>&#8211; Bianca Belair fait son entr\u00e9e et dit que \u00e7a fait du bien de mettre Bayley \u00e0 sa place, lorsque \u00ab\u00a0Ding Dong Hello\u00a0\u00bb est devenu \u00ab\u00a0Ding Dong Good Bye\u00a0\u00bb. Bayley peut dire au revoir \u00e0 son r\u00eave de devenir championne ce dimanche. Elle lui dit de venir mais Bayley ne vient pas. Belair poursuit en disant qu&rsquo;elle n&rsquo;est plus cet enfant qui laissait les autres la d\u00e9finir. Elle s&rsquo;est battue, elle a ramp\u00e9 pour arriver ici. Elle est fi\u00e8re. \u00c0 Hell in a Cell, Bayley lui donnera tout ce qu&rsquo;elle a mentalement et physiquement. Elle veut lui dire en face, mais elle l&rsquo;esquive : Belair la veut non seulement sur le ring, mais aussi dans la cage ! Bayley pense avoir le dernier rire, mais Belair restera championne de SmackDown. Tout d&rsquo;abord, ils essayent de vous ignorer. Ensuite, ils se moquent de vous, puis ils vous combattent et vous gagnez.<\/p>\n\n\n\n<p>Bayley fait son entr\u00e9e puis les deux catcheuses se battent ! Belair arrive \u00e0 faire sortir Bayley du ring, puis l&rsquo;envoie contre la table des commentateurs, avant de vouloir l&rsquo;envoyer contre la barricade, mais Bayley passe par dessus et lui tire les cheveux. Bayley reprend l&rsquo;avantage et la met sur le ring. Elle termine en prenant la ceinture et la soul\u00e8ve. Les \u00e9crans du ThunderDome sont remplis de Bayley.<\/p>\n\n\n\n<p>&#8211; En coulisses, Roman Reigns est rejoint par Jimmy Uso. Reigns lui demande o\u00f9 est son fr\u00e8re, puis Jimmy r\u00e9pond qu&rsquo;il n&rsquo;a pas eu de nouvelles de lui pendant toute la semaine. Mais si Reigns a besoin de son aide&#8230; Reigns lui dit qu&rsquo;il n&rsquo;a pas besoin de son aide. Il a besoin qu&rsquo;il trouve son fr\u00e8re car il a besoin de son fr\u00e8re. Ils ont besoin de son fr\u00e8re. Leur famille est la meilleure quand ils sont ensemble. Qu&rsquo;il retrouve son fr\u00e8re.<\/p>\n\n\n\n<p>&#8211; Otis et son nouvu look fait son entr\u00e9e  avec Chad Gable, suivis d&rsquo;Angelo Dawkins. Avant que la cloche ne sonne, Chad Gable gifle Angelo Dawkins puis sort du ring en courant. Dawkins lui course apr\u00e8s, mais Otis le met \u00e0 terre. Otis et Gable se mettent \u00e0 deux sur Dawkins. Ils le remettent sur le ring puis lui font un combo Discus Clothesline \/ German Suplex. Les officiels arrivent pour v\u00e9rifier que Dawkins aille bien.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; Dans les coulisses, Kayla Braxton est avec Cesaro pour parler de sa rivalit\u00e9 avec Seth Rollins. Ce dernier dit que Seth Rollins lui a fait le Stomp sur la rampe et l&rsquo;a mis sur une civi\u00e8re. La WWE, c&rsquo;est sa vie. Il adore faire \u00e7a. Il a travaill\u00e9 pendant longtemps pour \u00eatre l\u00e0 o\u00f9 il est, et Seth Rollins a essay\u00e9 de l&rsquo;enlever de sa place. Seth Rollins arrive et Cesaro se l\u00e8ve. Rollins lui dit de se calmer, il n&rsquo;est pas l\u00e0 pour se battre. Il veut une conversation, face \u00e0 face. Rollins prend la place de Braxton.<\/p>\n\n\n\n<p>Seth Rollins dit qu&rsquo;il est venu dire \u00e0 Cesaro qu&rsquo;il le d\u00e9goute. Tout ce qu&rsquo;il fait est une honte. Apr\u00e8s ce qu&rsquo;il a fait la semaine derni\u00e8re, il ne m\u00e9rite pas une once de respect. Ce samedi lors de Hell in a Cell, il va lui montrer et \u00e0 tout le monde ce qu&rsquo;il r\u00e9serve lorsqu&rsquo;il le mettra \u00e0 sa place. Cesaro dit qu&rsquo;il ne savait pas que Rollins avait le courage de lui faire face d&rsquo;homme \u00e0 homme. Il respecte tout ce que Rollins a dit. Il le respecte comme catcheur, ils se voient ce dimanche. Cesaro fait tomber Rollins de la chaise en le poussant puis part.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat Universal Hell in a Cell <\/strong><\/p>\n\n\n\n<p><strong>Roman Reigns vs Rey Mysterio<\/strong><\/p>\n\n\n\n<p>En fin de match, Roman Reigns envoie Rey Mysterio contre la cage et le fait remonter sur le ring. Il lui applique ensuite une Guillotine pour le faire taper.<\/p>\n\n\n\n<p><em>Gagnant: Romain Reigns<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, la cage remonte puis Jimmy Uso arrive et c\u00e9l\u00e8bre avec Roman Reigns. Rey Mysterio se rel\u00e8ve et Reigns lui applique une autre Guillotine. Le show se termine ainsi.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/06\/18\/regardez-le-wwe-friday-night-smackdown-du-18-juin-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour voir ce Smackdown, cliquez ici<\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re Heure de Smackdown, cliquez ici &#8211; Bianca Belair fait son entr\u00e9e et dit que \u00e7a fait du bien de mettre Bayley \u00e0 sa place, lorsque \u00ab\u00a0Ding Dong Hello\u00a0\u00bb est devenu \u00ab\u00a0Ding Dong Good Bye\u00a0\u00bb. Bayley peut dire au revoir \u00e0 son r\u00eave de devenir championne ce dimanche. Elle lui dit&#8230;<\/p>\n","protected":false},"author":4,"featured_media":53039,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"ppma_author":[292],"class_list":["post-53038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-smackdown"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=53038"}],"version-history":[{"count":14,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53038\/revisions"}],"predecessor-version":[{"id":53065,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/53038\/revisions\/53065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/53039"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=53038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=53038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=53038"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=53038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}