{"id":52939,"date":"2021-06-16T05:42:00","date_gmt":"2021-06-16T05:42:00","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=52939"},"modified":"2021-06-16T13:46:26","modified_gmt":"2021-06-16T13:46:26","slug":"aucune-importance-de-revenir-heel-ou-pas-pour-john-cena","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/06\/16\/aucune-importance-de-revenir-heel-ou-pas-pour-john-cena\/","title":{"rendered":"Aucune Importance de Revenir Heel ou Pas Pour John Cena!"},"content":{"rendered":"\n<p>Comme vous le savez, John Cena pourrait faire son retour \u00e0 WWE SmackDown le 16 juillet prochain. Avant son retour, le Super H\u00e9ro de la WWE a effectu\u00e9 plusieurs interviews avec la presse pour promouvoir Fast &amp; Forious 9. Durant l&rsquo;une d&rsquo;entre elles, accord\u00e9e \u00e0&nbsp;<a href=\"https:\/\/youtu.be\/yY1ihck6fTE\" target=\"_blank\" rel=\"noreferrer noopener\">Chris Van Vliet<\/a>, John Cena a abord\u00e9 le sujet d&rsquo;un heel turn \u00e0 la WWE.<\/p>\n\n\n\n<p>Rappelons qu&rsquo;il joue un vilain dans le prochain \u00e9pisode de Fast &amp; Forious. Pendant l&rsquo;interview, il est alors questionn\u00e9 par rapport \u00e0 son r\u00f4le \u00e0 la WWE pour savoir s&rsquo;il souhaite devenir Heel comme dans le film ou rester le Baby Face de la f\u00e9d\u00e9ration, r\u00f4le qu&rsquo;il porte sur ses \u00e9paules depuis plusieurs ann\u00e9es. Il a alors r\u00e9pondu :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&lt;&lt; S&rsquo;ils d\u00e9cident de changer mon comportement en Heel ou me laisser Baby Face, cela n&rsquo;aura aucune importance pour moi, car j&rsquo;ai les moyens d&rsquo;exprimer toutes les \u00e9motions que je souhaite faire. >><\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Comme vous le savez, John Cena pourrait faire son retour \u00e0 WWE SmackDown le 16 juillet prochain. Avant son retour, le Super H\u00e9ro de la WWE a effectu\u00e9 plusieurs interviews avec la presse pour promouvoir Fast &amp; Forious 9. Durant l&rsquo;une d&rsquo;entre elles, accord\u00e9e \u00e0&nbsp;Chris Van Vliet, John Cena a abord\u00e9 le sujet d&rsquo;un heel&#8230;<\/p>\n","protected":false},"author":4,"featured_media":52940,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[292],"class_list":["post-52939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=52939"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52939\/revisions"}],"predecessor-version":[{"id":52941,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52939\/revisions\/52941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/52940"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=52939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=52939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=52939"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=52939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}