{"id":52906,"date":"2021-06-15T22:26:46","date_gmt":"2021-06-15T22:26:46","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=52906"},"modified":"2021-06-17T20:44:30","modified_gmt":"2021-06-17T20:44:30","slug":"resultats-et-video-du-wwe-nxt-15-juin-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/06\/15\/resultats-et-video-du-wwe-nxt-15-juin-2021\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du WWE NXT, 15 Juin 2021!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/06\/15\/regardez-le-wwe-nxt-du-15-juin-2021\/\" target=\"_blank\"><strong>Pour voir ce WWE NXT, cliquez ici<\/strong><\/a><\/li><\/ul>\n\n\n\n<p><strong>WWE NXT, Capitol Wrestling Center, Orlando, Floride, 15 juin 2021!<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Vic Joseph, Wade Barrett et Beth Phoenix.<\/p>\n\n\n\n<p>&#8211; Le WWE NXT poste In Your House d\u00e9bute avec une vid\u00e9o des \u00e9v\u00e9nements \u00e0 NXT TakeOver In Your House. Les commentateurs nous souhaitent ensuite la bienvenue et&nbsp;<strong>William Regal<\/strong>&nbsp;arrive sur le ring.<\/p>\n\n\n\n<p>Regal dit qu&rsquo;il est avec NXT depuis le premier jour, il a commenc\u00e9 comme commentateur. Regal verse quelques larmes. Regal dit qu&rsquo;il a regard\u00e9 NXT devenir cette belle chose avec de grands catcheurs. Pour faire le tour aux \u00c9tats-Unis, au Japon, au UK et en Australie. On ne sait pas beaucoup de choses, son temps libre n&rsquo;\u00e9tait pas pass\u00e9 avec sa famille mais avec son r\u00eave de faire devenir NXT comme il est aujourd&rsquo;hui. Pour tous les catcheurs qui sont venus ici, les commentateurs et pour tous les fans. Il a finalement d\u00e9cid\u00e9 avec le chaos ici qu&rsquo;il a tout donn\u00e9 ce qu&rsquo;il \u00e9tait capable.<\/p>\n\n\n\n<p>Regal dit qu&rsquo;\u00e0 cause de nous, les catcheurs et les employ\u00e9s, il croit qu&rsquo;il n&rsquo;est plus capable de donner ce qu&rsquo;on m\u00e9rite. Alors il croit que c&rsquo;est le moment de &#8230; Regal est coup\u00e9 par la musique de Karrion Kross et il arrive avec Scarlett. Kross dit qu&rsquo;il savait que ce jour allait arriver, mais il ne savait pas quand. Ils devaient venir ici quand ils l&rsquo;ont entendu pour pouvoir le sentir et le voir. Est-ce que Regal pleure ? Oui, compl\u00e8tement path\u00e9tique. Il lui a dit que Regal avait perdu le contr\u00f4le du roster, Regal savait qu&rsquo;il avait raison. \u00c0 TakeOver Regal a r\u00e9alis\u00e9 qu&rsquo;il pouvait contr\u00f4ler NXT sous le chaos et la violence. Maintenant ils sont ici et il veut que Regal annonce qu&rsquo;il quitte. Il veut ensuite le voir partir et plus jamais le revoir. Regal doit dire que Kross avait raison. Ils n&rsquo;ont pas toute la soir\u00e9e. La musique de&nbsp;<strong>Samoa Joe<\/strong>&nbsp;commence et il arrive sur le ring ! Joe dit que Regal voulait parler avec lui. Regal confirme que oui, mais pas dans ses circonstances. \u00c0 cause de son amour pour NXT, il pense que NXT a besoin d&rsquo;un General Manager avec int\u00e9grit\u00e9 et le respect qu&rsquo;il m\u00e9rite.&nbsp;<strong>Il voudrait donc voir Samoa Joe comme le nouveau General Manager de NXT. <\/strong><\/p>\n\n\n\n<p><strong>Joe dit que sans aucun doute sa r\u00e9ponse est non<\/strong>&nbsp;! Il va expliquer pourquoi, il comprend que c&rsquo;est chaud. Joe dit qu&rsquo;en sept ans Regal a amen\u00e9 les meilleurs talents au monde, incluant lui. Regal a transform\u00e9 NXT en ph\u00e9nom\u00e8ne international. Joe dit qu&rsquo;il a toujours offert du respect pour Regal. Il aimerait donc s&rsquo;assurer que Regal re\u00e7oit le respect qu&rsquo;il m\u00e9rite de tout le monde. Regal dit que c&rsquo;est une id\u00e9e int\u00e9ressante. \u00c7a prendrait quelques conditions, comme Joe ne peut pas \u00eatre un comp\u00e9titeur et qu&rsquo;il ne peut pas frapper quelqu&rsquo;un \u00e0 moins d&rsquo;\u00eatre provoqu\u00e9. Joe dit qu&rsquo;il accepte l&rsquo;offre. Alors pourquoi Kross est encore sur le ring ? Tik tok pour Karrion Kross. Kross et Scarlett quittent le ring.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, en coulisse, on retrouve Grizzled Young Veterans. Zack Gibson dit qu&rsquo;ils ont bien entendu les insultes de Ciampa et Thatcher. Ce soir c&rsquo;est Tornado Match, aucune excuse. Ils vont d\u00e9couvrir pourquoi ils sont Grizzled Young Veterans.<\/p>\n\n\n\n<p><strong>Imperium (Marcel Barthel et Fabian Aichner) vs Breezago (Tyler Breeze et Fandango)<\/strong><\/p>\n\n\n\n<p>En fin de match, Aichner est en contr\u00f4le, mais Breeze le surprend avec un Roll Up pour la victoire.<\/p>\n\n\n\n<p><em>Gagnants : Breezango<\/em><\/p>\n\n\n\n<p> Apr\u00e8s le combat, Imperium est furieux et le duo attaque Breezango. Ils terminent avec leur Uppercut \u00e0 deux Breeze pour laisser leur banni\u00e8re sur lui.<\/p>\n\n\n\n<p>&#8211; En coulisse, Adam Cole et Kyle O&rsquo;Reilly se font s\u00e9parer par la s\u00e9curit\u00e9. Regal dit qu&rsquo;ils vont s&rsquo;affronter \u00e0 Great American Bash. Mais avant ils pourront choisir leur adversaire pour la semaine prochaine. Les deux commencent \u00e0 se frapper encore, Samoa Joe intervient et applique un Sleeper sur Cole pour le sonner. Joe dit aux arbitres d&rsquo;aviser Cole quand il se r\u00e9veillera de donner sa d\u00e9cision \u00e0 Regal.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, en coulisse, Santos Escobar dit que c&rsquo;\u00e9tait une trag\u00e9die ce qui est arriv\u00e9 \u00e0 TakeOver. Personne n&rsquo;a le droit de l&rsquo;envoyer dans un mur. C&rsquo;est la seule chose que Bronson Reed a r\u00e9ussi pour le garder au sol. Ils vont s&rsquo;affronter un contre un et il va lui prendre le titre Nord-Am\u00e9ricain.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o sur la nouvelle recrue Trey Baxter.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Cruiserweight Championship <\/strong><\/p>\n\n\n\n<p><strong>Kushida \u00a9 vs Trey Baxter<\/strong><\/p>\n\n\n\n<p>En fin de match, Kushida fait un DDT \u00e0 Baxter et enchaine avec son Arm Bar pour le faire taper.<\/p>\n\n\n\n<p><em>Gagnant : Kushida<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Kyle O&rsquo;Reilly entre sur le ring et le challenge pour un match la semaine prochaine comme il veut affronter les meilleurs. Kushida accepte.<\/p>\n\n\n\n<p>&#8211; En coulisse, Franky Monet annonce qu&rsquo;elle fera un encore de sa premi\u00e8re mondiale comme tout le monde veut. Monet rejoint Jessi Kamea et Aliyah plus loin en disant qu&rsquo;elles auraient gagn\u00e9 si ce n&rsquo;\u00e9tait pas de Robert Stone \u00e0 TakeOver. Stone arrive et Monet change de discours en le f\u00e9licitant pour TakeOver.<\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Mercedes Martinez dit que Tian Sha joue avec la mauvaise personne. Boa va encore une fois sentir l&rsquo;acier s&rsquo;il revient. C&rsquo;est un contre un avec Xia Li, elle est pr\u00eate.<\/p>\n\n\n\n<p>&#8211; Ted DiBiase arrive sur le ring pour le&nbsp;<strong>couronnement du nouveau champion Million Dollar<\/strong>. DiBiase dit qu&rsquo;il a enfin trouv\u00e9 quelqu&rsquo;un pour transporter son h\u00e9ritage. On voit une vid\u00e9o sur la carri\u00e8re de LA Knight et il arrive sur le ring. Knight dit qu&rsquo;il doit s&rsquo;adresser \u00e0 DiBiase. \u00c7a n&rsquo;arrive pas souvent qu&rsquo;on peut rencontrer nos h\u00e9ros et encore plus de partager le ring avec eux. Il ne sait m\u00eame pas comment d\u00e9crire ses sentiments lorsqu&rsquo;un h\u00e9ros lui donne son h\u00e9ritage. D&rsquo;\u00eatre ici avec DiBiase et le titre, toute la douleur du match \u00e0 TakeOver en valait la peine. Knight dit que DiBiase \u00e9tait toujours sur son \u00e9cran lorsqu&rsquo;il regardait le catch avec son p\u00e8re. Il veut exprimer sa gratitude et lui dire merci. C&rsquo;est le plus grand moment de sa carri\u00e8re et ce serait un honneur d&rsquo;\u00eatre couronn\u00e9.<\/p>\n\n\n\n<p>DiBiase dit que c&rsquo;est m\u00e9rit\u00e9 et il est heureux de le faire. DiBiase donne le titre Million Dollar Champion \u00e0 LA Knight sous les pyros. Les deux commencent \u00e0 rigoler. Knight dit qu&rsquo;il ne sait pas quoi dire. Il a tellement appris du Million Dollar Man et maintenant il a tout ce qu&rsquo;il veut. C&rsquo;est le moment d&rsquo;abandonner ce qu&rsquo;il n&rsquo;a pas de besoin. LA Knight frappe DiBiase en plein visage ! Knight repousse les agents de s\u00e9curit\u00e9 en bas du ring. Knight dit qu&rsquo;il est le seul vrai champion Million Dollar. Knight commence \u00e0 rouer de coups DiBiase. Cameron Grimes arrive sur le ring pour chasser LA Knight.<\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie est avec Raquel Gonzalez et Dakota Kai pour savoir pourquoi elles vont combattre ce soir apr\u00e8s TakeOver. Gonzalez dit qu&rsquo;elles n&rsquo;ont pas termin\u00e9 leur affaire, un titre ne lui suffit pas. Kai dit qu&rsquo;elles vont s&rsquo;occuper de Kacy et Carter pour ensuite devenir les nouvelles championnes.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; De retour, on voit une batterie qui charge.<\/p>\n\n\n\n<p><strong>Raquel Gonzalez et Dakota Kai vs Kacy Catanzaro et Kayden Carter<\/strong><\/p>\n\n\n\n<p>En fin de match, Catanzaro monte sur le coin, mais Kai se rel\u00e8ve et lui porte un coup de pied alors qu&rsquo;elle \u00e9tait distraite par Gonzalez qui a repouss\u00e9 Carter contre la barricade. Kai enchaine avec son GTK pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnantes : Raquel Gonzalez et Dakota Kai<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, on retrouve Ever-Rise. Ils sont furieux contre Hit Row qui ont attaqu\u00e9 leur maison en jouet. Chase Parker dit qu&rsquo;ils ont reconstruit leur maison. Si Hit Row revient, ils seront pr\u00eats \u00e0 r\u00e9pondre.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une vid\u00e9o de NXT TakeOver Great American Bash qui aura lieu mardi le 6 juillet.<\/p>\n\n\n\n<p>&#8211;&nbsp;<strong>Io Shirai<\/strong>&nbsp;arrive sur le ring et prend le micro pour son annonce. Shirai dit qu&rsquo;elle est de retour ! Elle se sent bien. Sa prochaine cible est&#8230; Shirai est coup\u00e9e par la musique de Candice LeRae qui arrive. LeRae dit que Shirai n&rsquo;est plus une championne imbattable, alors elle doit retourner la derni\u00e8re. Il faut gagner sa place ici. Mais une chose n&rsquo;a pas chang\u00e9, elle ne peut toujours pas endurer Shirai et elle a choisi le mauvais moment pour l&rsquo;arnaquer. Indi Hartwell arrive de l&rsquo;autre c\u00f4t\u00e9 pour frapper Shirai dans le dos ! LeRae et Hartwell enchainent les coups. Hartwell monte sur le coin, mais Zoey Stark arrive pour la frapper. Stark repousse les deux du ring avec l&rsquo;aide de Shirai.<\/p>\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une nouvelle vid\u00e9o sur&nbsp;<strong>Diamond Mine qui montre la mention \u00a0\u00bbouverture la semaine prochaine&rsquo;<\/strong>&lsquo;.<\/p>\n\n\n\n<p>&#8211; En coulisse, McKenzie demande \u00e0 WIlliam Regal et Samoa Joe leur commentaire sur la soir\u00e9e. Regal allait r\u00e9pondre, mais Johnny Gargano et Austin Theory arrivent en cirant le nom de Joe. Gargano dit que c&rsquo;est g\u00e9nial. L&rsquo;endroit avait besoin de Regal comme il a perdu le contr\u00f4le. Joe lui demande une faveur&#8230; de partir ! Pete Dunne arrive et regarde Samoa Joe sans rien dire.<\/p>\n\n\n\n<p><strong>Tommaso Ciampa et Timothy Thatcher vs Grizzled Young Veterans&nbsp;(Zack Gibson et James Drake)<\/strong><\/p>\n\n\n\n<p>En fin de match, Gibson et Thatcher enchainent une s\u00e9rie de renverses sur leur prise. Drake intervient avec un Drop Kick sur Thatcher. Ils font leur Back Stabber \u00e0 deux sur Thatcher pour le couvrir, mais Ciampa bloque le compte \u00e0 la derni\u00e8re seconde. Gibson am\u00e8ne Ciampa sur la table des commentateurs, mais Ciampa le renverse avec un Samoan Drop sur la table. Thatcher en profite pour frapper Drake. Ciampa fait son Fairy Tail Ending sur Drake. Ciampa et Thatcher enchainent avec une combinaison d&rsquo;Arm Bar et Ankle Lock pour le faire taper.<\/p>\n\n\n\n<p><em>Gagnants : Tommaso Ciampa et Timothy Thatcher<\/em><\/p>\n\n\n\n<p>&#8211; Dans le parking, on retrouve William Regal et Samoa Joe pour leur commentaire sur cette premi\u00e8re soir\u00e9e. Regal dit que c&rsquo;\u00e9tait bien diff\u00e9rent. Joe dit que c&rsquo;\u00e9tait une premi\u00e8re soir\u00e9e et d&rsquo;autres suivront. Les deux se serrent la main et Regal quitte en voiture.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/06\/15\/regardez-le-wwe-nxt-du-15-juin-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pour voir ce WWE NXT, cliquez ici<\/strong><\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce WWE NXT, cliquez ici WWE NXT, Capitol Wrestling Center, Orlando, Floride, 15 juin 2021! Les commentateurs sont Vic Joseph, Wade Barrett et Beth Phoenix. &#8211; Le WWE NXT poste In Your House d\u00e9bute avec une vid\u00e9o des \u00e9v\u00e9nements \u00e0 NXT TakeOver In Your House. Les commentateurs nous souhaitent ensuite la bienvenue et&nbsp;William&#8230;<\/p>\n","protected":false},"author":4,"featured_media":52907,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"ppma_author":[292],"class_list":["post-52906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=52906"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52906\/revisions"}],"predecessor-version":[{"id":52992,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52906\/revisions\/52992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/52907"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=52906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=52906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=52906"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=52906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}