{"id":52653,"date":"2021-06-11T21:21:23","date_gmt":"2021-06-11T21:21:23","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=52653"},"modified":"2021-06-14T14:28:39","modified_gmt":"2021-06-14T14:28:39","slug":"resultats-du-wwe-friday-night-smackdown-11-juin-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/06\/11\/resultats-du-wwe-friday-night-smackdown-11-juin-2021\/","title":{"rendered":"R\u00e9sultats et Vid\u00e9o du WWE Friday Night Smackdown, 11 Juin 2021!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.jdx.info\/lutte\/2021\/06\/11\/regardez-le-wwe-friday-night-smackdown-du-11-juin-2021\/\" target=\"_blank\"><strong>Pour voir ce Smackdown, cliquez ici<\/strong><\/a><\/li><\/ul>\n\n\n\n<p><strong>WWE SmackDown, ThunderDome, Tampa, Floride, 11 juin 2021<\/strong> <\/p>\n\n\n\n<p>Les commentateurs sont Michael Cole et Pat McAfee.<\/p>\n\n\n\n<p>&#8211; Le  WWE Friday Night SmackDown d\u00e9bute avec une vid\u00e9o sur ce qu&rsquo;il s&rsquo;est pass\u00e9 la semaine derni\u00e8re dans le main event. Dans les coulisses, Roman Reigns regardait la t\u00e9l\u00e9vision. Il dit \u00e0 Jey qu&rsquo;il les a sauv\u00e9s la semaine derni\u00e8re. Quelle est la seule chose qu&rsquo;il ne d\u00e9fendra pas ? Jey Uso r\u00e9pond le fait d&rsquo;humilier la famille. Reigns dit que Jey le comprend, mais pas son fr\u00e8re. La musique des Usos retentit et Jimmy fait son entr\u00e9e jusqu&rsquo;au ring, pendant que Reigns et Jey le regardent dans les coulisses.<\/p>\n\n\n\n<p>La semaine derni\u00e8re, c&rsquo;\u00e9tait cens\u00e9 \u00eatre une c\u00e9l\u00e9bration. Ce soir, ils \u00e9taient cens\u00e9s venir en tant que 7 fois champions par \u00e9quipe&#8230; mais non. Il n&rsquo;essaie pas de faire des excuses, il sort les faits. En premier, l&rsquo;arbitre n&rsquo;a pas vu que son \u00e9paule \u00e9tait relev\u00e9e. Mais ils ont eu une seconde chance. Mais<em>&nbsp;celui qui est au bout de la table<\/em>&nbsp;a mis le nez de leurs affaires. Il est venu et a attaqu\u00e9 Rey et Dominik Mysterio. Jimmy sait quel est le probl\u00e8me. Roman Reigns est jaloux du fait qu&rsquo;il soit de retour et qu&rsquo;il veuille que son fr\u00e8re soit avec lui. Il est jaloux qu&rsquo;ils veuillent repr\u00e9senter la famille et avoir l&rsquo;or, comme lui. Jimmy voit en lui. Reigns essaye de lui enlever Jey. Que Reigns l&rsquo;\u00e9coute : il promet qu&rsquo;il va faire quelque chose qu&rsquo;il ne regrettera pas.<\/p>\n\n\n\n<p>Roman Reigns dit \u00e0 Jey de s&rsquo;en occuper et ce dernier s&rsquo;en va.<\/p>\n\n\n\n<p>&#8211; Kevin Owens puis Big E font leur entr\u00e9e.<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Jimmy est rejoint par Jey et lui dit qu&rsquo;il est son fr\u00e8re, sa famille, son ami. Roman Reigns d\u00e9shonore la famille. Jey dit que Jimmy n&rsquo;\u00e9tait pas l\u00e0 pendant 1 an et il est loyal aupr\u00e8s du&nbsp;<em>Tribal Chief<\/em>. Alors quoi faire ? Jimmy r\u00e9pond que si Roman Reigns veut le voir, il sera dans son vestiaire.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p><strong>Kevin Owens et Big E vs Sami Zayn et Apollo Crews acc par Commander Azeez<\/strong><\/p>\n\n\n\n<p>En fin de match Sami Zayn rate son Helluva Kick sur Kevin Owens et ce dernier en profite pour lui faire un Stunner pour la victoire par tomb\u00e9.<\/p>\n\n\n\n<p><em>Gagnants : Kevin Owens et Big E<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le match, Apollo Crews prend un micro et demande \u00e0 Kevin Owens et Big E pourquoi ils c\u00e9l\u00e8brent. La seule raison pour laquelle ils ont gagn\u00e9, c&rsquo;est parce qu&rsquo;il \u00e9tait en \u00e9quipe avec Sami Zayn. Il les challenge pour la semaine prochaine : Kevin Owens &amp; Big E vs Apollo Crews &amp; Commander Azeez. Zayn monte sur le ring et Commander Azeez lui met un coup.<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Chad Gable va voir les Street Profits et s&rsquo;excuse pour Otis. Montez Ford r\u00e9pond que Gable ne peut pas contr\u00f4ler Otis, mais eux le peuvent. Gable leur dit qu&rsquo;ils ne savent pas quand s&rsquo;arr\u00eater et il le d\u00e9fie dans un match en un contre un. Otis ne viendra pas en ringside si Dawkins ne vient pas non plus.<\/p>\n\n\n\n<p>&#8211; Dans les coulisses, Roman Reigns est rejoint par Jey Uso et demande o\u00f9 est Jimmy. Jey r\u00e9pond que Jimmy l&rsquo;attend dans son vestiaire. Reigns lui dit de dire \u00e0 Jimmy qu&rsquo;il arrive.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Carmella vs Liv Morgan<\/strong><\/p>\n\n\n\n<p>En fin de match, Liv Morgan fait son ObLIVion sur Carmella pour la victoire par tomb\u00e9.<\/p>\n\n\n\n<p><em>Gagnante : Liv Morgan<\/em><\/p>\n\n\n\n<p>Apr\u00e8s le match, Carmella exige que l&rsquo;annonceur la surnomme comme \u00e9tant \u00ab\u00a0la plus belle femme \u00e0 la WWE\u00a0\u00bb, ce qu&rsquo;il fait.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/06\/11\/deuxieme-heure-de-smackdown-9\/\">Pour la suite de Smackdown, cliquez ici<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce Smackdown, cliquez ici WWE SmackDown, ThunderDome, Tampa, Floride, 11 juin 2021 Les commentateurs sont Michael Cole et Pat McAfee. &#8211; Le WWE Friday Night SmackDown d\u00e9bute avec une vid\u00e9o sur ce qu&rsquo;il s&rsquo;est pass\u00e9 la semaine derni\u00e8re dans le main event. Dans les coulisses, Roman Reigns regardait la t\u00e9l\u00e9vision. Il dit \u00e0&#8230;<\/p>\n","protected":false},"author":4,"featured_media":52655,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,36,23],"tags":[],"ppma_author":[292],"class_list":["post-52653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-resultats","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=52653"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52653\/revisions"}],"predecessor-version":[{"id":52735,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52653\/revisions\/52735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/52655"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=52653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=52653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=52653"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=52653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}