{"id":52434,"date":"2021-06-07T22:01:17","date_gmt":"2021-06-07T22:01:17","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=52434"},"modified":"2021-06-08T02:43:12","modified_gmt":"2021-06-08T02:43:12","slug":"deuxieme-heure-de-raw-6","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/06\/07\/deuxieme-heure-de-raw-6\/","title":{"rendered":"Deuxi\u00e8me Heure de RAW"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/06\/07\/resultats-du-wwe-monday-night-raw-7-juin-2021\/\"><strong>Pour revenir \u00e0 la premi\u00e8re heure de RAW, cliquez ici.<\/strong><\/a><\/li><\/ul>\n\n\n\n<p>&#8211; Drew McIntyre arrive sur le ring pour la&nbsp;<strong>signature de contrat de Hell in a Cell<\/strong>&nbsp;et on quitte pour une pause. De retour, Sonya Deville et Adam Pearce sont sur le ring avec McIntyre. Deville nous pr\u00e9sente le champion WWE, mais Bobby Lashley n&rsquo;arrive pas. McIntyre dit qu&rsquo;il va pr\u00e9dire ce qui va arriver. Lashley va venir avec son costard, MVP et ses femmes du train. Ils vont ensuite discuter du fait qu&rsquo;il obtient des chances encore et encore. McIntyre dit que c&rsquo;est le moment de battre Lashley \u00e0 Hell in a Cell et retrouver son titre. MVP appara\u00eet sur le TitanTron. MVP dit qu&rsquo;avant de signer, ils doivent discuter. Il s&rsquo;excuse pour le retard, mais ils arrivent. Lashley arrive sur le ring avec MVP et ses femmes. MVP dit qu&rsquo;il doit f\u00e9liciter McIntyre pour encore avoir manipul\u00e9 les choses pour avoir ce match.<\/p>\n\n\n\n<p>MVP demande s&rsquo;il sera encore menac\u00e9 d&rsquo;un 90 jours sans salaire. MVP demande \u00e0 Pearce comment il va remercier Lashley pour ses victoires. Lashley dit qu&rsquo;avec cette victoire \u00e0 Hell in a Cell,&nbsp;McIntyre n&rsquo;aura plus jamais de match contre lui pour le titre WWE. MVP dit que Lashley a bien h\u00e2te d&rsquo;amener le titre WWE devant les fans. McIntyre dit qu&rsquo;il accepte, mais il a besoin de quelque chose du champion.&nbsp;Il veut un match sans intervention qui peut changer la fin, il veut le match dans la Hell in a Cell. <\/p>\n\n\n\n<p>MVP dit que le champion accepte les termes. Pearce fait le changement sur le contrat et McIntyre signe. Lashley dit que McIntyre a oubli\u00e9 de dire que quand la r\u00e9alit\u00e9 il est impossible de le battre. McIntyre va partir sous la honte. Lashley signe le contrat. McIntyre dit qu&rsquo;il a \u00e9t\u00e9 dans la cage et Lashley non. Il n&rsquo;est pas sorti le m\u00eame homme en tombant du haut de la cage et il est pr\u00eat \u00e0 recommencer l&rsquo;exp\u00e9rience. Il va utiliser tous les objets et la cage pour retrouver son titre WWE. Ils vont se revoir en enfer. Lashley dit que lui aussi va le battre. McIntyre sort son \u00e9p\u00e9e et casse la table en deux avec pour intimider Lashley.<\/p>\n\n\n\n<p>&#8211; En coulisse, Sarah est avec Nikki Cross pour avoir ses commentaires. Cross dit que c&rsquo;est sa t\u00e9nacit\u00e9 qui fait d&rsquo;elle une championne, pas besoin d&rsquo;\u00eatre la plus belle et la plus forte. Sa seule chance \u00e9tait d&rsquo;essayer. Sarah lui demande si elle a trouv\u00e9 une partenaire. Cross dit que c&rsquo;est quelqu&rsquo;un qu&rsquo;elle admire depuis longtemps. Elle est heureuse qu&rsquo;Asuka a accept\u00e9.<\/p>\n\n\n\n<p>&#8211; Sheamus arrive sur le ring avec&nbsp;une protection au niveau du nez&nbsp;et prend place avec les commentateurs. Sheamus prend le micro et demande si on va parler de l&rsquo;injustice. Comment est-ce possible que quelqu&rsquo;un puisse avoir une chance apr\u00e8s l&rsquo;avoir fait saigner ? Si ce n&rsquo;\u00e9tait pas de l&rsquo;ordre du m\u00e9decin ce serait autrement. Carrillo et Ricochet menacent de sauter sur Sheamus pour se moquer.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Match pour l&rsquo;Aspirant au titre des USA <\/strong><\/p>\n\n\n\n<p><strong>Ricochet vs Humberto Carrillo<\/strong><\/p>\n\n\n\n<p>En fin de match, Ricochet et Carrillo s&rsquo;affrontent sur le tablier, Carrillo lui fait un Spanish Fly \u00e0 l&rsquo;ext\u00e9rieur du ring. L&rsquo;arbitre fait le compte et aucune des catcheurs ne remontent avant le dix.<\/p>\n\n\n\n<p><em>Double D\u00e9compte Ext\u00e9rieur<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Kofi Kingston et Xavier Woods discutent. MVP arrive disant qu&rsquo;il veut discuter avec Kofi. Kofi demande ce qu&rsquo;il veut. MVP dit qu&rsquo;il a \u00e9t\u00e9 impressionn\u00e9 par son match lundi dernier et ce soir. Mais il n&rsquo;est pas surpris de le voir perdre. MVP dit qu&rsquo;il repr\u00e9sente Lashley, mais il a \u00e9t\u00e9 un fan de Kofi pendant la KofiMania. Il a pleur\u00e9 en voyant Kofi remporter le grand match. Un champion en qui il pouvait \u00eatre fier. Est-ce que Kofi s&rsquo;est demand\u00e9 pourquoi la KofiMania s&rsquo;est termin\u00e9e ? Car il n&rsquo;est pas Bobby Lashley. \u00c0 la fin de son match contre McIntyre, Kofi a serr\u00e9 la main de McIntyre. Comme si Kofi est confortable de perdre. La KofiMania s&rsquo;est termin\u00e9e car Kofi l&rsquo;a arr\u00eat\u00e9. Kofi dit qu&rsquo;il n&rsquo;a pas besoin des conseils de MVP. Ses amis et sa famille lui donnent de la motivation. Pendant que Lashley le fait pour l&rsquo;argent. MVP dit que non, Lashley le fait pour la prestance.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; De retour, on pr\u00e9sente une nouvelle vid\u00e9o sur Eva Marie. Eva dit qu&rsquo;on a entendu son histoire, c&rsquo;est difficile d&rsquo;atteindre le succ\u00e8s. Maintenant c&rsquo;est le moment de montrer comment elle fait. Elle veut montrer un c\u00f4t\u00e9 \u00e0 la WWE Universe encore jamais vu.&nbsp;Eva-Lution arrive lundi prochain&nbsp;!<\/p>\n\n\n\n<p>&#8211; En coulisse, Mansoor s&rsquo;\u00e9chauffe et Mustafa Ali. Ali demande si Mansoor est pr\u00eat pour son match. Mansoor approuve. Ali dit que Mansoor le pense, mais il ne l&rsquo;est pas. Ali dit que Mansoor est pr\u00eat pour un combat juste contre Drew Gulak. Mais qu&rsquo;est-ce qu&rsquo;il va faire lorsque Gulak va lui mettre un doigt dans l&rsquo;oeil ou autre. Gulak va jouer avec lui et il doit \u00eatre pr\u00eat.<\/p>\n\n\n\n<p>&#8211; Avant le combat, en coulisse, Jeff Hardy dit qu&rsquo;il faut montrer du respect aux v\u00e9t\u00e9rans. Alexander se prom\u00e8ne comme si on lui doit tout. Ce soir il va lui montrer le respect.<\/p>\n\n\n\n<p><strong>Jeff Hardy vs Cedric Alexander<\/strong><\/p>\n\n\n\n<p>En fin de match, Alexander veut se moquer du saut de Jeff, mais Jeff bloque le saut et lui fait un Twist of Fate. Jeff enchaine avec son Swanton Bomb pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Jeff Hardy<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Rhea Ripley est avec Charlotte Flair. Charlotte dit que Ripley devrait suivre ses directives comme elle est la catcheuse avec le plus d&rsquo;exp\u00e9rience. Elle peut s&rsquo;amuser avec Cross pendant qu&rsquo;elle s&rsquo;occupe d&rsquo;Asuka. Ripley dit qu&rsquo;elle va suivre Charlotte en enfer dans deux semaines, mais ce soir c&rsquo;est Charlotte qui va la suivre.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/06\/07\/troisieme-heure-de-raw-7\/\">Pour la suite de RAW, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la premi\u00e8re heure de RAW, cliquez ici. &#8211; Drew McIntyre arrive sur le ring pour la&nbsp;signature de contrat de Hell in a Cell&nbsp;et on quitte pour une pause. De retour, Sonya Deville et Adam Pearce sont sur le ring avec McIntyre. Deville nous pr\u00e9sente le champion WWE, mais Bobby Lashley n&rsquo;arrive pas&#8230;.<\/p>\n","protected":false},"author":4,"featured_media":52439,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,1],"tags":[],"ppma_author":[292],"class_list":["post-52434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raw-wwe","category-uncategorized"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=52434"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52434\/revisions"}],"predecessor-version":[{"id":52477,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/52434\/revisions\/52477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/52439"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=52434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=52434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=52434"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=52434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}