{"id":51444,"date":"2021-05-21T13:35:00","date_gmt":"2021-05-21T13:35:00","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=51444"},"modified":"2021-05-21T21:47:01","modified_gmt":"2021-05-21T21:47:01","slug":"les-fans-de-retour-a-la-wwe-cest-officiel","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/05\/21\/les-fans-de-retour-a-la-wwe-cest-officiel\/","title":{"rendered":"Les Fans De Retour \u00e0 la WWE C&rsquo;est Officiel!"},"content":{"rendered":"\n<p>La WWE a annonc\u00e9 en ce vendredi qu&rsquo;elle sera de retour sur la route avec des fans \u00e0 partir du vendredi 16 juillet 2021 pour SmackDown, qui aura lieu \u00e0 Houston au Texas depuis le Toyota Center.<\/p>\n\n\n\n<p>Une tourn\u00e9e dans 25 villes jusqu&rsquo;au lundi 6 septembre 2021 pour RAW a \u00e9t\u00e9 annonc\u00e9. On attend des d\u00e9tails pour Smackdown. <\/p>\n\n\n\n<p>On sait aussi que le ppv Money in the Bank aura lieu le 18 juillet \u00e0 Fort Worth au Texas (Dickies Arena) et RAW le 19 juillet \u00e0 Dallas au Texas (American Airlines Center). <\/p>\n\n\n\n<p>Le reste de la tourn\u00e9e sera annonc\u00e9 pendant les prochaines semaines. D&rsquo;ailleurs, la vente de billets pour ces trois shows va commencer le 26 mai, alors pour l&rsquo;instant on ne connait pas le prix des billets ou la configuration de l&rsquo;ar\u00e9na.<\/p>\n\n\n\n<p>Le Texas permettant d\u00e9j\u00e0 les salles combles, l&rsquo;ambiance risque d&rsquo;\u00eatre \u00e9lectrisante! <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La WWE a annonc\u00e9 en ce vendredi qu&rsquo;elle sera de retour sur la route avec des fans \u00e0 partir du vendredi 16 juillet 2021 pour SmackDown, qui aura lieu \u00e0 Houston au Texas depuis le Toyota Center. Une tourn\u00e9e dans 25 villes jusqu&rsquo;au lundi 6 septembre 2021 pour RAW a \u00e9t\u00e9 annonc\u00e9. On attend des&#8230;<\/p>\n","protected":false},"author":4,"featured_media":51445,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,4,45,43,36,23],"tags":[],"ppma_author":[292],"class_list":["post-51444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-money-in-the-bank","category-news","category-ppv-wwe","category-raw-wwe","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/51444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=51444"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/51444\/revisions"}],"predecessor-version":[{"id":51446,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/51444\/revisions\/51446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/51445"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=51444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=51444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=51444"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=51444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}