{"id":49228,"date":"2021-04-16T16:04:37","date_gmt":"2021-04-16T16:04:37","guid":{"rendered":"https:\/\/www.jdx.info\/lutte\/?p=49228"},"modified":"2021-04-16T16:04:38","modified_gmt":"2021-04-16T16:04:38","slug":"randy-orton-sur-combien-il-a-paye-pour-que-sa-famille-assiste-a-wrestlemania-37","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/04\/16\/randy-orton-sur-combien-il-a-paye-pour-que-sa-famille-assiste-a-wrestlemania-37\/","title":{"rendered":"Randy Orton sur combien il a pay\u00e9 pour que sa famille assiste \u00e0 WrestleMania 37!"},"content":{"rendered":"\n<p>Randy Orton s&rsquo;est tourn\u00e9 vers Twitter apr\u00e8s avoir battu \u00abThe Fiend\u00bb Bray Wyatt lors du match d&rsquo;ouverture de WrestleMania 37 Night Two et a r\u00e9v\u00e9l\u00e9 le prix \u00e9lev\u00e9 pour amener sa famille \u00e0 la plus grande \u00e9tape de tous.<\/p>\n\n\n\n<p>Orton a not\u00e9 qu&rsquo;il avait \u00e9t\u00e9 factur\u00e9 20 000 $ pour amener sa femme et leurs 5 enfants au Raymond James Stadium pour le grand \u00e9v\u00e9nement.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Il a \u00e9crit: \u00abWM.&nbsp;Historique.&nbsp;Unique en son genre, seulement ici, \u00e0 #wwe, vous pouvez voir le spectacle!&nbsp;De plus, j&rsquo;ai \u00e9t\u00e9 factur\u00e9 20 mille dollars pour ma famille (femme et 5 enfants) pour regarder papa rassle combattre un d\u00e9mon\u2026.&nbsp;et GAGNEZ! \u00bb<\/p><\/blockquote>\n\n\n\n<p>Les co\u00fbts \u00e9lev\u00e9s des billets peuvent avoir quelque chose \u00e0 voir avec la limitation des billets compil\u00e9s et les protocoles COVID-19 peuvent avoir emp\u00each\u00e9 la famille d&rsquo;\u00eatre dans les coulisses.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Randy Orton s&rsquo;est tourn\u00e9 vers Twitter apr\u00e8s avoir battu \u00abThe Fiend\u00bb Bray Wyatt lors du match d&rsquo;ouverture de WrestleMania 37 Night Two et a r\u00e9v\u00e9l\u00e9 le prix \u00e9lev\u00e9 pour amener sa famille \u00e0 la plus grande \u00e9tape de tous. Orton a not\u00e9 qu&rsquo;il avait \u00e9t\u00e9 factur\u00e9 20 000 $ pour amener sa femme et leurs&#8230;<\/p>\n","protected":false},"author":665,"featured_media":49511,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1,42,23],"tags":[],"ppma_author":[289],"class_list":["post-49228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-uncategorized","category-wrestlemania","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/49228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=49228"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/49228\/revisions"}],"predecessor-version":[{"id":49513,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/49228\/revisions\/49513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/49511"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=49228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=49228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=49228"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=49228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}