{"id":47516,"date":"2021-03-17T15:35:37","date_gmt":"2021-03-17T15:35:37","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=47516"},"modified":"2021-03-17T15:36:17","modified_gmt":"2021-03-17T15:36:17","slug":"paul-wight-le-dernier-wwe-raw-que-jai-fait-etait-absolument-horrible","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/03\/17\/paul-wight-le-dernier-wwe-raw-que-jai-fait-etait-absolument-horrible\/","title":{"rendered":"Paul Wight: \u00ab\u00a0Le dernier WWE Raw que j&rsquo;ai fait \u00e9tait absolument horrible\u00a0\u00bb!"},"content":{"rendered":"\n<p>Paul Wight, anciennement connu sous le nom de The Big Show, a fait une apparition sur Talk Is Jericho pour discuter d&rsquo;un large \u00e9ventail de sujets.&nbsp;<\/p>\n\n\n\n<p>Au cours de celle-ci, il a parl\u00e9 de l&rsquo;\u00e9dition Legends Night de RAW plus t\u00f4t cette ann\u00e9e et souhaitait cr\u00e9er le Big Show Burger.&nbsp;Cet \u00e9pisode de RAW  a vu parler de lui par Randy Orton.&nbsp;Voici ce qu&rsquo;il avait \u00e0 dire :&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Le dernier Raw que j&rsquo;ai fait \u00e9tait absolument horrible.&nbsp;J&rsquo;\u00e9tais alors en train de n\u00e9gocier des contrats.&nbsp;Parfois, lorsque vous n\u00e9gociez un contrat avec eux, parfois, faute d&rsquo;un meilleur terme, ils rendront les choses un peu plus g\u00eanantes, difficiles, pour prouver un point.&nbsp;Cela fait partie de la psychologie du jeu.&nbsp;Ils voulaient que Randy Orton me fasse face sur une chaise, c&rsquo;est-\u00e0-dire qu&rsquo;il me frapperait au visage et me renverserait, puis je suis juste cens\u00e9 m&rsquo;asseoir dans le fauteuil et le prendre.&nbsp;Je suis comme, eh bien, il ne va pas me pousser sur le cul.&nbsp;Pas de manque de respect envers Randy, mais Randy sait qu&rsquo;il ne pourrait pas le faire si je ne le voulais pas.&nbsp;Pour faire quelque chose, oui, Randy peut mettre sa main sur ma poitrine et je vais m&rsquo;asseoir parce que je ne vais pas me battre contre Randy parce qu&rsquo;il essaie de rentrer dans ma t\u00eate.&nbsp;Vous pouvez toujours faire cette histoire m\u00eame si ce n&rsquo;est pas la bonne histoire \u00e0 raconter avec moi.&nbsp;Si Randy avait mis ses mains sur moi, s\u00e9rieusement, un g\u00e9ant aurait d\u00fb l&rsquo;assommer dans le couloir.&nbsp;Cela aurait \u00e9t\u00e9 une bonne affaire.&nbsp;Mais ensuite, pour aller sur le ring et s&rsquo;asseoir sur la rampe de la sc\u00e8ne avec Hogan, Flair et Booker et beaucoup de Hall Fame and Legends, ils essaient vraiment de me pousser dehors.&nbsp;<\/p><p>Ils veulent utiliser ma notori\u00e9t\u00e9 pour faire du travail communautaire et faire des m\u00e9dias \u00e0 l&rsquo;\u00e9tranger.&nbsp;Ils m&rsquo;enl\u00e8vent ma passion.&nbsp;Ils m&rsquo;ont enlev\u00e9 la lutte.&nbsp;Ensuite, pour m&rsquo;asseoir l\u00e0-bas sur la rampe et \u00eatre appel\u00e9 a \u00e9t\u00e9 pendant que je m&rsquo;assois l\u00e0 et regarde un match, vous parlez tellement de l\u00e9gendes et de respect pour les l\u00e9gendes et de respect pour le Temple de la renomm\u00e9e, mais \u00e0 chaque fois que les membres du Temple de la renomm\u00e9e sont l\u00e0, ils s&rsquo;enfoncent dans le sol.&nbsp;C&rsquo;est l&rsquo;une de ces choses o\u00f9 la machine avance toujours.&nbsp;Il s&rsquo;agit d&rsquo;aller de l&rsquo;avant et qu&rsquo;ils peuvent retirer de quelque pierre que ce soit, ils vont recevoir cette derni\u00e8re goutte jusqu&rsquo;\u00e0 ce qu&rsquo;il ne reste plus rien pour personne.&nbsp;Le talent n&rsquo;a plus rien.&nbsp;Les fans n&rsquo;ont plus rien pour eux.&nbsp;Pour moi, c&rsquo;\u00e9tait la cerise sur le g\u00e2teau o\u00f9 je devais recommencer.&nbsp;J&rsquo;ai d\u00fb me changer de nom.&nbsp;J&rsquo;ai essay\u00e9 de conclure quelques accords commerciaux avec la WWE et d&rsquo;utiliser ma propre marque et c&rsquo;\u00e9tait incroyable pour moi qu&rsquo;apr\u00e8s 20 ans de cr\u00e9ation d&rsquo;une marque parce qu&rsquo;ils d\u00e9tiennent la propri\u00e9t\u00e9 intellectuelle, je voulais faire un Big Show Burger.&nbsp;Cela aurait \u00e9t\u00e9 une galette d&rsquo;une demi-livre, sans antibiotiques, sans hormones, n&rsquo;importe o\u00f9 aux \u00c9tats-Unis en 36 heures.&nbsp;Vous commandez en ligne.&nbsp;C&rsquo;\u00e9tait humain et tout est fait correctement.&nbsp;Je suis all\u00e9 voir Vince et j&rsquo;ai dit que c&rsquo;\u00e9tait ce que je voulais faire.&nbsp;Je l&rsquo;ai mis en place.&nbsp;J&rsquo;avais Wolfgang Puck et nous allions faire un pain de viande ensemble pour le promouvoir comme une info publicit\u00e9 parlant de Big Show Burgers.&nbsp;<\/p><p>Vous auriez pens\u00e9 que j&rsquo;\u00e9tais un gars qui est sorti de la rue avec les chiffres qu&rsquo;ils m&rsquo;ont frapp\u00e9 pour utiliser une marque que j&rsquo;ai aid\u00e9 \u00e0 construire.&nbsp;Je veux dire, nous parlons de sept chiffres \u00e0 l&rsquo;avance.&nbsp;18 mois plus tard, une nouvelle tranche de sept chiffres.&nbsp;37% des b\u00e9n\u00e9fices.&nbsp;Ils voulaient que je crache sept chiffres d\u00e8s le d\u00e9part, puis sept mois plus tard, sept autres chiffres.&nbsp;Cela a tu\u00e9 toute l&rsquo;affaire pour moi.&nbsp;Mon truc \u00e9tait et c&rsquo;\u00e9tait avant Covid, mais je voulais acheter des food trucks, les emballer dans des camions Big Show Burger, puis comme \u00e0 WrestleMania Fan Axxess, j&rsquo;allais cuisiner des hamburgers et les vendre aux fans et aider \u00e0 promouvoir.&nbsp;Vous connaissez tout le truc.&nbsp;C&rsquo;est amusant d&rsquo;interagir avec les fans.&nbsp;C&rsquo;est amusant de la t\u00e9l\u00e9 et voici The Big Show Burger.&nbsp;Cela m&rsquo;a tellement d\u00e9courag\u00e9.&nbsp;Cela a mis les choses en perspective.&nbsp;Je joue au Big Show depuis 20 ans, mais,&nbsp;en ce qui les concerne, tout le monde peut jouer \u00e0 The Big Show, pas seulement Paul Wight, car ils le regardent comme un personnage de Marvel ou un personnage de Disney et ils en poss\u00e8dent la propri\u00e9t\u00e9 intellectuelle.&nbsp;Je pense aux prix qu&rsquo;ils me proposaient pour faire The Big Show Burger et je sais que j&rsquo;ai fait Honeycomb et j&rsquo;ai fait d&rsquo;autres choses au fil des ans qui n&rsquo;\u00e9taient m\u00eame pas de loin proches de ce genre de gain .&nbsp;J&rsquo;ai vu l&rsquo;\u00e9criture sur le mur.&nbsp;Donc, l&rsquo;\u00e9criture sur le mur \u00e9tait que nous ne voulons pas que vous fassiez cela, ou nous ne voulons pas que vous r\u00e9ussissiez, ou nous voyons ici une chance de faire une saisie d&rsquo;argent.&nbsp;L&rsquo;attitude \u00e9tait tr\u00e8s blas\u00e9e comme c&rsquo;est ce qu&rsquo;elle est.&nbsp;Ce n&rsquo;est pas grave parce que c&rsquo;est des affaires.&nbsp;Je comprends.&nbsp;Le probl\u00e8me \u00e9tait que je mettais des sentiments personnels et de la famille et tout ce qu&rsquo;ils disent, comme, vous \u00eates la famille et tout \u00e7a,&nbsp;mais en ce qui concerne les \u00e9crous et les boulons, c&rsquo;est la famille quand cela leur convient.&nbsp;Quand cela ne leur convient pas, ce sont les affaires.&nbsp;Donc, en r\u00e9alit\u00e9, ce n&rsquo;est que des affaires.&nbsp;Ce n&rsquo;est pas une chose n\u00e9gative.&nbsp;Je sais que les gens vont probablement penser que je suis foutu.&nbsp;Je ne le suis vraiment pas.&nbsp;Je dis juste qu&rsquo;il arrive un moment dans la vie d&rsquo;un talent o\u00f9 il faut faire ce qu&rsquo;il y a de mieux pour soi mentalement.&nbsp;Il ne s&rsquo;agit pas du dollar financier et de tout ce genre de choses.<\/p><\/blockquote>\n\n\n\n<p>Pour rappel, le Big Show est maintenant commentateur \u00e0 la AEW, et a fait son premier <a href=\"https:\/\/www.jdx.info\/lutte\/2021\/03\/16\/regardez-le-aew-darl-elevation-du-15-mars-2021\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s\u2019ouvre dans un nouvel onglet)\">DARK Elevation que vous pouvez regarder en cliquant ici.<\/a><\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Paul Wight, anciennement connu sous le nom de The Big Show, a fait une apparition sur Talk Is Jericho pour discuter d&rsquo;un large \u00e9ventail de sujets.&nbsp; Au cours de celle-ci, il a parl\u00e9 de l&rsquo;\u00e9dition Legends Night de RAW plus t\u00f4t cette ann\u00e9e et souhaitait cr\u00e9er le Big Show Burger.&nbsp;Cet \u00e9pisode de RAW a vu&#8230;<\/p>\n","protected":false},"author":665,"featured_media":47527,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,30,4],"tags":[],"ppma_author":[289],"class_list":["post-47516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-ex-wwe","category-news"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=47516"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47516\/revisions"}],"predecessor-version":[{"id":47529,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47516\/revisions\/47529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/47527"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=47516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=47516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=47516"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=47516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}