{"id":47389,"date":"2021-03-15T22:57:09","date_gmt":"2021-03-15T22:57:09","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=47389"},"modified":"2021-03-15T23:09:39","modified_gmt":"2021-03-15T23:09:39","slug":"resultats-du-wwe-monday-night-raw-15-mars-2021","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/03\/15\/resultats-du-wwe-monday-night-raw-15-mars-2021\/","title":{"rendered":"R\u00e9sultats du WWE Monday Night RAW, 15 Mars 2021"},"content":{"rendered":"\n<p><strong>WWE RAW St.  ThunderDome Petersburg, Floride, 15 mars 2021<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Tom Phillips, Byron Saxton et Samoa Joe.<\/p>\n\n\n\n<p>&#8211; Le WWE Monday Night RAW d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue. <\/p>\n\n\n\n<p>On annonce que\u00a0Bobby Lashley va d\u00e9fendre son titre WWE contre Drew McIntyre\u00a0\u00e0 WrestleMania 37. Bobby Lashley et MVP arrivent ensuite sur le ring.<\/p>\n\n\n\n<p>MVP dit qu&rsquo;ils ont une annonce officielle du Hurt Business. Des gens n&rsquo;ont pas compris la semaine derni\u00e8re il semble. Nous sommes dans l&rsquo;\u00e8re du Tout Puissant. Apr\u00e8s 16 ans de boulot, le directeur du Hurt Business a enfin eu une chance de remporter le titre WWE. Lashley dit qu&rsquo;il l&rsquo;a fait ! Il a prouv\u00e9 le contraire \u00e0 tous ceux qui ne l&rsquo;aiment pas. Il a d\u00e9truit Miz et il nous promet qu&rsquo;il va d\u00e9truire Drew McIntyre au main event de WrestleMania. Apr\u00e8s avoir d\u00e9truit McIntyre, il va d\u00e9truire tout le monde \u00e0 RAW et r\u00e9gner comme le meilleur. La musique du Miz commence et il arrive avec John Morrison. Miz dit qu&rsquo;il doit dire que son speech est remarquable. Miz dit qu&rsquo;il a \u00e9t\u00e9 si fier de partager le ring avec Lashley, ce fut un honneur. Mais il n&rsquo;a pas l&rsquo;impression que leur histoire est termin\u00e9e. Il faut penser \u00e0 Bret contre Shawn ou les autres. Alors on veut voir un Lashley contre Miz \u00e0 WrestleMania.<\/p>\n\n\n\n<p>Miz dit que Lashley doit se dire qu&rsquo;il a d\u00e9j\u00e0 eu sa chance, mais il est raisonnable. Il a d\u00e9fendu son titre deux fois en une soir\u00e9e. En plus il souffrait de crampes. Il n&rsquo;\u00e9tait pas \u00e0 100%. Est-ce que Lashley veut affronter le Miz \u00e0 son plein potentiel ? Le choix revient \u00e0 Lashley. La musique de Drew McIntyre commence et il arrive sur le ring. McIntyre dit qu&rsquo;il n&rsquo;a pas eu la chance de f\u00e9liciter Lashley. Ce fut un long parcours, 16 ans. Il conna\u00eet \u00e7a lui aussi avec 17 ans. Les deux ont un pass\u00e9 semblable qui ont travaill\u00e9 tr\u00e8s fort et les opportunit\u00e9s passaient devant eux. Soudainement ils ont perdu leur place \u00e0 la WWE et ils ont \u00e9t\u00e9 forc\u00e9 de travailler encore plus fort pour revenir. Il connait bien le sentiment de McIntyre. Par contre, il a remport\u00e9 le Royal Rumble et il a battu Brock Lesnar en cinq minutes. Alors que Lashley l&rsquo;a attaqu\u00e9 dans le dos. MVP dit que McIntyre devrait parler de Sheamus. McIntyre demande ce que fait MVP ici, Lashley peut parler par lui-m\u00eame. Lashley lui dit de pas de s&rsquo;inqui\u00e9ter des autres. Miz dit de ne pas l&rsquo;oublier.<\/p>\n\n\n\n<p>McIntyre dit qu&rsquo;il va donner une chance au Miz. Il va lui donner deux options. Il va finir la conversation et Miz peut soit l&rsquo;attaquer ou partir. McIntyre dit qu&rsquo;\u00e0 WrestleMania rien ne pourra \u00e9galiser leur clash physique. \u00c0 la fin il va sortir du Raymond James Stadium avec le titre et Lashley en pleurant. Miz dit \u00e0 McIntyre de se calmer un peu. Lashley en profite pour frapper McIntyre dans le dos qu&rsquo;il se retournait pour regarder Miz ! Lashley et MVP quittent le ring. Miz en profite pour rouer de coups McIntyre. Sheamus arrive sur la sc\u00e8ne et attaque Lashley ! Les officiels arrivent pour s\u00e9parer tout le monde.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, en coulisse, Sarah demande \u00e0 Sheamus pourquoi il a attaqu\u00e9 Lashley. Sheamus dit qu&rsquo;il veut battre Drew McIntyre, un McIntyre \u00e0 100%. Il ne veut pas que McIntyre puisse avoir des excuses pour leur match de dimanche. Ce soir il va montrer au monde entier qui il est et qu&rsquo;il peut battre Lashley, ce que McIntyre ne pourra pas faire \u00e0 WrestleMania.<\/p>\n\n\n\n<p><strong>Drew McIntyre vs The Miz\u00a0acc de John Morrison<\/strong><\/p>\n\n\n\n<p>En fin de match, McIntyre fait un DDT sur Miz et enchaine avec un Claymore Kick. McIntyre pointe le logo WrestleMania et applique un Hurt Lock sur Miz pour le faire taper.<\/p>\n\n\n\n<p><em>Gagnant : Drew McIntyre\u00a0<\/em><\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; Les commentateurs annoncent le\u00a0Grammy remport\u00e9 par Bad Bunny hier.<\/p>\n\n\n\n<p>&#8211; De retour, Braun Strowman est sur le ring et demande Shane McMahon. Shane arrive sur la sc\u00e8ne. Shane dit qu&rsquo;il ne comprend pas ce qu&rsquo;il arrive avec Strowman, chaque semaine il demande quelque chose. Strowman dit qu&rsquo;il a \u00e9t\u00e9 intimid\u00e9 toute sa vie par des gars comme Shane. Le probl\u00e8me est qu&rsquo;il ne vit pas dans un manoir ? Mais il demeure intelligent. Shane dit qu&rsquo;il n&rsquo;aurait jamais os\u00e9 se moquer d&rsquo;une autre personne. Strowman dit qu&rsquo;on sait tous que les McMahon ne s&rsquo;excusent pas. Shane est venu sur le ring car il avait peur. Shane demande ce que Strowman veut dire. Strowman dit que Shane n&rsquo;a pas les couilles de venir s&rsquo;adresser \u00e0 lui. Shane a peur de ce qu&rsquo;il peut faire. Il sait que Shane veut un match contre lui, mais il n&rsquo;a pas les couilles de le dire. Il veut affronter Shane ce soir ! <\/p>\n\n\n\n<p>Shane dit que Strowman ne peut pas rivaliser contre lui.\u00a0Maintenant il sait que Strowman est bien idiot. Il agit comme un idiot, parle comme un idiot. Une personne stupide fait des choses stupides. Le T-Rex n&rsquo;est plus ici car il ne pouvait pas s&rsquo;adapter. Strowman lui hurle de r\u00e9pondre \u00e0 son challenge. Shane dit qu&rsquo;il accepte\u00a0!<\/p>\n\n\n\n<p>&#8211; En coulisse, R-Truth est v\u00eatu comme Stone Cold et demande aux catcheuses de crier Hell Yeah. Mandy Rose dit que le jour 3:16 est demain, on est le 15 mars aujourd&rsquo;hui. Truth dit des \u00a0\u00bbwhat\u00a0\u00bb. Il dit que c&rsquo;est un mensonge car il le dit.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; De retour, Jax et Baszler sont avec les commentateurs pour le prochain combat.<\/p>\n\n\n\n<p><strong>Naomi et Lana vs Mandy Rose et Danna Brooke<\/strong><\/p>\n\n\n\n<p>En fin de match, Asuka arrive en ringside et commence \u00e0 se battre avec Baszler. Les officiels arrivent pour s\u00e9parer les deux. Rose en profite pour faire un Roll Up sur Lana, mais elle r\u00e9siste \u00e0 deux. Brooke prend la tag et surprend Lana avec un Neck Breaker pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnantes : Mandy Rose et Danna Brooke<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Riddle rejoint le New Day. Kofi Kingston dit que ce soir le New Day va retrouver sa place au top. Xavier Woods dit que Riddle peut aussi remporter son titre ce soir. Riddle dit qu&rsquo;ils vont tous manger des pancakes ensemble et ils auront des trottinettes \u00e0 leur effigie.<\/p>\n\n\n\n<p>&#8211; En coulisse, Riddle rejoint le New Day. Kofi Kingston dit que ce soir le New Day va retrouver sa place au top. Xavier Woods dit que Riddle peut aussi remporter son titre ce soir. Riddle dit qu&rsquo;ils vont tous manger des pancakes ensemble et ils auront des trottinettes \u00e0 leur effigie.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Championnat par \u00c9quipe de RAW<\/strong><\/p>\n\n\n\n<p><strong>New Day\u00a0(Kofi Kingston et Xavier Woods)\u00a0vs Shelton Benjamin et Cedric Alexander <\/strong>\u00a9<\/p>\n\n\n\n<p>En fin de match, Kofi fait son Trouble in Paradise sur Benjamin et donne la tag. Kofi se lance sur Alexander en bas du ring. Woods et Kofi font leur Daybreak pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : New Day<\/em><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/03\/15\/deuxieme-heure-de-raw-15-mars-2021\/\">Pour la suite de RAW, cliquez ici<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE RAW St. ThunderDome Petersburg, Floride, 15 mars 2021 Les commentateurs sont Tom Phillips, Byron Saxton et Samoa Joe. &#8211; Le WWE Monday Night RAW d\u00e9bute avec les commentateurs qui nous souhaitent la bienvenue. On annonce que\u00a0Bobby Lashley va d\u00e9fendre son titre WWE contre Drew McIntyre\u00a0\u00e0 WrestleMania 37. Bobby Lashley et MVP arrivent ensuite sur&#8230;<\/p>\n","protected":false},"author":4,"featured_media":47392,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,21,23],"tags":[],"ppma_author":[292],"class_list":["post-47389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=47389"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47389\/revisions"}],"predecessor-version":[{"id":47404,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47389\/revisions\/47404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/47392"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=47389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=47389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=47389"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=47389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}