{"id":47326,"date":"2021-03-15T14:16:49","date_gmt":"2021-03-15T14:16:49","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=47326"},"modified":"2021-03-15T14:16:52","modified_gmt":"2021-03-15T14:16:52","slug":"la-wwe-et-ses-superstars-implorent-les-fans-de-se-faire-vacciner-contre-le-covid-19","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/03\/15\/la-wwe-et-ses-superstars-implorent-les-fans-de-se-faire-vacciner-contre-le-covid-19\/","title":{"rendered":"La WWE et Ses Superstars Implorent les Fans de se Faire Vacciner Contre le COVID-19"},"content":{"rendered":"\n<p>Les superstars de la WWE appellent les fans \u00e0 se faire vacciner contre le COVID-19.<\/p>\n\n\n\n<p>Comme on le voit ci-dessous, la WWE a publi\u00e9 une nouvelle vid\u00e9o lors de SmackDown vendredi avec plusieurs Superstars encourageant les fans \u00e0 se faire vacciner contre le coronavirus quand ils le peuvent.&nbsp;Ils dirigent les fans vers GetVaccineAnswers.org pour plus d&rsquo;informations sur le vaccin.<\/p>\n\n\n\n<p>La vid\u00e9o pr\u00e9sente les commentaires de Daniel Bryan, Bianca Belair, Rey Mysterio et Montez Ford.<\/p>\n\n\n\n<p><strong>Daniel Bryan a ouvert la vid\u00e9o:<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abLe COVID-19 a chang\u00e9 notre mode de vie. La fa\u00e7on dont nous travaillons, la fa\u00e7on dont nous jouons, la fa\u00e7on dont nous vivons.\u00bb<\/p><\/blockquote>\n\n\n\n<p><strong> Belair a ajout\u00e9 :<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p> \u00ab\u00c0 l&rsquo;heure actuelle, les vaccins COVID-19 sont disponibles pour des millions d&rsquo;Am\u00e9ricains et bient\u00f4t ils seront disponibles pour tout le monde.\u00bb<\/p><\/blockquote>\n\n\n\n<p><strong>Mysterio poursuit:<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abRevenons \u00e0 nos vies et faisons-nous vacciner. Retroussez vos manches et faites votre part pour ceux que vous aimez.\u00bb<\/p><\/blockquote>\n\n\n\n<p>  Bryan et\u00a0Ford dans l&rsquo;ordre,ont termin\u00e9s la vid\u00e9o,  <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abC&rsquo;est notre coup\u00bb, <\/p><p>\u00ab\u00a0Et nous pouvons le faire ensemble.\u00a0\u00bb<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La WWE a \u00e9crit avec la vid\u00e9o : \u00abLe COVID-19 a chang\u00e9 notre mode de vie et avec les vaccins COVID-19 disponibles pour des millions et bient\u00f4t pour tout le monde, c&rsquo;est notre chance de retrousser nos manches et de faire notre part.\u00bb<\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-wrestling-headlines\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/wrestlingheadlines.com\/wwe-and-several-superstars-call-on-fans-to-get-the-covid-19-vaccine\/\n<\/div><\/figure>\n\n\n\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/vumFj_4vgLo\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Les superstars de la WWE appellent les fans \u00e0 se faire vacciner contre le COVID-19. Comme on le voit ci-dessous, la WWE a publi\u00e9 une nouvelle vid\u00e9o lors de SmackDown vendredi avec plusieurs Superstars encourageant les fans \u00e0 se faire vacciner contre le coronavirus quand ils le peuvent.&nbsp;Ils dirigent les fans vers GetVaccineAnswers.org pour plus&#8230;<\/p>\n","protected":false},"author":665,"featured_media":47368,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-47326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=47326"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47326\/revisions"}],"predecessor-version":[{"id":47369,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47326\/revisions\/47369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/47368"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=47326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=47326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=47326"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=47326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}