{"id":47231,"date":"2021-03-16T13:58:17","date_gmt":"2021-03-16T13:58:17","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=47231"},"modified":"2021-03-16T13:58:19","modified_gmt":"2021-03-16T13:58:19","slug":"mise-a-jour-sur-les-blessures-dasuka-son-statut-wrestlemania-37","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/03\/16\/mise-a-jour-sur-les-blessures-dasuka-son-statut-wrestlemania-37\/","title":{"rendered":"Mise \u00e0 jour sur les blessures d&rsquo;Asuka, son statut WrestleMania 37!"},"content":{"rendered":"\n<p>La Championne F\u00e9minine RAW Asuka est toujours hors de combat car elle aurait souffert d&rsquo;une commotion c\u00e9r\u00e9brale.<\/p>\n\n\n\n<p>Asuka a perdu une dent en prenant le coup de pied raide \u00e0 la bouche de la championne par \u00e9quipe f\u00e9minine de la WWE Shayna Baszler lors de l&rsquo;\u00e9mission RAW du 22 f\u00e9vrier, mais elle a \u00e9galement subi une commotion c\u00e9r\u00e9brale \u00e0 cet endroit, selon le Wrestling Observer Newsletter.<\/p>\n\n\n\n<p>On ne sait pas quand Asuka pourrait \u00eatre m\u00e9dicalement autoris\u00e9e \u00e0 concourir et il reste encore suffisamment de temps pour qu&rsquo;elle puisse travailler \u00e0 WrestleMania 37, mais ce n&rsquo;est pas acquis.<\/p>\n\n\n\n<p>La WWE a pr\u00e9vu que Charlotte Flair se batte pour le titre f\u00e9minin RAW \u00e0 WrestleMania, mais cela d\u00e9pendra de la sant\u00e9 d&rsquo;Asuka.&nbsp;C&rsquo;est la deuxi\u00e8me fois que le match WrestleMania 37 de Flair est mis en p\u00e9ril car ils l&rsquo;avaient initialement pr\u00e9vu de se quereller avec Lacey Evans, mais Evans est maintenant enceinte.<br><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La Championne F\u00e9minine RAW Asuka est toujours hors de combat car elle aurait souffert d&rsquo;une commotion c\u00e9r\u00e9brale. Asuka a perdu une dent en prenant le coup de pied raide \u00e0 la bouche de la championne par \u00e9quipe f\u00e9minine de la WWE Shayna Baszler lors de l&rsquo;\u00e9mission RAW du 22 f\u00e9vrier, mais elle a \u00e9galement subi&#8230;<\/p>\n","protected":false},"author":665,"featured_media":47435,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1,42,23],"tags":[],"ppma_author":[289],"class_list":["post-47231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-uncategorized","category-wrestlemania","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=47231"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47231\/revisions"}],"predecessor-version":[{"id":47436,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47231\/revisions\/47436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/47435"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=47231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=47231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=47231"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=47231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}