{"id":47130,"date":"2021-03-11T14:01:13","date_gmt":"2021-03-11T19:01:13","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=47130"},"modified":"2021-03-11T14:01:14","modified_gmt":"2021-03-11T19:01:14","slug":"shayna-baszler-sur-sa-difference-avec-le-stereotype-de-la-lutteuse-feminine","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/03\/11\/shayna-baszler-sur-sa-difference-avec-le-stereotype-de-la-lutteuse-feminine\/","title":{"rendered":"Shayna Baszler sur sa diff\u00e9rence avec le st\u00e9r\u00e9otype de la lutteuse f\u00e9minine!"},"content":{"rendered":"\n<p>La star de la WWE et actuelle championne du tag f\u00e9minin, Shayna Baszler, s&rsquo;est r\u00e9cemment entretenue avec&nbsp;<a href=\"https:\/\/www.arabianbusiness.com\/sport\/459597-wwe-superstar-shayna-baszler-smashing-stereotypes-into-submission\">Arabian Business<\/a>&nbsp;pour discuter d&rsquo;un certain nombre de sujets diff\u00e9rents, notamment du fait qu&rsquo;elle n&rsquo;a pas le look st\u00e9r\u00e9otyp\u00e9 d&rsquo;une lutteuse.&nbsp;Les faits saillants de l&rsquo;entrevue :<\/p>\n\n\n\n<p>Dit qu&rsquo;elle n&rsquo;a pas le look d&rsquo;une superstar f\u00e9minine typique de la WWE :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>C&rsquo;est fou d&rsquo;y penser encore, car je pense toujours que je ne suis qu&rsquo;un gamin du Midwest.&nbsp;Mais j&rsquo;ai eu, plus que les enfants r\u00e9els qui m&rsquo;ont arr\u00eat\u00e9, des gens m&rsquo;ont dit que leur fille, ou leur ni\u00e8ce ou jeune fille dans leur vie avait mentionn\u00e9 qu&rsquo;ils m&rsquo;aimaient.&nbsp;Je ne dis pas cela d&rsquo;une mani\u00e8re pour m&rsquo;insulter, mais je n&rsquo;ai pas le regard st\u00e9r\u00e9otyp\u00e9 de certaines des superstars f\u00e9minines, avec des photoshoots en bikini et un attrait sexuel \u00e0 cette fin.&nbsp;Je pense qu&rsquo;il y a beaucoup de jeunes filles qui voient \u00e7a et pensent que ce n&rsquo;est pas elles.&nbsp;C&rsquo;\u00e9tait moi, bien s\u00fbr, pas d&rsquo;une mani\u00e8re qui me d\u00e9rangeait, mais cela ne m&rsquo;identifiait tout simplement pas.<\/p><\/blockquote>\n\n\n\n<p>Comment il y a des filles plus jeunes qui l&rsquo;admirent pour sa diff\u00e9rence :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>On m&rsquo;a dit qu&rsquo;il y avait beaucoup de filles qui me regardaient et voyaient qu&rsquo;elle ne portait pas tout un tas de maquillage, elle ne faisait pas ces photoshoots, elle est comme moi.\u00a0M\u00eame parmi les filles qui regardent l&rsquo;exemple des lutteuses, je pense que je fais appel \u00e0 une niche encore plus vaine dans ce sens.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Je pense que c&rsquo;est une chose vraiment sp\u00e9ciale.\u00a0La lutte professionnelle occupe une place particuli\u00e8rement sp\u00e9ciale car elle est un divertissement.\u00a0J&rsquo;ai vraiment eu la chance d&rsquo;\u00eatre active \u00e0 cette \u00e9poque o\u00f9 les gens le regardent pour se divertir et ils le savent.\u00a0Prenons MMA d&rsquo;o\u00f9 je viens.\u00a0Il y aura beaucoup de gens qui vont simplement s&rsquo;\u00e9teindre, ils ne peuvent pas regarder les femmes se battre, c&rsquo;est inconfortable pour elles ou quelles que soient leurs id\u00e9es pr\u00e9con\u00e7ues sur les femmes qui se battent, elles ne peuvent tout simplement pas regarder et elles ne le feront pas.\u00a0M\u00eame aussi progressiste que les femmes dans les arts martiaux mixtes l&rsquo;ont \u00e9t\u00e9.\u00a0Mais je pense que dans le sens de la lutte professionnelle, ils peuvent regarder ceux-ci, qui sont des histoires de combats.\u00a0L\u00e0 o\u00f9 le MMA est le combat, la lutte professionnelle est l&rsquo;histoire du combat.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Je pense que les gens sont plus dispos\u00e9s \u00e0 regarder les femmes dans la lutte professionnelle parce que ce n&rsquo;est pas un combat en soi, donc ils peuvent le regarder pour son divertissement.\u00a0M\u00eame les faire regarder peut ouvrir des portes et commencer \u00e0 changer d&rsquo;avis sur les choses.\u00a0C&rsquo;est quelque chose dont je me souviens que Triple H nous a parl\u00e9, il s&rsquo;agit simplement d&rsquo;ouvrir la porte.\u00a0Certaines personnes n&rsquo;ouvriront m\u00eame pas la porte pour le v\u00e9rifier, peu importe ce que vous leur dites.\u00a0Mais si vous pouvez simplement ouvrir la porte et les laisser jeter un coup d&rsquo;\u0153il, alors ils commencent \u00e0 voir et ils veulent en voir plus et ils ouvriront la porte eux-m\u00eames.<\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La star de la WWE et actuelle championne du tag f\u00e9minin, Shayna Baszler, s&rsquo;est r\u00e9cemment entretenue avec&nbsp;Arabian Business&nbsp;pour discuter d&rsquo;un certain nombre de sujets diff\u00e9rents, notamment du fait qu&rsquo;elle n&rsquo;a pas le look st\u00e9r\u00e9otyp\u00e9 d&rsquo;une lutteuse.&nbsp;Les faits saillants de l&rsquo;entrevue : Dit qu&rsquo;elle n&rsquo;a pas le look d&rsquo;une superstar f\u00e9minine typique de la WWE :&#8230;<\/p>\n","protected":false},"author":665,"featured_media":47195,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1,23],"tags":[],"ppma_author":[289],"class_list":["post-47130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-uncategorized","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=47130"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47130\/revisions"}],"predecessor-version":[{"id":47196,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/47130\/revisions\/47196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/47195"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=47130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=47130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=47130"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=47130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}