{"id":46624,"date":"2021-03-03T14:14:38","date_gmt":"2021-03-03T19:14:38","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=46624"},"modified":"2021-03-03T14:14:41","modified_gmt":"2021-03-03T19:14:41","slug":"the-rock-dit-que-vince-mcmahon-etait-lun-de-ses-plus-grands-mentors-en-affaires-et-une-figure-paternelle","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/03\/03\/the-rock-dit-que-vince-mcmahon-etait-lun-de-ses-plus-grands-mentors-en-affaires-et-une-figure-paternelle\/","title":{"rendered":"The Rock dit que Vince McMahon \u00e9tait l&rsquo;un de ses plus grands mentors en affaires et une figure paternelle!"},"content":{"rendered":"\n<p>The Rock&nbsp;fait l&rsquo;\u00e9loge de Vince McMahon car il l&rsquo;a partag\u00e9 lors d&rsquo;une r\u00e9cente session de questions-r\u00e9ponses sur son compte Twitter.&nbsp;<\/p>\n\n\n\n<p>Au cours de l&rsquo;\u00e9pisode trois de \u00abYoung Rock\u00bb sur la NBA, l&rsquo;ancien champion de la WWE a r\u00e9pondu \u00e0 un fan en \u00e9crivant ce qui suit \u00e0 propos du pr\u00e9sident de la WWE :&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab@VinceMcMahon \u00e9tait l&rsquo;un de mes plus grands mentors en affaires et une figure paternelle.&nbsp;Pas toujours la relation que l&rsquo;on voudrait avec leur patron mais la convergence de nos vies l&rsquo;a fait.&nbsp;Nous rions quand nous nous r\u00e9unissons parce que nous reprenons toujours l\u00e0 o\u00f9 nous nous sommes arr\u00eat\u00e9s.&nbsp;#YoungRock. \u00bb<\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>The Rock&nbsp;fait l&rsquo;\u00e9loge de Vince McMahon car il l&rsquo;a partag\u00e9 lors d&rsquo;une r\u00e9cente session de questions-r\u00e9ponses sur son compte Twitter.&nbsp; Au cours de l&rsquo;\u00e9pisode trois de \u00abYoung Rock\u00bb sur la NBA, l&rsquo;ancien champion de la WWE a r\u00e9pondu \u00e0 un fan en \u00e9crivant ce qui suit \u00e0 propos du pr\u00e9sident de la WWE :&nbsp; \u00ab@VinceMcMahon&#8230;<\/p>\n","protected":false},"author":665,"featured_media":46648,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,1],"tags":[],"ppma_author":[289],"class_list":["post-46624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-uncategorized"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/46624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=46624"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/46624\/revisions"}],"predecessor-version":[{"id":46649,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/46624\/revisions\/46649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/46648"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=46624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=46624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=46624"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=46624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}