{"id":46611,"date":"2021-03-03T14:17:37","date_gmt":"2021-03-03T19:17:37","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=46611"},"modified":"2021-03-03T14:17:39","modified_gmt":"2021-03-03T19:17:39","slug":"the-miz-sur-son-segment-talking-smack-avec-daniel-bryan","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/03\/03\/the-miz-sur-son-segment-talking-smack-avec-daniel-bryan\/","title":{"rendered":"The Miz sur son segment Talking Smack avec Daniel Bryan!"},"content":{"rendered":"\n<p>Lors de son apparition dans les ORACLE Session, The Miz a parl\u00e9 du tristement c\u00e9l\u00e8bre segment Talking Smack avec Daniel Bryan qui a aid\u00e9 \u00e0 remettre sa carri\u00e8re sur les rails.\u00a0Voici ce qu&rsquo;il avait \u00e0 dire :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ce fut une mauvaise journ\u00e9e pour moi.\u00a0J&rsquo;avais le titre Intercontinental et je venais d&rsquo;\u00eatre rep\u00each\u00e9 \u00e0 SmackDown et ce soir-l\u00e0, je n&rsquo;\u00e9tais pas dans l&rsquo;\u00e9mission.\u00a0Je voulais vraiment faire le Championnat Intercontinental, comme je l&rsquo;ai dit, je voulais le rendre \u00e0 nouveau pertinent.\u00a0Je voulais le rendre aussi grand qu&rsquo;il l&rsquo;\u00e9tait quand je l&rsquo;ai vu dans les ann\u00e9es 80 avec l&rsquo;Ultimate Warrior l&rsquo;avoir, Shawn Michaels l&rsquo;avoir.\u00a0C&rsquo;\u00e9tait litt\u00e9ralement comme le titre de bourreau de travail et je voulais qu&rsquo;il revienne \u00e0 cela, puis vous entrez dans la t\u00e9l\u00e9vision et ils ont dit : Ah, ouais.\u00a0Vous n&rsquo;\u00eates pas n\u00e9cessaire.\u00a0Tu vas \u00eatre sur le match sombre ce soir.\u00a0Je pars, tu plaisantes, non?\u00a0J&rsquo;essaie de faire quelque chose ici et vous ne me permettez pas de le faire.\u00a0J&rsquo;\u00e9tais tellement en col\u00e8re que je suis all\u00e9 \u00e0 Road Dogg et j&rsquo;ai dit : \u00a0\u00bb Mettez-moi sur Talking Smack. \u00a0\u00bb\u00a0Il dit : Pourquoi?\u00a0Je dis : Daniel Bryan est le directeur g\u00e9n\u00e9ral et je vais tout d\u00e9cha\u00eener sur lui.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Alors, nous entrons dans Talking Smack et il m&rsquo;a trait\u00e9 de l\u00e2che.\u00a0Dans ma t\u00eate, je dis : \u00abCe type m&rsquo;appelle un l\u00e2che\u00bb et tout le monde est trait\u00e9 de l\u00e2che, mais quand Daniel Bryan m&rsquo;a appel\u00e9, c&rsquo;\u00e9tait diff\u00e9rent.\u00a0C&rsquo;\u00e9tait diff\u00e9rent de quand quelqu&rsquo;un sur une promo dit : \u00abVous \u00eates un l\u00e2che\u00bb.\u00a0Il y avait quelque chose en dessous.\u00a0Je savais ce que c&rsquo;\u00e9tait.\u00a0Je savais o\u00f9 il voulait en venir et cela me mettait en col\u00e8re parce que j&rsquo;\u00e9tais toujours capable de faire ce que je fais et lui ne l&rsquo;\u00e9tait pas.\u00a0Il n&rsquo;\u00e9tait plus l\u00e0.\u00a0La fa\u00e7on dont vous luttez et vous pouvez vous asseoir l\u00e0 et la d\u00e9tester comme je suis sur le ring, mais je vous garantis que je peux divertir un public.\u00a0Je n&rsquo;ai pas \u00e0 faire tous les trucs flippy, tous les trucs stupides qui te blessent parce que je vais \u00eatre l\u00e0 jour apr\u00e8s jour, chaque semaine et tu ne l&rsquo;es pas.\u00a0Cela m&rsquo;a fait penser \u00e0 tous ceux qui ne me comprennent tout simplement pas.\u00a0J&rsquo;essayais de faire comprendre aux gens pourquoi je fais les choses que je fais.\u00a0Et puis quand il est parti, c&rsquo;\u00e9tait presque comme, c&rsquo;\u00e9tait encore plus irrespectueux.\u00a0Si tu m&rsquo;avais frapp\u00e9, \u00e7a aurait \u00e9t\u00e9 mieux que lui de partir.\u00a0C&rsquo;\u00e9tait le gars qui \u00e9tait aim\u00e9 de tout le monde.\u00a0J&rsquo;\u00e9tais comme, pourquoi ne m&rsquo;aiment-ils pas?<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Je ne pense pas qu&rsquo;il essayait d&rsquo;\u00eatre m\u00e9chant.\u00a0Je pense qu&rsquo;il essayait juste de p\u00e9n\u00e9trer sous ma peau et il l&rsquo;a fait.\u00a0Il a tr\u00e8s bien r\u00e9ussi, puis \u00e7a a cr\u00e9\u00e9 tout un truc o\u00f9 j&rsquo;ai r\u00e9ussi \u00e0 rendre le titre Intercontinental pertinent \u00e0 nouveau, ce qui \u00e9tait g\u00e9nial.\u00a0Donc, parfois, vous avez juste besoin de ces moments et de ces opportunit\u00e9s et lorsque les choses ne se passent pas comme vous le souhaitez, trouvez des avenues.\u00a0Talking Smack n&rsquo;\u00e9tait rien avant de me lancer et m\u00eame Road Dogg me disait : \u00a0\u00bb Pourquoi voulez-vous \u00eatre sur Talking Smack? \u00a0\u00bb\u00a0Et je me suis dit : \u00a0\u00bb Si vous ne me donnez pas l&rsquo;opportunit\u00e9, je vais en cr\u00e9er une pour moi-m\u00eame. \u00a0\u00bb\u00a0Ce ne sont que les le\u00e7ons que je pense que beaucoup de superstars \u00e9mergentes doivent comprendre.\u00a0Si vous n&rsquo;\u00eates pas \u00e0 la t\u00e9l\u00e9vision, la WWE a de nombreuses avenues diff\u00e9rentes o\u00f9 vous pouvez mettre en valeur vos talents.<\/p><\/blockquote>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Lors de son apparition dans les ORACLE Session, The Miz a parl\u00e9 du tristement c\u00e9l\u00e8bre segment Talking Smack avec Daniel Bryan qui a aid\u00e9 \u00e0 remettre sa carri\u00e8re sur les rails.\u00a0Voici ce qu&rsquo;il avait \u00e0 dire : Ce fut une mauvaise journ\u00e9e pour moi.\u00a0J&rsquo;avais le titre Intercontinental et je venais d&rsquo;\u00eatre rep\u00each\u00e9 \u00e0 SmackDown et&#8230;<\/p>\n","protected":false},"author":665,"featured_media":46650,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,36,1,23],"tags":[],"ppma_author":[289],"class_list":["post-46611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-smackdown","category-uncategorized","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/46611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=46611"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/46611\/revisions"}],"predecessor-version":[{"id":46651,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/46611\/revisions\/46651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/46650"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=46611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=46611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=46611"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=46611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}