{"id":46359,"date":"2021-02-26T13:27:19","date_gmt":"2021-02-26T18:27:19","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=46359"},"modified":"2021-02-26T13:27:22","modified_gmt":"2021-02-26T18:27:22","slug":"ric-flair-ouvre-son-histoire-recente-avec-lacey-evans-et-charlotte","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/02\/26\/ric-flair-ouvre-son-histoire-recente-avec-lacey-evans-et-charlotte\/","title":{"rendered":"Ric Flair ouvre son histoire r\u00e9cente avec Lacey Evans et Charlotte!"},"content":{"rendered":"\n<p>Ric Flair a fait une apparition dans une r\u00e9cente \u00e9dition de Busted Open Radio pour discuter d&rsquo;un large \u00e9ventail de sujets.&nbsp;<\/p>\n\n\n\n<p>Pendant ce temps, il a parl\u00e9 du sc\u00e9nario de la WWE impliquant lui-m\u00eame, Charlotte et Lacey Evans et ce qu&rsquo;ils en pensaient.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00abCela nous a pris au d\u00e9pourvu.&nbsp;Il m&rsquo;a \u00e9t\u00e9 pr\u00e9sent\u00e9.&nbsp;Je pense que c&rsquo;\u00e9tait juste un essai et personne ne savait vraiment exactement ce qui allait se passer.&nbsp;Je m&rsquo;en voudrais si je pensais qu&rsquo;Ashley en \u00e9tait folle.&nbsp;Pour moi, je peux pratiquement r\u00e9aliser tout ce que je veux.&nbsp;Je suis vraiment dou\u00e9 pour faire les choses si j&rsquo;aime le programme et le comprends, mais en m\u00eame temps, il est difficile d&rsquo;\u00eatre dans un programme contre quelqu&rsquo;un de votre famille, en particulier votre fille quand tout le monde sait que vous \u00eates si pro et vous avez \u00e9t\u00e9 si positif envers elle en pensant et vous \u00eates si heureux de son succ\u00e8s.&nbsp;<\/p><p>Cela m&rsquo;a un peu pris au d\u00e9pourvu, mais, d&rsquo;un c\u00f4t\u00e9 de moi, je suis flatt\u00e9 qu&rsquo;ils m&rsquo;ont m\u00eame donn\u00e9 l&rsquo;occasion d&rsquo;\u00eatre \u00e0 la t\u00e9l\u00e9vision.&nbsp;Num\u00e9ro deux, \u00e7a a commenc\u00e9 un peu dur et je pense que \u00e7a s&rsquo;est adouci.&nbsp;Elle (Lacey Evans) est tomb\u00e9e enceinte.&nbsp;C&rsquo;est une belle fille.&nbsp;Je ne la connais pas tr\u00e8s bien, mais ce que je sais d&rsquo;elle, c&rsquo;est juste une personne vraiment gentille.&nbsp;J&rsquo;ai rencontr\u00e9 son mari.&nbsp;J&rsquo;ai rencontr\u00e9 sa fille qu&rsquo;ils avaient \u00e0 la t\u00e9l\u00e9vision un peu plus \u00e0 SmackDown, mais c&rsquo;est arriv\u00e9 et je suis s\u00fbr que nous \u00e9tions juste au point o\u00f9 nous allions vraiment faire fonctionner.&nbsp;J&rsquo;avais quelques id\u00e9es.&nbsp;Mon probl\u00e8me \u00e9tait qu&rsquo;ils ne me laisseraient pas monter sur le ring car il est si difficile de me faire virer \u00e0 cause de mes probl\u00e8mes de sant\u00e9, m\u00eame si mes m\u00e9decins m&rsquo;ont autoris\u00e9.&nbsp;Je ne pense pas qu&rsquo;ils soient pr\u00eats \u00e0 me laisser monter sur le ring au cas o\u00f9 quelque chose se passerait.&nbsp;Je pourrais avoir 40 sorties, mais,&nbsp;ce serait \u00e7a, pourquoi diable fais-tu \u00e7a?&nbsp;Pourquoi diable le laissez-vous faire \u00e7a?&nbsp;En fait, je voulais mettre des v\u00eatements de sueur et m&rsquo;entra\u00eener avec elle, ce qui, \u00e0 mon avis, aurait \u00e9t\u00e9 g\u00e9nial et lui apprendrait certaines choses et lui faisait imiter mon personnage, faisant les flips, suplex, se retournant, mendiant.&nbsp;<\/p><p>J&rsquo;avais tout \u00e9crit, mais ils ne m&rsquo;ont pas laiss\u00e9 monter sur le ring.&nbsp;J&rsquo;avais le plan directeur.&nbsp;Cela aurait \u00e9t\u00e9 amusant.&nbsp;Cela ne s&rsquo;est jamais concr\u00e9tis\u00e9 et je suis heureux que les choses se soient d\u00e9roul\u00e9es comme elles l&rsquo;ont fait, surtout pour elle parce que je pense qu&rsquo;elle \u00e9tait un peu boulevers\u00e9e, mais elle a ensuite dit :  H\u00e9, je vais avoir un b\u00e9b\u00e9.&nbsp;C&rsquo;est ce qui est cens\u00e9 arriver.&nbsp;Je suis jeune.&nbsp;J&rsquo;ai une belle fille et maintenant j&rsquo;en ai une deuxi\u00e8me en route.&nbsp;Tout le monde veut \u00eatre \u00e0 la t\u00e9l\u00e9vision, mais dans ce cas, si elle ne passe pas \u00e0 la t\u00e9l\u00e9vision pendant un certain temps, c&rsquo;est pour une tr\u00e8s belle raison dont nous sommes tous conscients.<\/p><\/blockquote>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ric Flair a fait une apparition dans une r\u00e9cente \u00e9dition de Busted Open Radio pour discuter d&rsquo;un large \u00e9ventail de sujets.&nbsp; Pendant ce temps, il a parl\u00e9 du sc\u00e9nario de la WWE impliquant lui-m\u00eame, Charlotte et Lacey Evans et ce qu&rsquo;ils en pensaient. \u00abCela nous a pris au d\u00e9pourvu.&nbsp;Il m&rsquo;a \u00e9t\u00e9 pr\u00e9sent\u00e9.&nbsp;Je pense que c&rsquo;\u00e9tait&#8230;<\/p>\n","protected":false},"author":665,"featured_media":46398,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,1,23],"tags":[],"ppma_author":[289],"class_list":["post-46359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-uncategorized","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/46359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=46359"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/46359\/revisions"}],"predecessor-version":[{"id":46399,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/46359\/revisions\/46399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/46398"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=46359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=46359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=46359"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=46359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}