{"id":44883,"date":"2021-02-04T03:28:39","date_gmt":"2021-02-04T08:28:39","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=44883"},"modified":"2021-02-04T03:28:42","modified_gmt":"2021-02-04T08:28:42","slug":"edge-dans-after-the-bell-il-parle-du-retour-de-christian-au-rumble","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/02\/04\/edge-dans-after-the-bell-il-parle-du-retour-de-christian-au-rumble\/","title":{"rendered":"Edge dans After The Bell, il parle du retour de Christian au Rumble!"},"content":{"rendered":"\n<p>Edge fera sa deuxi\u00e8me apparition sur le podcast After The Bell de la WWE aujourd&rsquo;hui.&nbsp;Edge discutera de sa carri\u00e8re, de la victoire du Royal Rumble, de WrestleMania 37 et plus encore.<\/p>\n\n\n\n<p>L&rsquo;animateur Corey Graves sera accompagn\u00e9 de \u00abl&rsquo;ami de l&rsquo;\u00e9mission\u00bb Vic Joseph pour l&rsquo;interview.<\/p>\n\n\n\n<p>Ce sera la deuxi\u00e8me apparition d&rsquo;Edge dans After The Bell, sa premi\u00e8re apparition \u00e9tant en avril 2020.<\/p>\n\n\n\n<p>Lors de son entretien avec CBS Sports, Edge a parl\u00e9 du retour de Christian au Royal Rumble.&nbsp;Voici ce qu&rsquo;il avait \u00e0 dire :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Le Rumble \u00e9tait l&rsquo;un de ces exemples o\u00f9, lorsque Christian descendait la rampe, j&rsquo;\u00e9tais si heureux pour lui.&nbsp;J&rsquo;\u00e9tais si fier de lui et fier du travail qu&rsquo;il a accompli et du travail et de la lutte pour \u00eatre d\u00e9gag\u00e9 et pouvoir recommencer.&nbsp;Comme moi, il peut y mettre fin \u00e0 ses conditions et pas simplement le faire enlever lorsque vous ne vous y attendez pas.&nbsp;C&rsquo;est une chose difficile \u00e0 avaler et maintenant nous avons une chance que ce ne soit pas le cas et c&rsquo;est vraiment sp\u00e9cial.<\/p><\/blockquote>\n\n\n<p><!--EndFragment--><br>\n<br>\n<\/p><p><\/p>","protected":false},"excerpt":{"rendered":"<p>Edge fera sa deuxi\u00e8me apparition sur le podcast After The Bell de la WWE aujourd&rsquo;hui.&nbsp;Edge discutera de sa carri\u00e8re, de la victoire du Royal Rumble, de WrestleMania 37 et plus encore. L&rsquo;animateur Corey Graves sera accompagn\u00e9 de \u00abl&rsquo;ami de l&rsquo;\u00e9mission\u00bb Vic Joseph pour l&rsquo;interview. Ce sera la deuxi\u00e8me apparition d&rsquo;Edge dans After The Bell, sa&#8230;<\/p>\n","protected":false},"author":665,"featured_media":44964,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,71,1,23],"tags":[],"ppma_author":[289],"class_list":["post-44883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-royal-rumble","category-uncategorized","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=44883"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44883\/revisions"}],"predecessor-version":[{"id":44965,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44883\/revisions\/44965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/44964"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=44883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=44883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=44883"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=44883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}