{"id":44873,"date":"2021-02-03T14:13:36","date_gmt":"2021-02-03T19:13:36","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=44873"},"modified":"2021-02-03T14:13:37","modified_gmt":"2021-02-03T19:13:37","slug":"lars-sulivan-explique-sa-fin-de-contrat-avec-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/02\/03\/lars-sulivan-explique-sa-fin-de-contrat-avec-la-wwe\/","title":{"rendered":"Lars Sulivan Explique Sa Fin de Contrat avec la WWE!"},"content":{"rendered":"\n<p>On apprenait mardi que\u00a0Lars Sullivan n&rsquo;est plus sous contrat avec la WWE\u00a0alors que la compagnie semble avoir d\u00e9cid\u00e9 de mettre un terme \u00e0 son aventure malgr\u00e9 que la compagnie n&rsquo;a fait aucune annonce officiel et que le profil du principal concern\u00e9 soit toujours sur le site de la WWE. <\/p>\n\n\n\n<p>Aujourd&rsquo;hui notre source a r\u00e9ussi de rejoindre Lars Sullivan pour avoir ses commentaires sur le sujet et on apprend que sa fin de contrat a \u00e9t\u00e9 fait avec compassion et honn\u00eatet\u00e9 alors qu&rsquo;il \u00e9tait toujours victime d&rsquo;anxi\u00e9t\u00e9 malgr\u00e9 l&rsquo;absence des fans dans le  ThunderDome. Il explique qu&rsquo;il avait des probl\u00e8mes \u00e0 manger et \u00e0 dormir lors des journ\u00e9es de shows ou \u00e0 l&rsquo;approche des shows.<\/p>\n\n\n\n<p>Sullivan se dit surpris que la WWE ne l&rsquo;a pas encore annonc\u00e9, mais il se consid\u00e8re responsable de tout alors qu&rsquo;il est son pire ennemi avec son anxi\u00e9t\u00e9 et ses actions idiotes. Pour ce qui est de son futur, Lars Sullivan dit que pour l&rsquo;instant sa carri\u00e8re  est termin\u00e9e.<\/p>\n\n\n\n<p>L&rsquo;anxi\u00e9t\u00e9 de Lars Sullivan lui aura co\u00fbt\u00e9 ch\u00e8re alors que ses d\u00e9buts dans le main roster avaient \u00e9t\u00e9 annul\u00e9, il avait rat\u00e9 un show tout r\u00e9cemment au ThunderDome et\u00a0il a \u00e9t\u00e9 sanctionn\u00e9\u00a0pour des commentaires racistes, homophobes et sexistes qu&rsquo;il avait d\u00e9clar\u00e9. La compagnie lui avait donn\u00e9 de nombreuses chances car croyait en lui pour devenir un top heel.<br><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>On apprenait mardi que\u00a0Lars Sullivan n&rsquo;est plus sous contrat avec la WWE\u00a0alors que la compagnie semble avoir d\u00e9cid\u00e9 de mettre un terme \u00e0 son aventure malgr\u00e9 que la compagnie n&rsquo;a fait aucune annonce officiel et que le profil du principal concern\u00e9 soit toujours sur le site de la WWE. Aujourd&rsquo;hui notre source a r\u00e9ussi de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":44874,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[292],"class_list":["post-44873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=44873"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44873\/revisions"}],"predecessor-version":[{"id":44875,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44873\/revisions\/44875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/44874"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=44873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=44873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=44873"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=44873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}