{"id":44810,"date":"2021-02-02T13:37:17","date_gmt":"2021-02-02T18:37:17","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=44810"},"modified":"2021-02-02T13:37:19","modified_gmt":"2021-02-02T18:37:19","slug":"plus-sur-le-retour-de-christian","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/02\/02\/plus-sur-le-retour-de-christian\/","title":{"rendered":"Plus Sur le Retour de Christian!"},"content":{"rendered":"\n<p>Cela faisait quelque temps qu&rsquo;on n&rsquo;avait pas vu Christian sur le ring, depuis l&rsquo;\u00e9t\u00e9 dernier. Si l&rsquo;on ne calcul pas son bref match face \u00e0 Randy Orton en juin 2020, dans lequel il a seulement re\u00e7u un Punt Kick, la derni\u00e8re rencontre de l&rsquo;ancien champion Intercontinental, ECW et d&rsquo;Impact Wrestling, remontait en 2014. <\/p>\n\n\n\n<p>Apr\u00e8s avoir subi une commotion c\u00e9r\u00e9brale, les d\u00e9s \u00e9taient jet\u00e9s :\u00a0<strong>la WWE ne voulait plus le revoir sur le ring<\/strong> question de s\u00e9curit\u00e9 mais aussi le fait que Vince McMahon ne l&rsquo;a jamais vraiment aim\u00e9.  Comme vous le savez lors du\u00a0Royal Rumble 2021 dimanche soir dernier, Christian est rentr\u00e9 \u00e0 la 24e place \u00e0 la grande surprise de tous.<\/p>\n\n\n\n<p>Apr\u00e8s l&rsquo;\u00e9v\u00e8nement, Christian a fait savoir qu&rsquo;il s&rsquo;\u00e9tait toujours promis un dernier match. On a maintenant davantage de d\u00e9tails \u00e0 ce sujet dans l&rsquo;entrevue que nous vous avons pass\u00e9 lundi. <\/p>\n\n\n\n<p>Nos source\u00a0nous informe que\u00a0Christian aurait \u00e9t\u00e9 autoris\u00e9, ce qui a \u00e9t\u00e9 gard\u00e9 tr\u00e8s secret, \u00e0 revenir sur le ring une semaine avant le Royal Rumble, apr\u00e8s avoir fait un voyage vers Pittsburgh. T\u00e8s peu de personnes avaient \u00e9t\u00e9 mises au courant.<\/p>\n\n\n\n<p>Il se dit que Christian travaillera en part-timer d\u00e8s maintenant. Malgr\u00e9 son absence lors de l&rsquo;\u00e9pisode de\u00a0RAW\u00a0qui a suivi le Royal Rumble, il devrait donc faire quelques apparitions \u00e0 l&rsquo;avenir. Il pourrait se rendre vers Smackdown pour le moment nous n&rsquo;avons pas plus de d\u00e9tails. <\/p>\n\n\n\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/www.jdx.info\/lutte\/2021\/02\/01\/lavenir-de-christian-a-la-wwe\/\"><strong>Pour la traduction de l&rsquo;entrevue d&rsquo;apr\u00e8s match de Christian, cliquez ici.<\/strong><\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Cela faisait quelque temps qu&rsquo;on n&rsquo;avait pas vu Christian sur le ring, depuis l&rsquo;\u00e9t\u00e9 dernier. Si l&rsquo;on ne calcul pas son bref match face \u00e0 Randy Orton en juin 2020, dans lequel il a seulement re\u00e7u un Punt Kick, la derni\u00e8re rencontre de l&rsquo;ancien champion Intercontinental, ECW et d&rsquo;Impact Wrestling, remontait en 2014. Apr\u00e8s avoir&#8230;<\/p>\n","protected":false},"author":4,"featured_media":44811,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[292],"class_list":["post-44810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=44810"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44810\/revisions"}],"predecessor-version":[{"id":44812,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44810\/revisions\/44812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/44811"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=44810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=44810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=44810"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=44810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}