{"id":44404,"date":"2021-01-29T15:16:04","date_gmt":"2021-01-29T20:16:04","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=44404"},"modified":"2021-01-29T15:16:07","modified_gmt":"2021-01-29T20:16:07","slug":"meiko-satomura-signe-avec-la-wwe-en-tant-que-coach-sur-nxt-uk","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/01\/29\/meiko-satomura-signe-avec-la-wwe-en-tant-que-coach-sur-nxt-uk\/","title":{"rendered":"Meiko Satomura signe avec la WWE en tant que coach sur NXT UK!"},"content":{"rendered":"\n<p>La star japonaise v\u00e9t\u00e9ran Meiko Satomura a sign\u00e9 un contrat avec la WWE.<\/p>\n\n\n\n<p>Il a \u00e9t\u00e9 rapport\u00e9 \u00e0 l&rsquo;automne que Satomura aurait sign\u00e9 pour travailler la marque WWE NXT UK en tant qu&rsquo;entra\u00eeneur et talent sur le ring.&nbsp;Maintenant,&nbsp;<a href=\"https:\/\/news.yahoo.co.jp\/articles\/ba6a9eac0958470945d5eecae99211f5215974b5\" rel=\"noreferrer noopener\" target=\"_blank\">Yahoo Japan<\/a>&nbsp;rapporte que la signature a \u00e9t\u00e9 confirm\u00e9e.<\/p>\n\n\n\n<p>Il a \u00e9t\u00e9 not\u00e9 que Satomura \u00e9tait \u00e0 Londres, en Angleterre depuis le 6 janvier. Elle s&rsquo;entra\u00eene au WWE UK Performance Center et se pr\u00e9pare apparemment \u00e0 ses d\u00e9buts sur le ring pour la marque.<\/p>\n\n\n\n<p>En ce qui concerne sa relation avec la Pro Wrestling de Sendai Girls, le rapport de Yahoo Japan indique que Satomura continuera \u00e0 \u00eatre la pr\u00e9sidente de la promotion et continuera \u00e0 travailler avec elles.&nbsp;Elle a aid\u00e9 \u00e0 cr\u00e9er la promotion avec Jinsei Shinzaki en 2006.<\/p>\n\n\n\n<p>Satomura, 41 ans, a fait ses d\u00e9buts \u00e0 la WWE en 2018 lors de la deuxi\u00e8me Mae Young Classic.&nbsp;Elle a remport\u00e9 des victoires sur Killer Kelly, Mercedes Martinez et Kayden Carter (Lacey Lane) avant d&rsquo;\u00eatre \u00e9limin\u00e9e en demi-finale par le vainqueur Toni Storm.<\/p>\n\n\n\n<p>Selon les rumeurs r\u00e9centes, Satomura serait la figure sombre avec Xia Li et Boa sur la principale marque NXT, mais il semble que ce ne soit pas possible car le rapport de Yahoo Japan indique qu&rsquo;elle est rest\u00e9e \u00e0 l&rsquo;\u00e9tranger.<\/p>\n\n\n\n<p>Restez \u00e0 l&rsquo;\u00e9coute pour en savoir plus sur la signature de Satomura avec la WWE.\u00a0L&rsquo;ancienne championne du monde PROGRESS continue de faire de la musculation et a r\u00e9cemment publi\u00e9 ces photos, qui ont \u00e9t\u00e9 \u00abaim\u00e9es\u00bb par la superstar de NXT UK Jinny  !<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La star japonaise v\u00e9t\u00e9ran Meiko Satomura a sign\u00e9 un contrat avec la WWE. Il a \u00e9t\u00e9 rapport\u00e9 \u00e0 l&rsquo;automne que Satomura aurait sign\u00e9 pour travailler la marque WWE NXT UK en tant qu&rsquo;entra\u00eeneur et talent sur le ring.&nbsp;Maintenant,&nbsp;Yahoo Japan&nbsp;rapporte que la signature a \u00e9t\u00e9 confirm\u00e9e. Il a \u00e9t\u00e9 not\u00e9 que Satomura \u00e9tait \u00e0 Londres, en&#8230;<\/p>\n","protected":false},"author":665,"featured_media":44466,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1,23],"tags":[],"ppma_author":[289],"class_list":["post-44404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-uncategorized","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=44404"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44404\/revisions"}],"predecessor-version":[{"id":44467,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44404\/revisions\/44467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/44466"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=44404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=44404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=44404"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=44404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}