{"id":44345,"date":"2021-01-27T17:27:28","date_gmt":"2021-01-27T22:27:28","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=44345"},"modified":"2021-01-27T17:27:31","modified_gmt":"2021-01-27T22:27:31","slug":"cest-lanniversaire-de-la-sortie-de-la-wwe-par-cm-punk","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2021\/01\/27\/cest-lanniversaire-de-la-sortie-de-la-wwe-par-cm-punk\/","title":{"rendered":"C&rsquo;est l&rsquo;Anniversaire de la Sortie de la WWE Par CM Punk!"},"content":{"rendered":"\n<p>Aujourd&rsquo;hui marque 7 ans depuis que CM Punk a quitt\u00e9 la WWE.<\/p>\n\n\n\n<p>L&rsquo;ancien champion de la WWE s&rsquo;est rendu sur Twitter cet apr\u00e8s-midi pour marquer l&rsquo;anniversaire.<\/p>\n\n\n\n<p>Il a \u00e9crit : \u00ab\u00a0[visage souriant avec emoji coeurs] joyeux anniversaire \u00e0 moi [visage souriant avec emoji coeurs]\u00a0\u00bb<\/p>\n\n\n\n<p>Il est int\u00e9ressant de noter que Punk est arriv\u00e9 l\u00e0 o\u00f9 seules les personnes qu&rsquo;il suit ou mentionn\u00e9es dans le tweet peuvent r\u00e9pondre.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Punk est sorti de l&rsquo;\u00e9pisode RAW du 27 janvier 2014 apr\u00e8s avoir dit \u00e0 Triple H et \u00e0 Vince McMahon qu&rsquo;il \u00abrentrait \u00e0 la maison\u00bb &#8211; un mouvement qui est venu apr\u00e8s que des probl\u00e8mes avec la soci\u00e9t\u00e9 se soient accumul\u00e9s.&nbsp;Son dernier match \u00e9tait le Match Royal Rumble Hommes 2014, o\u00f9 il est entr\u00e9 \u00e0 la premi\u00e8re place et a \u00e9t\u00e9 \u00e9limin\u00e9 \u00e0 la 27e place.&nbsp;Son dernier match en simple \u00e9tait une victoire sur le Hall of Famer de la WWE Billy Gunn lors de l&rsquo;\u00e9mission RAW du 20 janvier 2014.<\/p><\/blockquote>\n\n\n\n<p>Depuis qu&rsquo;il a quitt\u00e9 la WWE, Punk a jou\u00e9 dans quelques films et sign\u00e9 avec la UFC.\u00a0Il a une fiche de 0 victoires et 2 d\u00e9faites.\u00a0<\/p>\n\n\n\n<p>Punk a sign\u00e9 avec FOX Sports pour servir d&rsquo;h\u00f4te \u00e0 temps partiel de l&rsquo;\u00e9mission du studio WWE Backstage en novembre 2019, mais l&rsquo;\u00e9mission a \u00e9t\u00e9 annul\u00e9e en juin 2020 en raison de la pand\u00e9mie COVID-19.<\/p>\n\n\n\n<p>La photo est bien s\u00fbre tir\u00e9e de la storyline avec Vince MaMahon mais pour repr\u00e9sent\u00e9 l&rsquo;\u00e9v\u00e9nement elle semblait plus appropri\u00e9e.<\/p>\n\n\n\n<p>Restez \u00e0 l&rsquo;\u00e9coute pour plus de Punk.\u00a0<\/p>\n\n\n\n<center><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">&#x1f970;happy anniversary to me&#x1f970;<\/p>&mdash; player\/coach (@CMPunk) <a href=\"https:\/\/twitter.com\/CMPunk\/status\/1354464842346860547?ref_src=twsrc%5Etfw\">January 27, 2021<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/center>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui marque 7 ans depuis que CM Punk a quitt\u00e9 la WWE. L&rsquo;ancien champion de la WWE s&rsquo;est rendu sur Twitter cet apr\u00e8s-midi pour marquer l&rsquo;anniversaire. Il a \u00e9crit : \u00ab\u00a0[visage souriant avec emoji coeurs] joyeux anniversaire \u00e0 moi [visage souriant avec emoji coeurs]\u00a0\u00bb Il est int\u00e9ressant de noter que Punk est arriv\u00e9 l\u00e0 o\u00f9&#8230;<\/p>\n","protected":false},"author":665,"featured_media":44354,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,23],"tags":[],"ppma_author":[289],"class_list":["post-44345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=44345"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44345\/revisions"}],"predecessor-version":[{"id":44355,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/44345\/revisions\/44355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/44354"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=44345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=44345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=44345"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=44345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}