{"id":42158,"date":"2020-12-16T12:25:34","date_gmt":"2020-12-16T17:25:34","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=42158"},"modified":"2020-12-16T12:25:35","modified_gmt":"2020-12-16T17:25:35","slug":"la-wwe-veut-savoir-qui-est-sous-utilises-kevin-owens-cest-fait-refuser-plusieurs-partenaires-et-plus","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/12\/16\/la-wwe-veut-savoir-qui-est-sous-utilises-kevin-owens-cest-fait-refuser-plusieurs-partenaires-et-plus\/","title":{"rendered":"La WWE Veut Savoir Qui Est Sous Utilis\u00e9s! Kevin Owens C&rsquo;est Fait Refuser Plusieurs Partenaires, et Plus!"},"content":{"rendered":"\n<p>&#8211; C&rsquo;est connu, depuis presque toujours \u00e0 la WWE les fans se sont plaints que certains lutteurs occupaient un r\u00f4le en lowcard ou en midcard alors qu&rsquo;\u00e0 leurs yeux ils m\u00e9ritaient mieux. Ces derniers jours, la compagnie avoir montr\u00e9 la volont\u00e9 de faire une meilleure analyse de ses lutteurs dans cette situation.<\/p>\n\n\n\n<p>Selon\u00a0notre source, plusieurs booker auraient \u00e9t\u00e9 interrog\u00e9s sur les Superstars apparemment sous-utilis\u00e9es qui m\u00e9riteraient d&rsquo;avoir une chance plus haut sur la carte. Chacun aurait alors compos\u00e9 sa liste mais globalement les noms de Cesaro, Angel Garza, Chad Gable, Carmella et Peyton Royce seraient r\u00e9guli\u00e8rement ressortis.<\/p>\n\n\n\n<p>&#8211; En plus d&rsquo;avoir r\u00e9v\u00e9l\u00e9 qu&rsquo;il a failli affronter\u00a0Vince McMahon \u00e0 Wrestlemania 34, Kevin Owens n&rsquo;a pas h\u00e9sit\u00e9 \u00e0 faire d&rsquo;autres confessions au sujet de son utilisation \u00e0 la WWE. Le qu\u00e9b\u00e9cois a notamment donn\u00e9 la liste des Superstars avec qui il avait propos\u00e9 de faire \u00e9quipe.<\/p>\n\n\n\n<p>Si cela s&rsquo;est concr\u00e9tis\u00e9 avec Sami Zayn et Chris Jericho, trois autres lutteurs auraient pu \u00eatre \u00e0 ses c\u00f4t\u00e9s si la WWE avait accept\u00e9. Owens aurait ainsi pu \u00eatre associ\u00e9 \u00e0 AJ Styles, Mustafa Ali ou encore Apollo Crews. La compagnie a cependant refus\u00e9 ses propositions.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>&#8211; C&rsquo;est connu, depuis presque toujours \u00e0 la WWE les fans se sont plaints que certains lutteurs occupaient un r\u00f4le en lowcard ou en midcard alors qu&rsquo;\u00e0 leurs yeux ils m\u00e9ritaient mieux. Ces derniers jours, la compagnie avoir montr\u00e9 la volont\u00e9 de faire une meilleure analyse de ses lutteurs dans cette situation. Selon\u00a0notre source, plusieurs&#8230;<\/p>\n","protected":false},"author":4,"featured_media":42159,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,23],"tags":[],"ppma_author":[292],"class_list":["post-42158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/42158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=42158"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/42158\/revisions"}],"predecessor-version":[{"id":42160,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/42158\/revisions\/42160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/42159"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=42158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=42158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=42158"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=42158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}