{"id":41745,"date":"2020-12-07T21:52:47","date_gmt":"2020-12-08T02:52:47","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=41745"},"modified":"2020-12-07T22:00:24","modified_gmt":"2020-12-08T03:00:24","slug":"resultats-du-wwe-monday-night-raw-7-decembre-2020","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/12\/07\/resultats-du-wwe-monday-night-raw-7-decembre-2020\/","title":{"rendered":"R\u00e9sultats du WWE Monday Night RAW, 7 D\u00e9cembre 2020!"},"content":{"rendered":"\n<p><strong>WWE RAW Thunderdome Orlando, Floride, 7 d\u00e9cembre 2020<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Tom Phillips, Byron Saxton et Samoa Joe.<\/p>\n\n\n\n<p>&#8211; Le Monday Night RAW,d\u00e9bute avec les Superstars qui sont sur la sc\u00e8ne pour prendre une minute de silence en\u00a0m\u00e9moire de Pat Patterson. Les commentateurs nous souhaitent ensuite la bienvenue.<\/p>\n\n\n\n<p>&#8211; Randy Orton arrive sur le ring. On pr\u00e9sente une vid\u00e9o de son passage \u00e0 un \u00a0\u00bbMoment de Bliss\u00a0\u00bb\u00a0lundi dernier \u00e0 RAW. Orton dit qu&rsquo;il n&rsquo;est pas un homme ordinaire. Il n&rsquo;a pas besoin de porter un masque pour laisser sortir son c\u00f4t\u00e9 sombre au contraire du Fiend. Lorsque le moment arrivera, que son moment arrive, il va regarder le diable dans les yeux et lui dire que le pire fils de pute est \u00e0 la maison. Entre temps il va cogner \u00e0 la porte du Firefly Fun House, attendre et voir qui va le laisser entrer. <\/p>\n\n\n\n<p>On retrouve Bray Wyatt sur le TitanTron pour une \u00e9dition du Firefly Fun House. Wyatt dit qu&rsquo;Orton a \u00e9t\u00e9 m\u00e9chant lundi dernier, alors Alexa Bliss n&rsquo;est pas ici. Orton lui dit de ne pas jouer avec lui. Wyatt se transforme en pr\u00e9sentateur de jeux avec un quiz sp\u00e9cial Orton avec ses marionnettes. La premi\u00e8re question est comment Orton devrait \u00eatre puni \u00e0 WWE TLC. Personne ne trouve la bonne r\u00e9ponse. Wyatt dit que malheureusement pour Orton le Fiend a toujours la bonne r\u00e9ponse.\u00a0Orton dit que lui aussi va jouer. Il veut un combat ce soir, pas avec le Fiend car il va le voir \u00e0 TLC, il veut un combat contre Bray Wyatt. Wyatt est content et il accepte.<\/p>\n\n\n\n<p>&#8211; On annonce que Nia Jax et Shayna Baszler vont d\u00e9fendre les titres par \u00e9quipe contre Lana et Asuka \u00e0 WWE TLC.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, en coulisse, Nia et Shayna discutent Nia dit qu&rsquo;Asuka est dangereuse, mais Shayna est la reine de pique. Alors sa concentration est s\u00fbr d\u00e9molir Asuka ce soir. Ensuite elles vont s&rsquo;occuper de Lana, elle aura le pire visage de la plan\u00e8te. Son devant va ressembler \u00e0 son dos et le dos au-devant.<\/p>\n\n\n\n<p><strong>Asuka\u00a0acc de Lana\u00a0vs Shayna Baszler\u00a0acc de Nia Jax<\/strong><\/p>\n\n\n\n<p>En fin de match, Nia veut attaquer Lana en bas du ring, mais Lana la repousse contre la marche d&rsquo;acier et ensuite contre la table des commentateurs. Asuka en profite pour surprendre Baszler avec un Roll Up pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Asuka<\/em><\/p>\n\n\n\n<p>&#8211; De retour, en coulisse, Ricochet discute avec Dana Brooke. Riddle arrive avec sa boite de donuts alors qu&rsquo;il cherche MVP et Lashley. Il souhaite bonne chance aux deux pour leur combat mixte ce soir. Sarah arrive et lui demande pourquoi ils sont en \u00e9quipe ce soir. Ricochet dit que la force de RETRIBUTION est le nombre, alors ils ont d\u00e9cid\u00e9 de s&rsquo;unir. Brooke dit que la gifle sur Ali n&rsquo;a pas suffi. Ce soir c&rsquo;est pour le travail, elle ne va pas h\u00e9siter de frapper Ali encore une fois s&rsquo;il le faut.<\/p>\n\n\n\n<p>&#8211; De retour, les catcheurs arrivent. Avant le combat,  RETRIBUTION explique qu&rsquo;ils vont montrer que Ricochet et Brooke ont peur du changement. Ali dit qu&rsquo;ils vont faire face \u00e0 leur fin.<\/p>\n\n\n\n<p><strong>Mixed Tag Team Match<\/strong><br>Slapack et Reckoning\u00a0acc de Mustafa Ali\u00a0vs Ricochet et Dana Brooke<\/p>\n\n\n\n<p>En fin de match, Brooke fait son\u00a0Michinoku Driver sur Reckoning pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Ricochet et Dana Brooke<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Mustafa Ali est furieux par la d\u00e9faite de son \u00e9quipe.<\/p>\n\n\n\n<p>&#8211; En coulisse, Keith Lee rejoint Sheamus. Keith Lee dit que tout le monde sait qu&rsquo;il s&rsquo;agit d&rsquo;une question de temps avec que Sheamus trahis son ami Drew McIntyre. Sheamus dit qu&rsquo;il doit se pr\u00e9occuper de son match sinon il \u00e9craserait Lee.<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/12\/07\/deuxieme-heure-du-wwe-monday-night-raw-7-decembre-2020\/\">Pour la suite de RAW, cliquez ici.<\/a><\/strong><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>WWE RAW Thunderdome Orlando, Floride, 7 d\u00e9cembre 2020 Les commentateurs sont Tom Phillips, Byron Saxton et Samoa Joe. &#8211; Le Monday Night RAW,d\u00e9bute avec les Superstars qui sont sur la sc\u00e8ne pour prendre une minute de silence en\u00a0m\u00e9moire de Pat Patterson. Les commentateurs nous souhaitent ensuite la bienvenue. &#8211; Randy Orton arrive sur le ring&#8230;.<\/p>\n","protected":false},"author":4,"featured_media":41746,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,21,23],"tags":[],"ppma_author":[292],"class_list":["post-41745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-resultats","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/41745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=41745"}],"version-history":[{"count":4,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/41745\/revisions"}],"predecessor-version":[{"id":41753,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/41745\/revisions\/41753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/41746"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=41745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=41745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=41745"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=41745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}