{"id":40661,"date":"2020-11-17T16:07:18","date_gmt":"2020-11-17T21:07:18","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=40661"},"modified":"2020-11-17T16:07:23","modified_gmt":"2020-11-17T21:07:23","slug":"la-wwe-pourrait-retourner-au-performance-center","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/11\/17\/la-wwe-pourrait-retourner-au-performance-center\/","title":{"rendered":"La WWE Pourrait Retourner au Performance Center!"},"content":{"rendered":"\n<p>Cella fera bient\u00f4t faire 3 mois que la WWE est partie du Performance Center pour aller \u00e0  dans le Amway Center pour y installer son ThunderDome. Depuis, ce Performance Center est devenu le Capitol Wrestling Center pour NXT ainsi que 205 Live, et\u00a0la f\u00e9d\u00e9ration de Vince McMahon doit laisser l&rsquo;Amway Center libre d\u00e8s d\u00e9cembre. Retourner au PC pourrait \u00eatre l&rsquo;un des choix de la WWE.<\/p>\n\n\n\n<p>Notre source nous apprend que\u00a0la WWE garde la possibilit\u00e9 d&rsquo;organiser RAW et SmackDown au Capitol Wrestling Center.\u00a0Ce n&rsquo;est cependant pas le plan A et si c&rsquo;est le cas, ce sera pendant un court laps de temps, c&rsquo;est m\u00eame possible que ce soit pendant une seule semaine avant de partir. Une personne dans les coulisses a d\u00e9clar\u00e9 : \u00ab\u00a0<em>Si c&rsquo;est plus d&rsquo;une semaine, je serais tr\u00e8s surpris(e).<\/em>\u00ab\u00a0<\/p>\n\n\n\n<p>Une autre source nous informe que la WWE pourrait passez deux mois pour la saison morte de d\u00e9cembre au Royal Rumble, mais comme tout le monde seraient surpris pour plus d&rsquo;une semaine, il semble que ce plan-ci serait \u00e9cart\u00e9. <\/p>\n\n\n\n<p>Rappelons que la\u00a0WWE aurait \u00e9galement choisi le Tropicana Fields\u00a0de St-Petersburg en Floride pour l&rsquo;apr\u00e8s Amway Center. Pour le moment, la compagnie n&rsquo;a rien confirm\u00e9.<\/p>\n\n\n\n<p>Rassurez-vous le studio d&rsquo;enregistrement de la WWE a \u00e9t\u00e9 relook\u00e9. Ceux qui suivent NXT le savent pour les autres sachez qu&rsquo;ils ont transform\u00e9 le tout en un mini Thunderdome avec les lutteurs en formations autour du ring pour mettre l&rsquo;ambiance. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/Emqx7DSW8AABdKw.jpg\" alt=\"\"\/><\/figure>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Cella fera bient\u00f4t faire 3 mois que la WWE est partie du Performance Center pour aller \u00e0 dans le Amway Center pour y installer son ThunderDome. Depuis, ce Performance Center est devenu le Capitol Wrestling Center pour NXT ainsi que 205 Live, et\u00a0la f\u00e9d\u00e9ration de Vince McMahon doit laisser l&rsquo;Amway Center libre d\u00e8s d\u00e9cembre. Retourner&#8230;<\/p>\n","protected":false},"author":4,"featured_media":40662,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,36,23],"tags":[],"ppma_author":[292],"class_list":["post-40661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-smackdown","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/40661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=40661"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/40661\/revisions"}],"predecessor-version":[{"id":40663,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/40661\/revisions\/40663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/40662"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=40661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=40661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=40661"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=40661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}