{"id":39808,"date":"2020-11-02T22:00:42","date_gmt":"2020-11-03T03:00:42","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=39808"},"modified":"2020-11-03T02:34:19","modified_gmt":"2020-11-03T07:34:19","slug":"resultats-du-wwe-raw-2-novembre-2020-troisieme-heure","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/11\/02\/resultats-du-wwe-raw-2-novembre-2020-troisieme-heure\/","title":{"rendered":"R\u00e9sultats du WWE RAW 2 Novembre 2020! Troisi\u00e8me Heure!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/11\/02\/resultats-du-wwe-monday-night-raw-2-novembre-2020-deuxieme-heure\/\"><strong>Pour revenir \u00e0 la deuxi\u00e8me heure de RAW, cliquez ici.<\/strong><\/a><\/li><\/ul>\n\n\n\n<p>&#8211; &nbsp;le Hurt Business arrive sur le ring pour un VIP Lounge. <\/p>\n\n\n\n<p>MVP dit qu&rsquo;il a une annonce officielle du Hurt Business pour nous. C&rsquo;est normal de les voir dans le VIP Lounge, c&rsquo;est pour les meilleurs. Comme Survivor Series qui permet de battre les meilleurs. Cedric Alexander dit que si Sami Zayn reste champion Intercontinental il va d\u00e9couvrir que Lashley est le meilleur. Lashley dit qu&rsquo;il a entendu Zayn parler contre lui comme Zayn repr\u00e9sente beaucoup de pays et lui un seul. Lashley dit qu&rsquo;il a une seule chose \u00e0 dire, \u00e0 Survivor Series ce sera termin\u00e9 de parler et il va le faire dormir. MVP dit qu&rsquo;ils ont r\u00e9gl\u00e9 le probl\u00e8me RETRIBUTION, c&rsquo;est le moment de collecter le paiement de la WWE. Ils ont d\u00e9cid\u00e9 qu&rsquo;ils vont collecter le paiement sous la forme de l&rsquo;\u00e9quipe de RAW. Shelton Benjamin dit qu&rsquo;ils vont prouver qu&rsquo;ils sont meilleurs que New Day. <\/p>\n\n\n\n<p>Le New Day arrive sur la sc\u00e8ne. Xavier Woods dit qu&rsquo;il est un grand fan du champion des \u00c9tats-Unis, tellement qu&rsquo;il a eu des ennuis lorsqu&rsquo;il est rest\u00e9 debout pour le voir quand il avait 11 ans. Kofi Kingston dit que MVP le fait aussi depuis longtemps, mais il est bon au micro. Benjamin une grande acquisition de la WWE et Alexander aura une belle carri\u00e8re. Mais qui aussi le fait bien et si longtemps ? Qui ? C&rsquo;est nos gars le New Day. Kofi dit qu&rsquo;ils sont ici comme les champions par \u00e9quipe les plus d\u00e9cor\u00e9s de la WWE. Il a gagn\u00e9 plus de titres que tous les gars sur le ring. Il parle des titres par \u00e9quipe, titres des \u00c9tats-Unis, titres Intercontinental et le titre WWE. MVP dit qu&rsquo;il \u00e9tait bien fier de la victoire de Kofi, mais il a perdu en huit secondes contre Brock Lesnar. Il peut parier que Lashley peut le faire encore plus rapidement. Kofi dit qu&rsquo;il ne croyait pas que le Hurt Business allait blesser ses sentiments aussi. Le temps de huit secondes est bien, car selon Lana c&rsquo;est le temps pour lequel Lashley peut durer. MVP dit que c&rsquo;est \u00e7a le probl\u00e8me, le New Day aime les blagues et eux le business. Le New Day veut faire sourire les gens et eux la douleur. MVP dit que le New Day ne veut pas danser avec eux. Alexander et Benjamin ont bien h\u00e2te de leur prendre les titres. Woods dit que les seuls profits qui les inqui\u00e8tent sont les Street Profits comme ils vont les affronter \u00e0 Survivor Series.<\/p>\n\n\n\n<p>&#8211; De retour, le combat est d\u00e9but\u00e9 et MVP est avec les commentateurs.<\/p>\n\n\n\n<p><strong>Shelton Benjamin et Cedric Alexander vs New Day&nbsp;(Kofi Kingston et Xavier Woods)<\/strong><\/p>\n\n\n\n<p>En fin de match, Alexander prend la tag dans le dos et il surprend Woods avec un coup de pied. Benjamin enchaine avec son Pay Dirt et Alexander couvre Woods pour la victoire.<\/p>\n\n\n\n<p><em>Gagnants : Shelton Benjamin et Cedric Alexander<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Nikki Cross rejoint Alexa Bliss et lui demande pourquoi elle n&rsquo;a pas de r\u00e9ponse \u00e0 ses messages. Elle veut savoir ce qui arrive. Elle demande si le Fiend est responsable. Bliss ne dit rien et reste de dos. Cross dit que Bliss est plus forte que \u00e7a. Cross retourne Bliss, mais Bliss est en d\u00e9mon, Cross prend la fuite.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n\n<p> &#8211; De retour, Tucker est d\u00e9j\u00e0 sur le ring. Le combat commence et Mustafa Ali arrive en ringside. <\/p>\n\n\n\n<p><strong>Ricochet vs Tucker<\/strong><\/p>\n\n\n\n<p>  En moins de deux minutes, Ricochet fait son Recoil sur Tucker pour le couvrir pour la victoire!<\/p>\n\n\n\n<p><em>Gagnant : Ricochet<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, le reste de Retribution arrive pour encercler Ricochet. T-Bar lance Ricochet en bas du ring et Retribution attaque ensuite Tucker. Ricochet revient dans l&rsquo;action, mais Retribution l&rsquo;attaque encore.<\/p>\n\n\n\n<p>&#8211; En coulisse, Sheamus et Drew McIntyre discutent. Sheamus dit que McIntyre devrait \u00eatre dans l&rsquo;\u00e9quipe de Survivor Series et retrouver leur connexion Celtic. McIntyre dit qu&rsquo;il serait heureux de refaire \u00e9quipe avec lui, mais il ne peut pas. Il doit s&rsquo;occuper de Randy Orton. Sheamus dit qu&rsquo;il comprend, mais si McIntyre change d&rsquo;id\u00e9e il doit l&rsquo;aviser.<\/p>\n\n\n\n<p><strong>The Miz et John Morrison vs Drew McIntyre<\/strong><\/p>\n\n\n\n<p>En fin de match,&nbsp;McIntyre fait son Future Shock DDT sur Miz et se pr\u00e9pare pour son Claymore. Morrison d\u00e9cide de tirer Miz en bas du ring pour le sauver, mais McIntyre se lance en bas du ring sur les deux hommes. McIntyre ram\u00e8ne Miz sur le ring et lui fait son Claymore Kick pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Drew McIntyre<\/em><\/p>\n\n\n\n<p>Le show se termine avec une c\u00e9l\u00e9bration de McIntyre, mais Randy Orton arrive de nulle part et lui fait un RKO, mais on entend le Fiend rigoler.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/11\/02\/regardez-le-wwe-monday-night-raw-du-2-novembre-2020\/\"><strong>Pour voir ce RAW, cliquez ici.<\/strong><\/a><\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir \u00e0 la deuxi\u00e8me heure de RAW, cliquez ici. &#8211; &nbsp;le Hurt Business arrive sur le ring pour un VIP Lounge. MVP dit qu&rsquo;il a une annonce officielle du Hurt Business pour nous. C&rsquo;est normal de les voir dans le VIP Lounge, c&rsquo;est pour les meilleurs. Comme Survivor Series qui permet de battre les&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"ppma_author":[292],"class_list":["post-39808","post","type-post","status-publish","format-standard","hentry","category-raw-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/39808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=39808"}],"version-history":[{"count":11,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/39808\/revisions"}],"predecessor-version":[{"id":39834,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/39808\/revisions\/39834"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=39808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=39808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=39808"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=39808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}