{"id":39461,"date":"2020-10-28T16:49:14","date_gmt":"2020-10-28T20:49:14","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=39461"},"modified":"2020-10-28T16:49:18","modified_gmt":"2020-10-28T20:49:18","slug":"booker-t-dit-quil-a-adore-lhistoire-de-sasha-banks-et-bayley-a-hell-in-a-cell","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/10\/28\/booker-t-dit-quil-a-adore-lhistoire-de-sasha-banks-et-bayley-a-hell-in-a-cell\/","title":{"rendered":"Booker T dit qu&rsquo;il a ador\u00e9 l&rsquo;histoire de Sasha Banks et Bayley \u00e0 Hell in a Cell"},"content":{"rendered":"\n<p>Dans le dernier \u00e9pisode de son podcast Hall of Fame,  le lutteur l\u00e9gendaire Booker T a fait part de ses r\u00e9flexions sur le match pour le titre f\u00e9minin de SmackDown entre Sasha Banks et Bayley de Hell in a Cell dimanche dernier. Ce que l&rsquo;ancien cinq fois champion du monde avait \u00e0 dire :<\/p>\n\n\n\n<p>Comment Bayley est bonne dans tout et joue bien ses r\u00f4les :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Bayley n\u2019est peut-\u00eatre pas dou\u00e9e pour quoi que ce soit, mais elle est bonne pour tout. C\u2019est une travailleuse. Ce n\u2019est rien du tout &#8211; je n\u2019\u00e9tais pas dou\u00e9 pour quoi que ce soit, vraiment pas. Mais j&rsquo;\u00e9tais bon. J&rsquo;\u00e9tais bon dans tout ce que je savais faire et je savais aussi comment raconter une bonne histoire. C\u2019est ce que j\u2019entends par l\u00e0. Bayley ne pourra peut-\u00eatre pas aller l\u00e0-bas et faire un \u00ab\u00a0rana\u00a0\u00bb ou un moonsault et elle ne pourra peut-\u00eatre pas atterrir avec pr\u00e9cision sur le plongeon de la corde sup\u00e9rieure; c&rsquo;est ce que je veux dire. Elle peut aller l\u00e0-bas et faire les parties fonctionnelles de l&rsquo;entreprise de mani\u00e8re appropri\u00e9e. \u00c0 chaque fois, elle est exceptionnelle quand il s\u2019agit de tout faire correctement dans un match\u2026 Si j\u2019avais 10 Bayleys sur un roster, ce serait un sacr\u00e9 alignement parce que tout le monde conna\u00eetrait son r\u00f4le. C\u2019est comme quand elle jouait un r\u00f4le de babyface &#8211; elle devait aller l\u00e0-bas et faire son petit truc dans le coin l\u00e0-bas et que sais-je encore, et tout allait bien. Elle a travaill\u00e9 aussi loin qu&rsquo;elle pouvait avec, et boum, actionnant l&rsquo;interrupteur et tournant Heel.<\/p><\/blockquote>\n\n\n\n<p>Comment l&rsquo;histoire qu&rsquo;ils ont racont\u00e9e \u00e0 HIAC \u00e9tait parfaite :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Je suis d\u2019accord en ce qui concerne Bayley qui a tourn\u00e9e Heel. Au d\u00e9but, je ne pensais pas que c\u2019\u00e9tait quelque chose de si chaud. Je ne pensais pas que c&rsquo;\u00e9tait quelque chose qui allait s\u00e9duire les gens ou quelque chose comme \u00e7a. Plus elle le faisait, plus elle en sortait et le perfectionnait. Puis Sasha revenait, puis l&rsquo;angle des meilleurs amis. Vous pouviez voir quelque chose se pr\u00e9parer. Je pouvais sentir que quelque chose allait se passer  et c&rsquo;\u00e9tait parfait. Bayley qui c&rsquo;est retourn\u00e9e contre Sasha au lieu de Sasha contre Bayley. Nous avons une sacr\u00e9e heel \u00e0 Bayley, alors pourquoi tout g\u00e2cher? Bayley est pr\u00eate. Maintenant, Sasha revient avec une grosse victoire. Donc, pour moi, l&rsquo;histoire \u00e9tait parfaite pour \u00eatre racont\u00e9e \u00e0 l&rsquo;int\u00e9rieur de Hell in a Cell. Les femmes sont sorties et ont jou\u00e9 \u00e0 un tr\u00e8s tr\u00e8s haut niveau. Je donne \u00e0 Sasha des chiffres vraiment tr\u00e8s \u00e9lev\u00e9s en ce qui concerne son talent. J&rsquo;aurais tort de m&rsquo;asseoir ici et de dire que Sasha n&rsquo;\u00e9tait pas l&rsquo;une des meilleures femmes de l&rsquo;entreprise ni l&rsquo;une des meilleures femmes que l&rsquo;entreprise ait jamais eues parce qu&rsquo;elle est tr\u00e8s tr\u00e8s talentueuse. Beaucoup de femmes dans les vestiaires peuvent apprendre d&rsquo;elle, et ce n&rsquo;est pas non plus une blague. <\/p><\/blockquote>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Dans le dernier \u00e9pisode de son podcast Hall of Fame, le lutteur l\u00e9gendaire Booker T a fait part de ses r\u00e9flexions sur le match pour le titre f\u00e9minin de SmackDown entre Sasha Banks et Bayley de Hell in a Cell dimanche dernier. Ce que l&rsquo;ancien cinq fois champion du monde avait \u00e0 dire : Comment&#8230;<\/p>\n","protected":false},"author":665,"featured_media":39514,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-39461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/39461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=39461"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/39461\/revisions"}],"predecessor-version":[{"id":39515,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/39461\/revisions\/39515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/39514"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=39461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=39461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=39461"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=39461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}