{"id":38824,"date":"2020-10-19T11:52:18","date_gmt":"2020-10-19T15:52:18","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=38824"},"modified":"2020-10-19T11:52:21","modified_gmt":"2020-10-19T15:52:21","slug":"un-garde-du-corps-pour-aj-styles","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/10\/19\/un-garde-du-corps-pour-aj-styles\/","title":{"rendered":"Un Garde du Corps Pour Aj Styles ?"},"content":{"rendered":"\n<p> Alors que pendant longtemps \u00e0 RAW AJ Styles avait autour de lui Karl Anderson et Luke Gallows mais le leader du OC est maintenant seul au sein du show rouge apr\u00e8s un court s\u00e9jour \u00e0 Smackdown. <\/p>\n\n\n\n<p>Selon\u00a0<em>notre source<\/em>, l&rsquo;ancien champion Intercontinental pourrait prochainement se voir associer un autre lutteur pour le prot\u00e9ger et l&rsquo;aider durant ses matchs.<\/p>\n\n\n\n<p>Une id\u00e9e, il n&rsquo;est pas pr\u00e9cis\u00e9 son degr\u00e9 d&rsquo;avancement, voudrait ainsi que Styles se voit donner un garde du corps une peu comme  Shawn Michaels avait eut en la personne de Diesel ou The Brian Kendrick avec Ezequiel Jackson. <\/p>\n\n\n\n<p>Il se dit que ce pourrait \u00eatre le g\u00e9ant nig\u00e9rian Jordan Omogbehin, vu r\u00e9cemment comme le ninja forma g\u00e9ant d&rsquo;Akira Tozawa. C&rsquo;\u00e9tait \u00e9galement le portier de RAW Underground qui agissait pour Shawn McMahon.<\/p>\n\n\n\n<p>Bien sure, ce n&rsquo;est pas le genre de nouvelle que la WWE confirme \u00e0 l&rsquo;avance, il faudra donc attendre pour voir si le tout se concr\u00e9tisera. <\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Alors que pendant longtemps \u00e0 RAW AJ Styles avait autour de lui Karl Anderson et Luke Gallows mais le leader du OC est maintenant seul au sein du show rouge apr\u00e8s un court s\u00e9jour \u00e0 Smackdown. Selon\u00a0notre source, l&rsquo;ancien champion Intercontinental pourrait prochainement se voir associer un autre lutteur pour le prot\u00e9ger et l&rsquo;aider durant&#8230;<\/p>\n","protected":false},"author":4,"featured_media":38825,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[292],"class_list":["post-38824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/38824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=38824"}],"version-history":[{"count":1,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/38824\/revisions"}],"predecessor-version":[{"id":38826,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/38824\/revisions\/38826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/38825"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=38824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=38824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=38824"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=38824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}