{"id":37917,"date":"2020-10-05T14:28:41","date_gmt":"2020-10-05T18:28:41","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=37917"},"modified":"2020-10-05T14:28:46","modified_gmt":"2020-10-05T18:28:46","slug":"nia-jax-confirme-quelle-et-shayna-baszler-seront-a-la-wwe-raw-de-ce-soir","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/10\/05\/nia-jax-confirme-quelle-et-shayna-baszler-seront-a-la-wwe-raw-de-ce-soir\/","title":{"rendered":"Nia Jax confirme qu\u2019elle et Shayna Baszler seront \u00e0 la WWE Raw de ce soir!"},"content":{"rendered":"\n<p>La championne du tag f\u00e9minin de la WWE, Nia Jax, a publi\u00e9 une br\u00e8ve d\u00e9claration sur Twitter peu de temps apr\u00e8s l&rsquo;\u00e9mission sp\u00e9ciale NXT Takeover 31 de la nuit derni\u00e8re pour r\u00e9v\u00e9ler qu&rsquo;elle et Shayna Baszler appara\u00eetront dans l&rsquo;\u00e9pisode de Monday Night Raw de ce soir. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Jax \u00e9crit : \u00abDevinez qui sera sur #RAW demain soir, donnant des coups de pied \u00e0 ASH, conservant quelques titres, avec un nouveau tissage et un look DAMN GOOD! Je vais vous donner un indice\u2026 PAS mon partenaire par \u00e9quipe. Je veux dire, elle sera l\u00e0, mais elle n\u2019aura pas de nouveau tissage. \u00bb<\/p><\/blockquote>\n\n\n\n<p>Jax et Baszler ont \u00e9t\u00e9 absentes de la t\u00e9l\u00e9vision ces derni\u00e8res semaines en tant que protocole de s\u00e9curit\u00e9 pour l&rsquo;\u00e9pid\u00e9mie mineure de COVID-19 de la WWE. Elles devaient d\u00e9fendre leurs titres au Clash of Champions pay per view contre la Riott Squad avant de mettre leur match en quarantaine. <\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La championne du tag f\u00e9minin de la WWE, Nia Jax, a publi\u00e9 une br\u00e8ve d\u00e9claration sur Twitter peu de temps apr\u00e8s l&rsquo;\u00e9mission sp\u00e9ciale NXT Takeover 31 de la nuit derni\u00e8re pour r\u00e9v\u00e9ler qu&rsquo;elle et Shayna Baszler appara\u00eetront dans l&rsquo;\u00e9pisode de Monday Night Raw de ce soir. Jax \u00e9crit : \u00abDevinez qui sera sur #RAW demain&#8230;<\/p>\n","protected":false},"author":665,"featured_media":37953,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,43,23],"tags":[],"ppma_author":[289],"class_list":["post-37917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-raw-wwe","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/37917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=37917"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/37917\/revisions"}],"predecessor-version":[{"id":37954,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/37917\/revisions\/37954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/37953"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=37917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=37917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=37917"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=37917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}