{"id":36715,"date":"2020-09-16T21:59:27","date_gmt":"2020-09-17T01:59:27","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=36715"},"modified":"2020-09-16T22:09:33","modified_gmt":"2020-09-17T02:09:33","slug":"resultats-du-aew-dynamite-16-septembre-2020","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/09\/16\/resultats-du-aew-dynamite-16-septembre-2020\/","title":{"rendered":"R\u00e9sultats du AEW Dynamite, 16 Septembre 2020!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li> <a href=\"https:\/\/www.jdx.info\/lutte\/2020\/09\/16\/regardez-le-aew-dynamite-du-16-septembre-2020\/\"><strong>Pour voir ce AEW Dynamite, cliquez ici.<\/strong><\/a> <\/li><\/ul>\n\n\n\n<p><strong>AEW Dynamite Jacksonville, Floride, 16 septembre 2020<\/strong><\/p>\n\n\n\n<p>Les commentateurs sont Jim Ross, Tony Schiavone et Excalibur.<\/p>\n\n\n\n<p>-Le AEW Dynamite,d\u00e9bute avec les pyros et les commentateurs nous souhaitent la bienvenue.<\/p>\n\n\n\n<p>&#8211; Jurassic Express est d\u00e9j\u00e0 sur le ring, mais les Young Bucks arrivent et ils font un Superkick \u00e0 l&rsquo;arbitre pour ensuite partir ! Les Young Bucks vont voir Tony Khan dans le bureau des producteurs et lui lance de l&rsquo;argent pour payer l&rsquo;amende.<\/p>\n\n\n\n<p><strong>Jurassic Express\u00a0<em>(Luchasaurus et Jungle Boy) @ de Jungle Boy<\/em>\u00a0vs FTR\u00a0<em>(Dax Harwood et Cash Wheeler) @ de Tully Blanchard<\/em><\/strong><\/p>\n\n\n\n<p>En fin de match, Boy veut faire un Roll Up sur Harwood, mais Wheeler renverse le compte en sa faveur. Harwood compl\u00e8te le compte alors que Wheeler l&rsquo;aide \u00e0 maintenir le compte.<\/p>\n\n\n\n<p><em>Gagnants : FTR<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Alex Marvez rejoint Matt Hardy qui a \u00e9t\u00e9 attaqu\u00e9 alors que Private Party s&rsquo;occupe de Matt. Chris Jericho et Jake Harger arrivent pour voir comment il va. Jericho commence ensuite \u00e0 rigoler en lui sugg\u00e9rant de mettre de la glace.<\/p>\n\n\n\n<p>&#8211; De retour suite \u00e0 la pause, Kenny Omega est avec les commentateurs pour le prochain combat.<\/p>\n\n\n\n<p><strong>Frankie Kazarian vs Adam Hangman Page<\/strong><\/p>\n\n\n\n<p>En fin de match, Page se pr\u00e9pare pour sa Clothesline, mais Kazarian l&rsquo;\u00e9vite et le tire en bas du ring, mais Page le surprend avec une Clothesline contre la barricade. Page le monte sur le ring, les deux \u00e9changent quelques coups du tablier, mais Page r\u00e9ussi sa Springboard Clothesline pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Adam Hangman Page<\/em><\/p>\n\n\n\n<p>-Apr\u00e8s le combat, Omega quitte en coulisse sans donner ses commentaires.<\/p>\n\n\n\n<p><strong>MJF&nbsp;<em>accompagn\u00e9 de Wardlow<\/em>&nbsp;vs Shawn Dean<\/strong><\/p>\n\n\n\n<p>Le combat commence et MJF lui applique un Arm Bar pour le faire taper.<\/p>\n\n\n\n<p><em>Gagnant : MJF\u00a0<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, MJF prend le micro et dit qu&rsquo;on est tous d&rsquo;accord qu&rsquo;il est bien beau et que Jon Moxley a trich\u00e9. On n&rsquo;aime pas la v\u00e9rit\u00e9 car on ne peut pas y faire face. Moxley a trich\u00e9 et il devrait \u00eatre invaincu, il devrait \u00eatre le champion mondial AEW. Comme il est toujours invaincu comme Moxley a trich\u00e9 et qu&rsquo;il devrait \u00eatre le champion, on doit le nommer comme l&rsquo;invaincu et le champion non couronn\u00e9 de l&rsquo;AEW. MJF demande \u00e0 Justin Roberts de l&rsquo;annoncer ainsi. MJF dit qu&rsquo;il est clair qu&rsquo;il faut \u00eatre dans un groupe ou faction pour avoir sa place. On dirait qu&rsquo;\u00e0 chaque semaine qu&rsquo;il y a un nouveau groupe. Il se consid\u00e9rait comme un loup solitaire, mais c&rsquo;est peut-\u00eatre le temps que le loup retrouve une meute. M\u00eame s&rsquo;il reste seul ce n&rsquo;est pas important car \u00e0 la fin de la journ\u00e9e il restera toujours meilleur que nous et on le sait.<\/p>\n\n\n\n<p>&#8211; Le groupe d&rsquo;Eddie Kingston est sur le ring. Kingston dit qu&rsquo;il a trois points \u00e0 faire. Premi\u00e8rement, il n&rsquo;a jamais perdu le Battle Royal. Il devrait \u00eatre le grand gagnant. Deuxi\u00e8mement, ils font une famille. Ils ne sont pas un groupe ou une faction. Ils sont une famille de violence et de chaos. Kingston dit \u00e0 Butcher et Blade de trouver des victimes. Le groupe s&rsquo;amuse \u00e0 battre des catcheurs dans la foule. Kingston dit que tout le monde est pr\u00eat. Troisi\u00e8mement, c&rsquo;est le moment pour Blade de r\u00e9gler ses probl\u00e8mes \u00e0 la maison.<\/p>\n\n\n\n<p>&#8211; De retour, les catcheurs arrivent.<\/p>\n\n\n\n<p><strong>Private Party\u00a0<em>(Isiah Kassidy et Marq Quen)<\/em>\u00a0vs Chris Jericho et Jake Hager<\/strong><\/p>\n\n\n\n<p>En fin de match, Kassidy \u00e9vite le Judas Effect et le couvre rapidement, mais Jericho r\u00e9siste. Kassidy enchaine avec un Springboard Neck Breaker et le couvre, mais il r\u00e9siste encore. Jericho \u00e9vite le saut du coin de Kassidy et lui fait son Judas Effect pour le compte de trois alors que Quen \u00e9tait sonn\u00e9 en bas du ring apr\u00e8s un saut d&rsquo;Hager.<\/p>\n\n\n\n<p><em>Gagnants : Chris Jericho et Jake Hager<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Jericho s&rsquo;amuse \u00e0 attaquer Kassidy qui est d\u00e9j\u00e0 sonn\u00e9 et lui fait un Walls of Jericho, mais Quen intervient et le sort du ring avec un Springboard Kick.<\/p>\n\n\n\n<p>&#8211; De retour, les commentateurs annoncent que la semaine prochaine nous aurons un Six-Man Tag Team Match entre des \u00e9quipes form\u00e9es par Jon Moxley et Lance Archer.<\/p>\n\n\n\n<p><strong>Championnat F\u00e9minin NWA<\/strong><br>Iv\u00e9lisse<em>\u00a0accompagn\u00e9 de Dimante<\/em>\u00a0vs Thunder Rosa (c)<\/p>\n\n\n\n<p>En fin de match, Rosa bloque une charge d&rsquo;Ivelisse avec un coup de genou et poursuit  avec son Tombstone pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnante : Thunder Rosa<\/em><\/p>\n\n\n\n<p>&#8211; Apr\u00e8s le combat, Dimant\u00e9 d\u00e9cide d&rsquo;attaquer Rosa sur le ring pendant sa c\u00e9l\u00e9bration, mais Hikaru Shida arrive pour repousser Ivelisse et Diamante du ring.<\/p>\n\n\n\n<p>&#8211; On pr\u00e9sente des images sur les d\u00e9buts de Miro \u00e0 la AEW mercredi dernier. En coulisse, on voit que Kip Sabian et Miro s\u2019entra\u00eenent. Sabian dit que lorsqu&rsquo;ils auront sur le ring ils vont s&rsquo;imposer. Miro dit qu&rsquo;il est le meilleur homme, alors le meilleur offre le meilleur enterrement de vie de gar\u00e7on.<\/p>\n\n\n\n<p>&#8211; De retour, Lance Archer arrive avec Jake Roberts. Archer s&rsquo;amuse \u00e0 attaquer un catcheur dans la foule. Roberts dit qu&rsquo;ils ont maintenant besoin de partenaires pour le Six-Man Tag Team Match. Il est important de s&rsquo;allier avec le diable quand il le faut. Roberts demande \u00e0 Taz de venir le rejoindre. Taz arrive et dit qu&rsquo;ils sont heureux de faire des affaires avec eux. Ce sera un trio mortel de voir Starks et Cage avec l&rsquo;aspirant num\u00e9ro un. Mais ils ont un accord, lorsque Archer va d\u00e9truire Moxley il devra donner sa premi\u00e8re chance au titre \u00e0 Brian Cage. Roberts dit que c&rsquo;est exactement ce que tout le monde veut. Archer dit qu&rsquo;ils seront des amis pour la semaine prochaine, mais lorsqu&rsquo;il va vaincre Moxley l&rsquo;histoire sera diff\u00e9rente. Les faits d&rsquo;Eddie Kingston ne sont pas importants, nous aurons un clash de g\u00e9ants entre lui et Cage. Le champion Jon Moxley arrive dans la foule, mais il se fait attaquer par quelqu&rsquo;un dans la foule qui est Ricky Starks ! Brian Cage se joint \u00e0 l&rsquo;action pour battre Moxley avec Starks.<\/p>\n\n\n\n<p>Brian Cage se joint \u00e0 l&rsquo;action pour battre Moxley avec Starks. Will Hobbs arrive avec une chaise pour chasser Cage et Starks. Moxley annonce que ses partenaires pour la semaine prochaine seront Will Hobbs et Darby Allin ! Ils iront \u00e0 la guerre.<\/p>\n\n\n\n<p>&#8211; On annonce que Brodie Lee va d\u00e9fendre son titre TNT face \u00e0 Orange Cassidy la semaine prochaine. Aussi, Shida et Rose vont affronter Diamant\u00e9 et Ivelisse, et Chris Jericho va s&rsquo;adresser \u00e0 la foule.<\/p>\n\n\n\n<p>&#8211; De retour, les catcheurs arrivent dans le parking et le combat commence !<\/p>\n\n\n\n<p><strong>Parking Lot Fight<\/strong><br>Best Friends<em>\u00a0(Chuck Taylor et Trent)<\/em>\u00a0vs Santana et Ortiz<\/p>\n\n\n\n<p>En fin de match,Ortiz fait une Powerbomb \u00e0 Trent sur le toit d&rsquo;une voiture. Ortiz et Santana encha\u00eenent avec un  Powerbomb Crucifix \u00e0 deux sur Trent \u00e0 travers le pare-brise. Ensuite, Santana veut frapper Chuck avec un tuyau d&rsquo;acier, mais Orange Cassidy sort du coffre de la voiture et fait son Superman Punch avec une cha\u00eene ! Chuck fait un Pile Driver \u00e0 Santana sur une voiture et Trent avec un Pile Driver \u00e0 travers d&rsquo;une planche de bois \u00e0 Ortiz pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnants : Best Friends<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/09\/16\/regardez-le-aew-dynamite-du-16-septembre-2020\/\"><strong>Pour voir ce AEW Dynamite, cliquez ici.<\/strong><\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour voir ce AEW Dynamite, cliquez ici. AEW Dynamite Jacksonville, Floride, 16 septembre 2020 Les commentateurs sont Jim Ross, Tony Schiavone et Excalibur. -Le AEW Dynamite,d\u00e9bute avec les pyros et les commentateurs nous souhaitent la bienvenue. &#8211; Jurassic Express est d\u00e9j\u00e0 sur le ring, mais les Young Bucks arrivent et ils font un Superkick \u00e0&#8230;<\/p>\n","protected":false},"author":4,"featured_media":36717,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,24,50,4,21],"tags":[],"ppma_author":[292],"class_list":["post-36715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew","category-aew-impact-njpw-roh","category-dynamite","category-news","category-resultats"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/36715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=36715"}],"version-history":[{"count":3,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/36715\/revisions"}],"predecessor-version":[{"id":36726,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/36715\/revisions\/36726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/36717"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=36715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=36715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=36715"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=36715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}