{"id":36228,"date":"2020-09-09T03:02:33","date_gmt":"2020-09-09T07:02:33","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=36228"},"modified":"2020-09-09T03:02:37","modified_gmt":"2020-09-09T07:02:37","slug":"el-gringo-loco-conversation-sur-kamala","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/09\/09\/el-gringo-loco-conversation-sur-kamala\/","title":{"rendered":"El Gringo Loco &#8211; Conversation sur Kamala!"},"content":{"rendered":"\n<p>Tr\u00e8s peu de lutteurs ont autant d&rsquo;impact sur ma vie que Kamala. La premi\u00e8re fois que je l&rsquo;ai vu, j&rsquo;ai juste pens\u00e9, oh un autre lutteur sauvage. J&rsquo;avais d\u00e9j\u00e0 vu les Samoans sauvages, et quelques autres gadgets \u00absauvages\u00bb, donc ajouter Kamala au m\u00e9lange ne me choquait pas. Il a en quelque sorte coch\u00e9 toutes les cases: pieds nus, cochez; long b\u00e2ton \/ lance, v\u00e9rifiez; jupe \/ robe comme du tissu, v\u00e9rifier; bonus, il avait de la peinture pour le visage. Oui, en regardant Kamala comme un jeune gar\u00e7on, je pensais qu&rsquo;il \u00e9tait juste un autre monstre que mon h\u00e9ros peut \u00e9pingler. Puis il a fait quelque chose que je n&rsquo;ai jamais vu venir. \u00c7a me colle toujours quand je regarde en arri\u00e8re\u2026<\/p>\n\n\n\n<p>Jamais je n&rsquo;avais vu un grand homme sauter de la corde et \u00e9craser quelqu&rsquo;un. Ouais Jimmy Snuka a vol\u00e9 dans les airs, tout comme Randy Savage, mais Kamala pesait plus de 400 livres. Il bougeait comme aucun autre grand homme de cette \u00e9poque. Je croyais vraiment que c&rsquo;\u00e9tait un homme capable de battre Hulk Hogan. Juste ma chance, Kamala vs Hulk Hogan venait \u00e0 Los Angeles et les billets sont en vente! Alors j&rsquo;ai fait ce que tous les enfants font quand ils veulent quelque chose, j&rsquo;ai mis mon p\u00e8re sur \u00e9coute jusqu&rsquo;\u00e0 ce qu&rsquo;il dise oui. Ce n&rsquo;\u00e9tait pas une vente difficile. Mon parrain a promis d&rsquo;acheter les billets si mon p\u00e8re nous conduisait au LA Sports Arena (domicile de Wrestlemania 2 et 7).<\/p>\n\n\n\n<p>Mon tout premier \u00e9v\u00e9nement WWF, et j&rsquo;avais une vue magnifique sur le ring. Je me souviens tr\u00e8s peu de cette nuit maintenant, mais ce souvenir me reste. Quand il semblait que Kamala allait gagner, je me suis couvert les yeux. La pens\u00e9e que j&rsquo;\u00e9tais vivant dans la foule quand Hulk Hogan a perdu le titre m&rsquo;a fait peur. Je ne me souviens pas de la fin parce que je ne pouvais pas supporter de regarder. Ce n&rsquo;est que lorsque l&rsquo;annonceur a dit que c&rsquo;\u00e9tait une finition DQ que j&rsquo;ai ouvert les yeux. Je pouvais entendre la musique de Hulk Hogan jou\u00e9e et il \u00e9tait sur le point d\u2019\u00eatre. Mec, quelle nuit.<\/p>\n\n\n\n<p>James Harris<\/p>\n\n\n\n<p>James Harris, \u00e0 qui on a confi\u00e9 le r\u00f4le de Kamala, est malheureusement d\u00e9c\u00e9d\u00e9 il y a un mois. Harris a rejoint l&rsquo;une des plus de 180000 vies am\u00e9ricaines perdues \u00e0 cause du CoVID-19. Il souffrait de plusieurs probl\u00e8mes de sant\u00e9 et le virus a malheureusement port\u00e9 le coup final. Mais ce n\u2019est pas la fin dont les gens devraient parler, mais le travail de toute sa vie. Les lutteurs qui ont parl\u00e9 de Harris disent qu&rsquo;il \u00e9tait une personne tr\u00e8s douce, g\u00e9n\u00e9reuse et facile \u00e0 travailler. Bret Hart a dit que travailler avec lui \u00e9tait comme une nuit de cong\u00e9. Il n&rsquo;est pas surprenant que de nombreux lutteurs soient sortis et ont parl\u00e9 du Mighty Kamala. Tr\u00e8s peu de grands hommes bougeaient aussi vite ou pouvaient claquer Andr\u00e9 avec la facilit\u00e9 qu&rsquo;Harris pouvait. C&rsquo;\u00e9tait un talent tr\u00e8s sp\u00e9cial.<\/p>\n\n\n\n<p>Avant d&rsquo;arriver \u00e0 ce que j&rsquo;\u00e9tais, je veux aller dans cette chronique, je tiens \u00e0 dire que James Harris a prouv\u00e9 maintes et maintes fois pourquoi il \u00e9tait dans cet \u00e9v\u00e9nement principal. C&rsquo;\u00e9tait un grand homme qui pouvait bouger, sauter des grenouilles, claquer des g\u00e9ants et travailler si bien son gadget que les gens ne savaient pas si c&rsquo;\u00e9tait r\u00e9el ou non. J&rsquo;ai regard\u00e9 de nombreux matchs de Kamala, et je peux vous dire que sa capacit\u00e9 \u00e0 rester dans gimmick \u00e9tait l\u00e0-haut avec de nombreux grands. Harris m\u00e9ritait toute la renomm\u00e9e qu&rsquo;il avait re\u00e7ue, et il m\u00e9ritait plus d&rsquo;argent qu&rsquo;il n&rsquo;en gagnait. Kamala \u00e9tait divertissant, et j&rsquo;ai pass\u00e9 des heures dans le terrier de YouTube \u00e0 regarder ses matchs. Et c\u2019est \u00e0 cause du talent sp\u00e9cial de James Harris.<\/p>\n\n\n\n<p>Parlons-en<\/p>\n\n\n\n<p>Lorsque vous \u00e9coutez Harris, ses plaintes au sujet de la r\u00e9mun\u00e9ration n&rsquo;\u00e9taient pas uniquement li\u00e9es \u00e0 son exp\u00e9rience en tant qu&rsquo;homme noir. Harris a remis en question \u00e0 juste titre l&rsquo;\u00e9quit\u00e9 de l&rsquo;\u00e9chelle salariale entre les lutteurs noirs et les lutteurs blancs. En outre, les lutteurs noirs avaient une opportunit\u00e9 limit\u00e9e pour les places de l&rsquo;\u00e9v\u00e9nement principal en haut de la carte. Harris aurait sa chance en t\u00eate d&rsquo;affiche des matchs avec Hulk Hogan \u00e0 travers le pays. Mais tout revient toujours \u00e0 payer. Cela a conduit \u00e0 son d\u00e9part en 1987,<\/p>\n\n\n\n<p>En raison de son \u00e9poque, Harris aurait \u00e0 lutter contre de nombreux st\u00e9r\u00e9otypes raciaux, \u00e0 la fois sur le ring et \u00e0 l&rsquo;ext\u00e9rieur. Des r\u00e9compenses pour les lutteurs noirs \u00e0 un gadget profond\u00e9ment raciste, Harris a toujours r\u00e9ussi et s&rsquo;est fait un nom dans le monde de la lutte. Le gadget de Kamala est une partie du st\u00e9r\u00e9otype racial et une partie d&rsquo;un homme noir faisant une salade de poulet avec de la merde de poulet. A Memphis, Jerry Lawler voulait utiliser le grand homme. Voyant une image raciste, Lawler a eu l&rsquo;id\u00e9e de faire de Harris un sauvage, ce qui aiderait \u00e0 dissimuler \u00e0 quel point Harris \u00e9tait vert \u00e0 l&rsquo;\u00e9poque. Harris prendrait ce gadget et courrait avec, parcourant le monde.<\/p>\n\n\n\n<p>Le divertissement \u00e9tait diff\u00e9rent dans les ann\u00e9es 80<\/p>\n\n\n\n<p>Comme les Samoans sauvages, Kamala est venu ne pas parler anglais et est toujours coinc\u00e9 dans leurs habitudes. Maintenant, quiconque a immigr\u00e9 dans ce pays vous le dira, vous finirez par apprendre l&rsquo;anglais. Je vous garantis que Charlotte Flair n\u2019apprend pas l\u2019espagnol pour parler avec Andrade. Elle a peut-\u00eatre appris quelques mots, mais aux \u00c9tats-Unis, vous parlez anglais. Au lieu de montrer sa croissance, le personnage de Kamala est rest\u00e9 un personnage pendant de tr\u00e8s nombreuses ann\u00e9es. Et c&rsquo;\u00e9tait juste, accept\u00e9. Le WWF a fait un peu de d\u00e9veloppement du personnage en 1993 pendant le bref tour de visage de Kamala. Pens\u00e9 en revoyant les matchs, il est surprenant de voir Kamala oublier comment terminer un match. Mais voir la foule interagir avec Kamala \u00e9tait tr\u00e8s en phase avec le divertissement \u00e0 l&rsquo;\u00e8re de Home Alone et Hocus Pocus.<\/p>\n\n\n\n<p>Aujourd&rsquo;hui, un gadget comme Kamala ne volerait pas. Dans les ann\u00e9es 80, vous saviez simplement que le divertissement avait un certain niveau de racisme. Et peut-\u00eatre que certains d&rsquo;entre vous veulent revenir \u00e0 cette \u00e9poque; Personnellement, je ne le ferais pas. Et bien nous pouvons tous regarder en arri\u00e8re \u00e0 quel point le gadget est devenu obsol\u00e8te, il est ind\u00e9niable que m\u00eame dans les ann\u00e9es 80, l&rsquo;origine avait une histoire raciste. Oui, les Samoans sauvages faisaient leur truc, mais ils \u00e9taient au moins, vous savez, samoans. Kamala n&rsquo;\u00e9tait jamais all\u00e9 en Ouganda, ni en Afrique avant sa carri\u00e8re de catcheur.<\/p>\n\n\n\n<p>Persistance<\/p>\n\n\n\n<p>Maintenant, ce n&rsquo;est pas une colonne enti\u00e8re sur les maux du gimmick Kamala. Je veux que ce point soit tr\u00e8s clair; James Harris a pris un gadget et en a cr\u00e9\u00e9 une vie. Pendant 20 ans, Kamala pourrait arriver dans une ar\u00e8ne WWF \/ E et obtenir une \u00e9norme pop de la foule. Kamala n\u2019\u00e9tait pas le seul acte st\u00e9r\u00e9otyp\u00e9 raciste auquel un artiste noir devait faire face dans les ann\u00e9es 80. Les artistes noirs ont d\u00fb, et continuent d&rsquo;avoir, \u00e0 surmonter les st\u00e9r\u00e9otypes raciaux afin d&rsquo;ex\u00e9cuter leur art. C&rsquo;est exactement ce que faisait James Harris. Il a fait une salade de poulet avec de la merde de poulet pour pouvoir nourrir sa famille et subvenir \u00e0 ses besoins. J&rsquo;admire le travail que James Harris a fait pour faire fonctionner Kamala, et je secoue la t\u00eate face au racisme du gadget.<\/p>\n\n\n\n<p>Harris \u00e9tait un homme qui connaissait son r\u00f4le dans le monde de la lutte et qui l&rsquo;a bien jou\u00e9. Il est devenu Kamala sur le ring et \u00e0 l&rsquo;ext\u00e9rieur. Il avait toujours l&rsquo;air incertain sur le ring et utilisait vendredi, Kim Chee ou Slick pour se guider. Lorsque la WCW a cr\u00e9\u00e9 le Dungeon of Doom, Kamala s&rsquo;int\u00e9grait tout simplement parce qu&rsquo;il pouvait garder son gadget. Au dire de tous, Harris \u00e9tait tr\u00e8s g\u00e9n\u00e9reux sur le ring, sachant que son travail consistait \u00e0 \u00eatre le m\u00e9chant monstre qui avait de la sympathie pour les babyfaces. James Harris \u00e9tait vraiment un talent du Temple de la renomm\u00e9e et ses cadeaux dans le monde de la lutte nous manqueront. Pour le plaisir, voici Kamala qui claque Andr\u00e9 le G\u00e9ant.<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Tr\u00e8s peu de lutteurs ont autant d&rsquo;impact sur ma vie que Kamala. La premi\u00e8re fois que je l&rsquo;ai vu, j&rsquo;ai juste pens\u00e9, oh un autre lutteur sauvage. J&rsquo;avais d\u00e9j\u00e0 vu les Samoans sauvages, et quelques autres gadgets \u00absauvages\u00bb, donc ajouter Kamala au m\u00e9lange ne me choquait pas. Il a en quelque sorte coch\u00e9 toutes les&#8230;<\/p>\n","protected":false},"author":665,"featured_media":36287,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,4,1],"tags":[],"ppma_author":[289],"class_list":["post-36228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ex-wwe","category-news","category-uncategorized"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/36228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=36228"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/36228\/revisions"}],"predecessor-version":[{"id":36288,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/36228\/revisions\/36288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/36287"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=36228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=36228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=36228"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=36228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}