{"id":35928,"date":"2020-09-05T02:04:26","date_gmt":"2020-09-05T06:04:26","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=35928"},"modified":"2020-09-05T02:04:30","modified_gmt":"2020-09-05T06:04:30","slug":"aj-styles-commente-que-shane-mcmahon-assume-peut-etre-plus-de-taches-a-la-wwe","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/09\/05\/aj-styles-commente-que-shane-mcmahon-assume-peut-etre-plus-de-taches-a-la-wwe\/","title":{"rendered":"AJ Styles commente que Shane McMahon assume peut-\u00eatre plus de t\u00e2ches \u00e0 la WWE"},"content":{"rendered":"\n<p>Sur le dernier Twitch, AJ Styles a discut\u00e9 de la rumeur selon laquelle Shane McMahon pourrait \u00e9ventuellement assumer plus de t\u00e2ches dans les coulisses. La rumeur veut que McMahon all\u00e9gera certaines des t\u00e2ches de Bruce Prichard \u00e0 Raw. Ce qui permettrait \u00e0 ce dernier de se concentrer principalement sur Smackdown. Styles a reconnu qu&rsquo;il ne connaissait aucun des d\u00e9tails, mais a montr\u00e9 son soutien \u00e0 McMahon si c&rsquo;\u00e9tait vrai.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Styles d\u00e9clare : \u00c9coutez, si quelqu&rsquo;un peut le faire, c&rsquo;est Shane McMahon\u00bb. Il y a aussi Triple H, mais il a les mains pleines avec NXT. S&rsquo;ils l&rsquo;ont fait, ce serait g\u00e9nial pour RAW. Il y a tellement de choses en jeu et vous ne le comprenez pas vraiment tant que vous n\u2019\u00eates pas l\u00e0 et que vous n\u2019examinez pas tout. C\u2019est beaucoup \u00e0 affronter. C&rsquo;est dur.<\/p><p>J&rsquo;adore Shane poursuit AJ. Il n\u2019y a personne de mieux. Quand il met son c\u0153ur et son \u00e2me dans quelque chose, il donne vraiment tout. J&rsquo;ai \u00e9t\u00e9 sur le ring avec lui, donc je sais. Si nous parlons d&rsquo;un match qui a d\u00e9pass\u00e9 les attentes de tout le monde, ce serait mon match \u00e0 WrestleMania contre Shane McMahon. Personne ne s&rsquo;attendait \u00e0 ce que ce soit ce que c&rsquo;\u00e9tait et j&rsquo;ai trouv\u00e9 que c&rsquo;\u00e9tait g\u00e9nial. Encore une fois, si les rumeurs sont vraies selon lesquelles il va retirer certaines t\u00e2ches de Bruce Pritchard, je pense que ce serait formidable pour toutes les personnes impliqu\u00e9es. C\u2019est trop pour une seule personne. <\/p><\/blockquote>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sur le dernier Twitch, AJ Styles a discut\u00e9 de la rumeur selon laquelle Shane McMahon pourrait \u00e9ventuellement assumer plus de t\u00e2ches dans les coulisses. La rumeur veut que McMahon all\u00e9gera certaines des t\u00e2ches de Bruce Prichard \u00e0 Raw. Ce qui permettrait \u00e0 ce dernier de se concentrer principalement sur Smackdown. Styles a reconnu qu&rsquo;il ne&#8230;<\/p>\n","protected":false},"author":665,"featured_media":35948,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-35928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=35928"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35928\/revisions"}],"predecessor-version":[{"id":35949,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35928\/revisions\/35949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/35948"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=35928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=35928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=35928"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=35928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}