{"id":35686,"date":"2020-09-04T01:24:23","date_gmt":"2020-09-04T05:24:23","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=35686"},"modified":"2020-09-04T01:58:32","modified_gmt":"2020-09-04T05:58:32","slug":"les-usos-sur-les-conseils-quils-ont-recus-de-randy-orton","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/09\/04\/les-usos-sur-les-conseils-quils-ont-recus-de-randy-orton\/","title":{"rendered":"Les Usos sur les conseils qu&rsquo;ils ont re\u00e7us de Randy Orton!"},"content":{"rendered":"\n<p>Lors de leur apparition sur Table Talk, les Usos ont rappel\u00e9 les conseils qu&rsquo;ils avaient re\u00e7us de Randy Orton la premi\u00e8re fois qu&rsquo;ils l&rsquo;ont rencontr\u00e9. Voici ce qu\u2019il avait \u00e0 dire :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Je me souviens que Randy Orton a crach\u00e9 le plus r\u00e9el \u00abish\u00bb de ma premi\u00e8re ann\u00e9e quand nous sommes arriv\u00e9s. Je me souviens de lui disant : \u00abVous allez tous faire du bien ici. Il m&rsquo;a fallu environ 6 ans pour vraiment d\u00e9couvrir qui \u00e9tait Randy Orton. Vous vous retrouverez. Accrochez-vous, travaillez dur, restez humble et vous vous retrouverez.\u00bb Et je me souviens ne pas savoir de quoi il parlait, puis cela a r\u00e9sonn\u00e9 sur moi. Toujours en croissance dans cette entreprise et toujours en train d&rsquo;apprendre chaque jour sur cette entreprise.<\/p><\/blockquote>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Lors de leur apparition sur Table Talk, les Usos ont rappel\u00e9 les conseils qu&rsquo;ils avaient re\u00e7us de Randy Orton la premi\u00e8re fois qu&rsquo;ils l&rsquo;ont rencontr\u00e9. Voici ce qu\u2019il avait \u00e0 dire : Je me souviens que Randy Orton a crach\u00e9 le plus r\u00e9el \u00abish\u00bb de ma premi\u00e8re ann\u00e9e quand nous sommes arriv\u00e9s. Je me souviens&#8230;<\/p>\n","protected":false},"author":665,"featured_media":35828,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23],"tags":[],"ppma_author":[289],"class_list":["post-35686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=35686"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35686\/revisions"}],"predecessor-version":[{"id":35829,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35686\/revisions\/35829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/35828"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=35686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=35686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=35686"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=35686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}