{"id":35350,"date":"2020-08-30T19:23:21","date_gmt":"2020-08-30T23:23:21","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=35350"},"modified":"2020-08-30T21:18:55","modified_gmt":"2020-08-31T01:18:55","slug":"resultats-du-wwe-payback-2020-2","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/08\/30\/resultats-du-wwe-payback-2020-2\/","title":{"rendered":"R\u00e9sultats du WWE Payback 2020! Premi\u00e8re Heure!"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/08\/30\/resultats-du-wwe-payback-2020\/\"><strong>Pour revenir aux r\u00e9sultats du Kickoff, cliquez ici.<\/strong><\/a><\/li><li> <a href=\"https:\/\/www.jdx.info\/lutte\/2020\/08\/30\/regardez-la-reprise-du-wwe-payback-2020\/\"><strong>Pour voir la reprise du WWE Payback, cliquez ici.<\/strong><\/a> <\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Les commentateurs sont Tom Phillips, Byron Saxton et Samoa Joe pour RAW \/ Michael Cole et Corey Graves pour SmackDown.<\/p>\n\n\n\n<p>&#8211; Le WWE Payback d\u00e9bute avec la vid\u00e9o d&rsquo;ouverture, les pyros et les commentateurs qui nous souhaitent la bienvenue.<\/p>\n\n\n\n<p>&#8211; Dans une vid\u00e9o plus t\u00f4t aujourd&rsquo;hui, MVP dit que Crews a eu sa plus grande victoire en carri\u00e8re dimanche dernier par chance. Ce soir Lashley va s&rsquo;assurer que Crews reste \u00e0 la maison pour de bon.<\/p>\n\n\n\n<p><strong>Championnat des USA:<\/strong><br><strong>Bobby Lashley&nbsp;acc de MVP et Shelton Benjamin&nbsp;vs Apollo Crews<\/strong> \u00a9<\/p>\n\n\n\n<p>En fin de match, Lashley est en contr\u00f4le et applique un Sleeper \u00e0 Crews, Crews r\u00e9siste, mais tape.<\/p>\n\n\n\n<p><em>Gagnant  et nouveaux champion Bobby Lashley <\/em><\/p>\n\n\n\n<p>Apr\u00e8s le combat, Crews attaque Lashley dans le dos pour le repousser au sol et prend la fuite.<\/p>\n\n\n\n<p> &#8211; En coulisse, Kayla Braxton attend devant la loge de Roman Reigns. Paul Heyman arrive et Braxton demande si Reigns a sign\u00e9. Heyman dit que Reigns a dit qu&rsquo;il allait signer le contrat, et il est confiant qu&rsquo;il va le faire. Braxton demande si elle peut parler \u00e0 Reigns, Heyman refuse. <\/p>\n\n\n\n<p>&#8211; En coulisse, Keith Lee se pr\u00e9pare et JBL arrive. JBL dit qu&rsquo;il l&rsquo;aime bien et il veut s&rsquo;assurer qu&rsquo;il soit pr\u00eat pour ce soir. JBL lui donne une carte d&rsquo;affaire pour l&rsquo;aider en investissement. Lee dit qu&rsquo;il n&rsquo;a pas d&rsquo;argent pour le moment. JBL lui dit que si Lee perd il n&rsquo;a pas besoin de se sentir mal car Orton est le meilleur de tous les temps.<\/p>\n\n\n\n<center><p><script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-1986975368136072\" data-ad-slot=\"7818521013\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p><\/center>\n\n\n\n<p>&#8211; On pr\u00e9sente une vid\u00e9o d&rsquo;avant match, Sheamus dit que c&rsquo;est le moment de Big E de tomber comme les autres.<\/p>\n\n\n\n<p><strong>Sheamus vs Big E<\/strong><\/p>\n\n\n\n<p>En fin de match.  &nbsp;Big E \u00e9vite une charge de Sheamus et lui fait son Big Ending pour le compte de trois. <\/p>\n\n\n\n<p><em>Gagnant: Big E<\/em><\/p>\n\n\n\n<p>&#8211; En coulisse, Alyse Ashton est avec Matt Riddle pour avoir ses commentaires. Riddle dit qu&rsquo;il est toujours motiv\u00e9. Depuis ses d\u00e9buts Corbin ne le laisse pas tranquille. Corbin a peur de le voir gagner et ce soir il va rouler dessus. Alyse demande ses commentaires sur le fait que Corbin dit qu&rsquo;il va prouver que Riddle est un \u00e9chec sur le ring et \u00e0 la maison. Riddle reste sans r\u00e9ponse.<\/p>\n\n\n\n<p>&#8211; En coulisse, Nia Jax et Shayna Baszler se pr\u00e9parent. Nia dit que tout va bien si elle suit ses directives. Baszler dit qu&rsquo;elles vont gagner si Nia sort de son chemin. Les deux se poussent. Baszler dit qu&rsquo;elles vont seulement se pr\u00e9parer chacun de leur c\u00f4t\u00e9.<\/p>\n\n\n\n<p><strong>King Corbin vs Matt Riddle<\/strong><\/p>\n\n\n\n<p>En fin de match, Riddle fait son Bro To Sleep et enchaine avec son Corkscrew Splash pour le compte de trois.<\/p>\n\n\n\n<p><em>Gagnant : Matt Riddle<\/em><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong><a href=\"https:\/\/www.jdx.info\/lutte\/2020\/08\/30\/resultats-wwe-payback-2020-deuxieme-heure\/\">Pour la suite du WWE Payback, cliquez ici.<\/a><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li> <a href=\"https:\/\/www.jdx.info\/lutte\/2020\/08\/30\/regardez-la-reprise-du-wwe-payback-2020\/\"><strong>Pour voir la reprise du WWE Payback, cliquez ici.<\/strong><\/a> <\/li><\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Pour revenir aux r\u00e9sultats du Kickoff, cliquez ici. Pour voir la reprise du WWE Payback, cliquez ici. Les commentateurs sont Tom Phillips, Byron Saxton et Samoa Joe pour RAW \/ Michael Cole et Corey Graves pour SmackDown. &#8211; Le WWE Payback d\u00e9bute avec la vid\u00e9o d&rsquo;ouverture, les pyros et les commentateurs qui nous souhaitent la&#8230;<\/p>\n","protected":false},"author":4,"featured_media":35354,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[],"ppma_author":[292],"class_list":["post-35350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-payback"],"authors":[{"term_id":292,"user_id":4,"is_guest":0,"slug":"jean","display_name":"Jean Vinnier","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/33aba0263fd870a0b487e0e079ff407e10e3997c9d2987cbcc0db0db2c5c75a9?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=35350"}],"version-history":[{"count":15,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35350\/revisions"}],"predecessor-version":[{"id":35419,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35350\/revisions\/35419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/35354"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=35350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=35350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=35350"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=35350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}