{"id":35222,"date":"2020-08-29T13:42:07","date_gmt":"2020-08-29T17:42:07","guid":{"rendered":"http:\/\/www.jdx.info\/lutte\/?p=35222"},"modified":"2020-08-29T13:42:14","modified_gmt":"2020-08-29T17:42:14","slug":"la-wwe-depose-une-opposition-aux-depots-recents-de-marques-deposees-par-ftr","status":"publish","type":"post","link":"https:\/\/www.jdx.info\/lutte\/2020\/08\/29\/la-wwe-depose-une-opposition-aux-depots-recents-de-marques-deposees-par-ftr\/","title":{"rendered":"La WWE d\u00e9pose une opposition aux d\u00e9p\u00f4ts r\u00e9cents de marques d\u00e9pos\u00e9es par FTR!"},"content":{"rendered":"\n<p>Les avocats de la WWE ont d\u00e9pos\u00e9 leur opposition \u00e0 plusieurs marques d\u00e9pos\u00e9es par Dax Harwood et Cash Wheeler le mardi 26 ao\u00fbt.<\/p>\n\n\n\n<p>La WWE a d\u00e9pos\u00e9 une opposition aux marques suivantes: Shatter Machine, Say Yeah, Top Guys, #FTRKO et No Flips, Just Fists, selon PWInsider.<\/p>\n\n\n\n<p>L&rsquo;opposition a not\u00e9 que chacun des noms ci-dessus n&rsquo;est pas identifi\u00e9 comme \u00abPropri\u00e9t\u00e9 intellectuelle du lutteur\u00bb et a \u00e9t\u00e9 cr\u00e9\u00e9 par la WWE. Ce qui suit a \u00e9t\u00e9 inclus avec l&rsquo;opposition :<\/p>\n\n\n\n<p>Les candidats (Wheeler et Harwood) ont conclu des contrats avec Opposer (WWE) \u00e0 compter du 10 avril 2017 pour fournir exclusivement des services de lutte professionnelle pour Opposer dans le cadre d&rsquo;expositions de lutte professionnelle en direct et t\u00e9l\u00e9vis\u00e9es de la WWE ( le accords de r\u00e9servation ). Conform\u00e9ment \u00e0 la section 3 des contrats de r\u00e9servation intitul\u00e9e Propri\u00e9t\u00e9 intellectuelle, les candidats ont express\u00e9ment convenu que Opposer d\u00e9tenait, \u00e0 perp\u00e9tuit\u00e9, toutes les marques, marques de service et \/ ou indices distinctifs et identifiants, y compris, entre autres, le nom de l&rsquo;anneau, le surnom, la ressemblance , personnalit\u00e9, personnages, gestes, routines, th\u00e8mes et tout autre \u00e9l\u00e9ment de propri\u00e9t\u00e9 intellectuelle tangible ou immat\u00e9rielle \u00e9crit, compos\u00e9, soumis, ajout\u00e9, improvis\u00e9, cr\u00e9\u00e9, utilis\u00e9 par ou associ\u00e9 \u00e0 la performance des candidats pendant la dur\u00e9e des contrats de r\u00e9servation. La seule exception aux droits de propri\u00e9t\u00e9 intellectuelle d\u00e9tenus par la WWE en vertu des accords de r\u00e9servation est toute propri\u00e9t\u00e9 intellectuelle sp\u00e9cifiquement identifi\u00e9e dans l&rsquo;annexe A des accords de r\u00e9servation, d\u00e9finie dans les accords de r\u00e9servation comme \u00abPropri\u00e9t\u00e9 intellectuelle de WRESTLER\u00bb. <\/p>\n\n\n\n<p>La d\u00e9claration suivante a \u00e9galement \u00e9t\u00e9 jointe \u00e0 l&rsquo;opposition :<\/p>\n\n\n\n<p>En avril 2020 ou vers cette date, les candidats et la WWE ont r\u00e9sili\u00e9 les accords de r\u00e9servation (\u00ab accords de r\u00e9siliation \u00bb). Conform\u00e9ment au langage clair du paragraphe 3 des accords de r\u00e9servation et \u00e0 la propri\u00e9t\u00e9 de SHATTER MACHINE par la WWE. Les candidats ont accept\u00e9 et confirm\u00e9 dans les accords de r\u00e9siliation qu&rsquo;il leur \u00e9tait \u00e0 jamais interdit d&rsquo;utiliser toute propri\u00e9t\u00e9 intellectuelle non identifi\u00e9e comme propri\u00e9t\u00e9 intellectuelle de WRESTLER. Les accords de r\u00e9siliation pr\u00e9voient explicitement que les candidats \u00e9taient \u00e0 jamais emp\u00each\u00e9s d&rsquo;utiliser toute propri\u00e9t\u00e9 intellectuelle de la WWE, y compris, mais sans s&rsquo;y limiter, \u00ables noms, les ressemblances, les costumes, les accessoires, les gadgets, les gestes, les routines, les th\u00e8mes, les dictons (par exemple, les r\u00e9f\u00e9rences des \u00e9quipes de la WWE ou comme les Top Guys, \u00abNo flips, Just fists\u00bb ou FTKRO [sic]), des personnalit\u00e9s, des caricatures ou des coups de finition (par exemple Shatter Machine) qui font r\u00e9f\u00e9rence ou se rapportent \u00e0, ou qui sont similaires \u00e0 celles utilis\u00e9es en relation avec vos performances \u00bb avec la WWE. <\/p>\n\n\n\n<p>liens \/\/\/ : https:\/\/wrestlingheadlines.com\/wwe-files-opposition-to-recent-trademark-filings-by-ftr\/<\/p>\n\n\n\n<p><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Les avocats de la WWE ont d\u00e9pos\u00e9 leur opposition \u00e0 plusieurs marques d\u00e9pos\u00e9es par Dax Harwood et Cash Wheeler le mardi 26 ao\u00fbt. La WWE a d\u00e9pos\u00e9 une opposition aux marques suivantes: Shatter Machine, Say Yeah, Top Guys, #FTRKO et No Flips, Just Fists, selon PWInsider. L&rsquo;opposition a not\u00e9 que chacun des noms ci-dessus n&rsquo;est&#8230;<\/p>\n","protected":false},"author":665,"featured_media":35291,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,30,4,23],"tags":[],"ppma_author":[289],"class_list":["post-35222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aew-impact-njpw-roh","category-ex-wwe","category-news","category-wwe"],"authors":[{"term_id":289,"user_id":665,"is_guest":0,"slug":"line","display_name":"Line Edmond","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/852de09636413c90cdaa278312f9ea5bc4396768745424755cb63d99a05989d0?s=96&d=mm&r=g","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/comments?post=35222"}],"version-history":[{"count":2,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35222\/revisions"}],"predecessor-version":[{"id":35292,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/posts\/35222\/revisions\/35292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media\/35291"}],"wp:attachment":[{"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/media?parent=35222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/categories?post=35222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/tags?post=35222"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.jdx.info\/lutte\/wp-json\/wp\/v2\/ppma_author?post=35222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}